{"text_format":"1","workbook":"xlsx","n_sheets":5,"sheets":["Main Data Entry","Results","Historian Data","Calculations","Chart"],"not_rendered":{"charts":1,"images":3,"macros":1,"external_links":0,"defined_names":4,"comments":1,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Main Data Entry","index":0,"n_rows":35,"n_cols":26,"rows_kept":35,"cut":false,"hidden":false,"merged":[]}
["Unit Information & Characteristics",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,11111109]
[]
[null,null,"EIA 860 Plant Name (US Only):"]
[null,null,"EIA 860 Plant Code (US Only):"]
[null,null,"EIA 860 Generator ID (US Only):"]
[null,null,"GADS Generator Unit ID:"]
[null,null,"Planning Case Bus Number:"]
[null,null,"Balancing Authority:"]
[null,null,"Generator Type:"]
[null,null,"Generator Machine Base (MBASE)(MVA):"]
[null,null,"Inertia Constant (H):"]
[]
[null,null,"Droop Setting:",0.05,null,"Hz Span",{"$f":"D13*D20","v":3},"Hz"]
[null,null,"Deadband Setting:",1.7000000000000001E-2,"Hz","Hz Span (dB)",{"$f":"G13-D14","v":2.9830000000000001},"Hz"]
[null,null,"Maximum Operating Level (Pmax)(HSL):",415,"MW","Turbine NDC",{"$f":"D15","v":415},"MW"]
[null,null,"Minimum Operating Level (Pmin)(LSL):",125,"MW"]
["System & Event Characteristics"]
[]
[null,null,"Time of Frequency Event (UTC):","2017-01-24T03:50:20","Date","Time"]
[null,null,"Grid Nominal Frequency:",60,{"$f":"D19","v":"2017-01-24T03:50:20"},{"$f":"D19","v":42759.159953703704}]
[]
["Report Options"]
[null,null,"Data Source:","Historian"]
[null,null,"Time Zone of Historian Data:","CST"]
[]
["Manual Data Entry"]
[]
[null,null,null,"Pre-Perturbation Average Frequency [T(-16) to T(-2)]",null,"Hz"]
[null,null,null,"Post-Perturbation Average Frequency [T(+20 to T(+52)]",null,"Hz"]
[null,null,null,"Post-Perturbation Frequency [(T+46)]",null,"Hz"]
[null,null,null,"Pre-Perturbation Average MW [T(-2 ) to T(-16)]",null,"MW"]
[null,null,null,"Post-Perturbation Average MW [T(+20 to T(+52)]",null,"MW"]
[null,null,null,"Maximum MW Response [T(+46) to T(+60)]",null,"MW"]
[null,null,null,"MW Output [T(-4)]",null,"MW"]
[null,null,null,"MW Output [T(-60)]",null,"MW"]

{"sheet":"Results","index":1,"n_rows":16,"n_cols":5,"rows_kept":16,"cut":false,"hidden":false,"merged":[[11,0,13,4],[17,1,25,4]]}
[]
[]
[]
[]
[]
["Results"]
[]
[null,null,null,"P.U. Primary Frequency Response Performance (PUPFR):",1.5091368338849815]
[null,null,null,"P.U. Sustained Primary Frequency Response Performance (PUSPFR):",1.6551460533810938]
[null,null,null,"Overall Unit Performance:","J"]
[null,null,null,"Minimum Acceptable Score (PU):",0.75]
["For Generators between Pmin and % of Pmax and eligible to provide PFR;\n-Generators who provide response in the proper direction and sustained it for the lessor of the event duration or for 1 minute: J\n-Generators whose MW output remained unchanged or was in the wrong direction: L\n"]
[]
[]
[]
["Reason for Performance (optional)"]

{"sheet":"Historian Data","index":2,"n_rows":1508,"n_cols":5,"rows_kept":1508,"cut":false,"hidden":false,"merged":[]}
[null,null,null,"Start (2mins before T(0))",{"$f":"'Main Data Entry'!$D$19-(2/(24*60))","v":"2017-01-24T03:48:20"}]
[null,null,null,"Offset",{"$f":"myexacttimematch(E1,$A$8:$A$20000,TRUE)","v":-1}]
["-Data should be pulled for NO LESS THAN 1 minute before t(0) and NO LESS THAN 2 minutes after t(0)."]
["-Data may be pulled at any sample interval from 1s to 8s, as long as it is in the proper format."]
["-Note that the resulting Primary Frequency Response (PFR) calculations are a product of the Data provided.  Faster sampled data will provide a result most representative of the units response."]
["-Any data beyond Row 4000 of this sheet will not be sampled or used in the calculation."]
["Timestamp","Unit Frequency","MW Output"]
["2017-01-23T21:40:20",60.015998840332031,137.60885620117187]
["2017-01-23T21:40:21",60.014999389648438,137.60885620117187]
["2017-01-23T21:40:22",60.014999389648438,137.40330505371094]
["2017-01-23T21:40:23",60.015998840332031,137.40330505371094]
["2017-01-23T21:40:24",60.018001556396484,137.40330505371094]
["2017-01-23T21:40:25",60.020000457763672,137.40330505371094]
["2017-01-23T21:40:26",60.020999908447266,137.40330505371094]
["2017-01-23T21:40:27",60.020000457763672,137.40330505371094]
["2017-01-23T21:40:28",60.019001007080078,136.56980895996094]
["2017-01-23T21:40:29",60.016998291015625,136.56980895996094]
["2017-01-23T21:40:30",60.016998291015625,136.60092163085937]
["2017-01-23T21:40:31",60.016998291015625,136.60092163085937]
["2017-01-23T21:40:32",60.019001007080078,136.06657409667969]
["2017-01-23T21:40:33",60.019001007080078,136.06657409667969]
["2017-01-23T21:40:34",60.020999908447266,136.08633422851562]
["2017-01-23T21:40:35",60.021999359130859,136.08633422851562]
["2017-01-23T21:40:36",60.020999908447266,136.74186706542969]
["2017-01-23T21:40:37",60.020999908447266,136.74186706542969]
["2017-01-23T21:40:38",60.020000457763672,136.71760559082031]
["2017-01-23T21:40:39",60.020999908447266,136.71760559082031]
["2017-01-23T21:40:40",60.021999359130859,136.800537109375]
["2017-01-23T21:40:41",60.021999359130859,136.800537109375]
["2017-01-23T21:40:42",60.021999359130859,136.800537109375]
["2017-01-23T21:40:43",60.020000457763672,136.800537109375]
["2017-01-23T21:40:44",60.016998291015625,136.38742065429687]
["2017-01-23T21:40:45",60.014999389648438,136.38742065429687]
["2017-01-23T21:40:46",60.012001037597656,136.402587890625]
["2017-01-23T21:40:47",60.012001037597656,136.402587890625]
["2017-01-23T21:40:48",60.012001037597656,135.52020263671875]
["2017-01-23T21:40:49",60.012001037597656,135.52020263671875]
["2017-01-23T21:40:50",60.013999938964844,135.55284118652344]
["2017-01-23T21:40:51",60.015998840332031,135.55284118652344]
["2017-01-23T21:40:52",60.016998291015625,135.3875732421875]
["2017-01-23T21:40:53",60.016998291015625,135.3875732421875]
["2017-01-23T21:40:54",60.016998291015625,135.3875732421875]
["2017-01-23T21:40:55",60.018001556396484,135.3875732421875]
["2017-01-23T21:40:56",60.018001556396484,136.11123657226562]
["2017-01-23T21:40:57",60.018001556396484,136.11123657226562]
["2017-01-23T21:40:58",60.018001556396484,136.08468627929687]
["2017-01-23T21:40:59",60.016998291015625,136.08468627929687]
["2017-01-23T21:41:00",60.014999389648438,137.15208435058594]
["2017-01-23T21:41:01",60.014999389648438,137.15208435058594]
["2017-01-23T21:41:02",60.014999389648438,137.11257934570312]
["2017-01-23T21:41:03",60.014999389648438,137.11257934570312]
["2017-01-23T21:41:04",60.013999938964844,136.60134887695312]
["2017-01-23T21:41:05",60.01300048828125,136.60134887695312]
["2017-01-23T21:41:06",60.01300048828125,136.62026977539062]
["2017-01-23T21:41:07",60.01300048828125,136.62026977539062]
["2017-01-23T21:41:08",60.013999938964844,135.75823974609375]
["2017-01-23T21:41:09",60.013999938964844,135.75823974609375]
["2017-01-23T21:41:10",60.015998840332031,135.79013061523438]
["2017-01-23T21:41:11",60.014999389648438,135.79013061523438]
["2017-01-23T21:41:12",60.014999389648438,135.60438537597656]
["2017-01-23T21:41:13",60.014999389648438,135.60438537597656]
["2017-01-23T21:41:14",60.015998840332031,135.60438537597656]
["2017-01-23T21:41:15",60.016998291015625,135.60438537597656]
["2017-01-23T21:41:16",60.018001556396484,136.63639831542969]
["2017-01-23T21:41:17",60.018001556396484,136.63639831542969]
["2017-01-23T21:41:18",60.016998291015625,136.59846496582031]
["2017-01-23T21:41:19",60.016998291015625,136.59846496582031]
["2017-01-23T21:41:20",60.016998291015625,136.51783752441406]
["2017-01-23T21:41:21",60.015998840332031,136.51783752441406]
["2017-01-23T21:41:22",60.013999938964844,136.51783752441406]
["2017-01-23T21:41:23",60.013999938964844,136.51783752441406]
["2017-01-23T21:41:24",60.011001586914063,135.33125305175781]
["2017-01-23T21:41:25",60.008998870849609,135.33125305175781]
["2017-01-23T21:41:26",60.007999420166016,135.37527465820312]
["2017-01-23T21:41:27",60.007999420166016,135.37527465820312]
["2017-01-23T21:41:28",60.008998870849609,135.08653259277344]
["2017-01-23T21:41:29",60.009998321533203,135.08653259277344]
["2017-01-23T21:41:30",60.011001586914063,135.09721374511719]
["2017-01-23T21:41:31",60.011001586914063,135.09721374511719]
["2017-01-23T21:41:32",60.011001586914063,135.81459045410156]
["2017-01-23T21:41:33",60.01300048828125,135.81459045410156]
["2017-01-23T21:41:34",60.01300048828125,135.78805541992187]
["2017-01-23T21:41:35",60.014999389648438,135.78805541992187]
["2017-01-23T21:41:36",60.014999389648438,136.13766479492188]
["2017-01-23T21:41:37",60.014999389648438,136.13766479492188]
["2017-01-23T21:41:38",60.014999389648438,136.12472534179687]
["2017-01-23T21:41:39",60.013999938964844,136.12472534179687]
["2017-01-23T21:41:40",60.01300048828125,136.00215148925781]
["2017-01-23T21:41:41",60.01300048828125,136.00215148925781]
["2017-01-23T21:41:42",60.01300048828125,136.00215148925781]
["2017-01-23T21:41:43",60.009998321533203,136.00215148925781]
["2017-01-23T21:41:44",60.007999420166016,135.69891357421875]
["2017-01-23T21:41:45",60.007999420166016,135.69891357421875]
["2017-01-23T21:41:46",60.006999969482422,135.71029663085937]
["2017-01-23T21:41:47",60.006999969482422,135.71029663085937]
["2017-01-23T21:41:48",60.006000518798828,135.56631469726562]
["2017-01-23T21:41:49",60.005001068115234,135.56631469726562]
["2017-01-23T21:41:50",60.005001068115234,135.56631469726562]
["2017-01-23T21:41:51",60.006000518798828,135.56631469726562]
["2017-01-23T21:41:52",60.006999969482422,135.56631469726562]
["2017-01-23T21:41:53",60.007999420166016,135.56631469726562]
["2017-01-23T21:41:54",60.006999969482422,135.56631469726562]
["2017-01-23T21:41:55",60.006000518798828,135.56631469726562]
["2017-01-23T21:41:56",60.006000518798828,136.14567565917969]
["2017-01-23T21:41:57",60.006000518798828,136.14567565917969]
["2017-01-23T21:41:58",60.006000518798828,136.12443542480469]
["2017-01-23T21:41:59",60.006000518798828,136.12443542480469]
["2017-01-23T21:42:00",60.006999969482422,135.98165893554687]
["2017-01-23T21:42:01",60.004001617431641,135.98165893554687]
["2017-01-23T21:42:02",60.004001617431641,135.98165893554687]
["2017-01-23T21:42:03",59.999000549316406,135.98165893554687]
["2017-01-23T21:42:04",59.995998382568359,135.78167724609375]
["2017-01-23T21:42:05",59.993000030517578,135.78167724609375]
["2017-01-23T21:42:06",59.993000030517578,135.78167724609375]
["2017-01-23T21:42:07",59.987998962402344,135.78167724609375]
["2017-01-23T21:42:08",59.98699951171875,136.11711120605469]
["2017-01-23T21:42:09",59.986000061035156,136.11711120605469]
["2017-01-23T21:42:10",59.985000610351563,136.10498046875]
["2017-01-23T21:42:11",59.984001159667969,136.10498046875]
["2017-01-23T21:42:12",59.983001708984375,136.94624328613281]
["2017-01-23T21:42:13",59.983001708984375,136.94624328613281]
["2017-01-23T21:42:14",59.985000610351563,136.91511535644531]
["2017-01-23T21:42:15",59.986000061035156,136.91511535644531]
["2017-01-23T21:42:16",59.98699951171875,137.12135314941406]
["2017-01-23T21:42:17",59.987998962402344,137.12135314941406]
["2017-01-23T21:42:18",59.988998413085937,137.12135314941406]
["2017-01-23T21:42:19",59.988998413085937,137.12135314941406]
["2017-01-23T21:42:20",59.990001678466797,136.04759216308594]
["2017-01-23T21:42:21",59.991001129150391,136.04759216308594]
["2017-01-23T21:42:22",59.991001129150391,136.08705139160156]
["2017-01-23T21:42:23",59.991001129150391,136.08705139160156]
["2017-01-23T21:42:24",59.992000579833984,135.98304748535156]
["2017-01-23T21:42:25",59.992000579833984,135.98304748535156]
["2017-01-23T21:42:26",59.992000579833984,135.98304748535156]
["2017-01-23T21:42:27",59.992000579833984,135.98304748535156]
["2017-01-23T21:42:28",59.992000579833984,136.19183349609375]
["2017-01-23T21:42:29",59.992000579833984,136.19183349609375]
["2017-01-23T21:42:30",59.98699951171875,136.19183349609375]
["2017-01-23T21:42:31",59.98699951171875,136.19183349609375]
["2017-01-23T21:42:32",59.986000061035156,136.08198547363281]
["2017-01-23T21:42:33",59.985000610351563,136.08198547363281]
["2017-01-23T21:42:34",59.985000610351563,136.08198547363281]
["2017-01-23T21:42:35",59.985000610351563,136.08198547363281]
["2017-01-23T21:42:36",59.984001159667969,135.06024169921875]
["2017-01-23T21:42:37",59.984001159667969,135.06024169921875]
["2017-01-23T21:42:38",59.984001159667969,134.01127624511719]
["2017-01-23T21:42:39",59.984001159667969,134.01127624511719]
["2017-01-23T21:42:40",59.984001159667969,134.05007934570312]
["2017-01-23T21:42:41",59.985000610351563,134.05007934570312]
["2017-01-23T21:42:42",59.986000061035156,133.76153564453125]
["2017-01-23T21:42:43",59.985000610351563,133.76153564453125]
["2017-01-23T21:42:44",59.984001159667969,133.772216796875]
["2017-01-23T21:42:45",59.981998443603516,133.772216796875]
["2017-01-23T21:42:46",59.981998443603516,133.52572631835937]
["2017-01-23T21:42:47",59.980998992919922,133.52572631835937]
["2017-01-23T21:42:48",59.979999542236328,133.52572631835937]
["2017-01-23T21:42:49",59.981998443603516,133.52572631835937]
["2017-01-23T21:42:50",59.981998443603516,133.22689819335937]
["2017-01-23T21:42:51",59.981998443603516,133.22689819335937]
["2017-01-23T21:42:52",59.983001708984375,133.23828125]
["2017-01-23T21:42:53",59.983001708984375,133.23828125]
["2017-01-23T21:42:54",59.983001708984375,132.74568176269531]
["2017-01-23T21:42:55",59.984001159667969,132.74568176269531]
["2017-01-23T21:42:56",59.985000610351563,132.76390075683594]
["2017-01-23T21:42:57",59.986000061035156,132.76390075683594]
["2017-01-23T21:42:58",59.987998962402344,131.79936218261719]
["2017-01-23T21:42:59",59.988998413085937,131.79936218261719]
["2017-01-23T21:43:00",59.988998413085937,131.83505249023437]
["2017-01-23T21:43:01",59.988998413085937,131.83505249023437]
["2017-01-23T21:43:02",59.98699951171875,131.91575622558594]
["2017-01-23T21:43:03",59.980998992919922,131.91575622558594]
["2017-01-23T21:43:04",59.980998992919922,131.91575622558594]
["2017-01-23T21:43:05",59.979000091552734,131.91575622558594]
["2017-01-23T21:43:06",59.979000091552734,132.65116882324219]
["2017-01-23T21:43:07",59.978000640869141,132.65116882324219]
["2017-01-23T21:43:08",59.979000091552734,132.62384033203125]
["2017-01-23T21:43:09",59.979999542236328,132.62384033203125]
["2017-01-23T21:43:10",59.979999542236328,133.36314392089844]
["2017-01-23T21:43:11",59.979000091552734,133.36314392089844]
["2017-01-23T21:43:12",59.979999542236328,133.33578491210937]
["2017-01-23T21:43:13",59.979999542236328,133.33578491210937]
["2017-01-23T21:43:14",59.979000091552734,133.2547607421875]
["2017-01-23T21:43:15",59.979000091552734,133.2547607421875]
["2017-01-23T21:43:16",59.980998992919922,133.2547607421875]
["2017-01-23T21:43:17",59.983001708984375,133.2547607421875]
["2017-01-23T21:43:18",59.983001708984375,133.23713684082031]
["2017-01-23T21:43:19",59.981998443603516,133.23713684082031]
["2017-01-23T21:43:20",59.979999542236328,133.23713684082031]
["2017-01-23T21:43:21",59.979000091552734,133.23713684082031]
["2017-01-23T21:43:22",59.978000640869141,133.13534545898437]
["2017-01-23T21:43:23",59.979000091552734,133.13534545898437]
["2017-01-23T21:43:24",59.983001708984375,133.13534545898437]
["2017-01-23T21:43:25",59.990001678466797,133.13534545898437]
["2017-01-23T21:43:26",59.995998382568359,133.79524230957031]
["2017-01-23T21:43:27",60.000999450683594,133.79524230957031]
["2017-01-23T21:43:28",60.006000518798828,133.77096557617187]
["2017-01-23T21:43:29",60.008998870849609,133.77096557617187]
["2017-01-23T21:43:30",60.012001037597656,134.71522521972656]
["2017-01-23T21:43:31",60.01300048828125,134.71522521972656]
["2017-01-23T21:43:32",60.013999938964844,134.68028259277344]
["2017-01-23T21:43:33",60.014999389648438,134.68028259277344]
["2017-01-23T21:43:34",60.015998840332031,133.63568115234375]
["2017-01-23T21:43:35",60.015998840332031,133.63568115234375]
["2017-01-23T21:43:36",60.016998291015625,133.67433166503906]
["2017-01-23T21:43:37",60.016998291015625,133.67433166503906]
["2017-01-23T21:43:38",60.016998291015625,133.01664733886719]
["2017-01-23T21:43:39",60.015998840332031,133.01664733886719]
["2017-01-23T21:43:40",60.015998840332031,133.04098510742187]
["2017-01-23T21:43:41",60.015998840332031,133.04098510742187]
["2017-01-23T21:43:42",60.015998840332031,133.04098510742187]
["2017-01-23T21:43:43",60.015998840332031,133.04098510742187]
["2017-01-23T21:43:44",60.015998840332031,133.04098510742187]
["2017-01-23T21:43:45",60.016998291015625,133.04098510742187]
["2017-01-23T21:43:46",60.015998840332031,132.93757629394531]
["2017-01-23T21:43:47",60.015998840332031,132.93757629394531]
["2017-01-23T21:43:48",60.013999938964844,132.93757629394531]
["2017-01-23T21:43:49",60.013999938964844,132.93757629394531]
["2017-01-23T21:43:50",60.013999938964844,132.83869934082031]
["2017-01-23T21:43:51",60.013999938964844,132.83869934082031]
["2017-01-23T21:43:52",60.013999938964844,132.83869934082031]
["2017-01-23T21:43:53",60.015998840332031,132.83869934082031]
["2017-01-23T21:43:54",60.019001007080078,132.94488525390625]
["2017-01-23T21:43:55",60.019001007080078,132.94488525390625]
["2017-01-23T21:43:56",60.019001007080078,132.94488525390625]
["2017-01-23T21:43:57",60.019001007080078,132.94488525390625]
["2017-01-23T21:43:58",60.020000457763672,132.32600402832031]
["2017-01-23T21:43:59",60.020000457763672,132.32600402832031]
["2017-01-23T21:44:00",60.016998291015625,132.34877014160156]
["2017-01-23T21:44:01",60.016998291015625,132.34877014160156]
["2017-01-23T21:44:02",60.016998291015625,132.24539184570312]
["2017-01-23T21:44:03",60.01300048828125,132.24539184570312]
["2017-01-23T21:44:04",60.01300048828125,132.24539184570312]
["2017-01-23T21:44:05",60.011001586914063,132.24539184570312]
["2017-01-23T21:44:06",60.009998321533203,132.63871765136719]
["2017-01-23T21:44:07",60.009998321533203,132.63871765136719]
["2017-01-23T21:44:08",60.009998321533203,132.62431335449219]
["2017-01-23T21:44:09",60.007999420166016,132.62431335449219]
["2017-01-23T21:44:10",60.006999969482422,132.66584777832031]
["2017-01-23T21:44:11",60.006999969482422,132.66584777832031]
["2017-01-23T21:44:12",60.008998870849609,132.66584777832031]
["2017-01-23T21:44:13",60.008998870849609,132.66584777832031]
["2017-01-23T21:44:14",60.012001037597656,132.74639892578125]
["2017-01-23T21:44:15",60.012001037597656,132.74639892578125]
["2017-01-23T21:44:16",60.012001037597656,132.74639892578125]
["2017-01-23T21:44:17",60.012001037597656,132.74639892578125]
["2017-01-23T21:44:18",60.012001037597656,132.74639892578125]
["2017-01-23T21:44:19",60.01300048828125,132.74639892578125]
["2017-01-23T21:44:20",60.012001037597656,132.74639892578125]
["2017-01-23T21:44:21",60.012001037597656,132.74639892578125]
["2017-01-23T21:44:22",60.01300048828125,133.07160949707031]
["2017-01-23T21:44:23",60.01300048828125,133.07160949707031]
["2017-01-23T21:44:24",60.01300048828125,133.05946350097656]
["2017-01-23T21:44:25",60.01300048828125,133.05946350097656]
["2017-01-23T21:44:26",60.01300048828125,133.14193725585937]
["2017-01-23T21:44:27",60.01300048828125,133.14193725585937]
["2017-01-23T21:44:28",60.013999938964844,133.14193725585937]
["2017-01-23T21:44:29",60.013999938964844,133.14193725585937]
["2017-01-23T21:44:30",60.013999938964844,132.95443725585937]
["2017-01-23T21:44:31",60.013999938964844,132.95443725585937]
["2017-01-23T21:44:32",60.01300048828125,132.95443725585937]
["2017-01-23T21:44:33",60.01300048828125,132.95443725585937]
["2017-01-23T21:44:34",60.01300048828125,131.77154541015625]
["2017-01-23T21:44:35",60.01300048828125,131.77154541015625]
["2017-01-23T21:44:36",60.01300048828125,131.81556701660156]
["2017-01-23T21:44:37",60.01300048828125,131.81556701660156]
["2017-01-23T21:44:38",60.01300048828125,131.21922302246094]
["2017-01-23T21:44:39",60.01300048828125,131.21922302246094]
["2017-01-23T21:44:40",60.01300048828125,131.24128723144531]
["2017-01-23T21:44:41",60.01300048828125,131.24128723144531]
["2017-01-23T21:44:42",60.01300048828125,131.63011169433594]
["2017-01-23T21:44:43",60.01300048828125,131.63011169433594]
["2017-01-23T21:44:44",60.01300048828125,131.61572265625]
["2017-01-23T21:44:45",60.01300048828125,131.61572265625]
["2017-01-23T21:44:46",60.01300048828125,131.92387390136719]
["2017-01-23T21:44:47",60.01300048828125,131.92387390136719]
["2017-01-23T21:44:48",60.01300048828125,131.9124755859375]
["2017-01-23T21:44:49",60.01300048828125,131.9124755859375]
["2017-01-23T21:44:50",60.01300048828125,131.62579345703125]
["2017-01-23T21:44:51",60.01300048828125,131.62579345703125]
["2017-01-23T21:44:52",59.993000030517578,131.63639831542969]
["2017-01-23T21:44:53",59.993000030517578,131.63639831542969]
["2017-01-23T21:44:54",59.993000030517578,131.51295471191406]
["2017-01-23T21:44:55",59.993000030517578,131.51295471191406]
["2017-01-23T21:44:56",59.993000030517578,131.51295471191406]
["2017-01-23T21:44:57",59.997001647949219,131.51295471191406]
["2017-01-23T21:44:58",59.997001647949219,131.33277893066406]
["2017-01-23T21:44:59",59.997001647949219,131.33277893066406]
["2017-01-23T21:45:00",59.997001647949219,131.33277893066406]
["2017-01-23T21:45:01",59.997001647949219,131.33277893066406]
["2017-01-23T21:45:02",60.004001617431641,131.35987854003906]
["2017-01-23T21:45:03",60.004001617431641,131.35987854003906]
["2017-01-23T21:45:04",60.004001617431641,131.35987854003906]
["2017-01-23T21:45:05",60.004001617431641,131.35987854003906]
["2017-01-23T21:45:06",60.004001617431641,131.09254455566406]
["2017-01-23T21:45:07",60.004001617431641,131.09254455566406]
["2017-01-23T21:45:08",60.004001617431641,131.09254455566406]
["2017-01-23T21:45:09",60.004001617431641,131.09254455566406]
["2017-01-23T21:45:10",60.004001617431641,130.42529296875]
["2017-01-23T21:45:11",60.004001617431641,130.42529296875]
["2017-01-23T21:45:12",60.004001617431641,130.45034790039062]
["2017-01-23T21:45:13",60.004001617431641,130.45034790039062]
["2017-01-23T21:45:14",60.004001617431641,130.38789367675781]
["2017-01-23T21:45:15",60.014999389648438,130.38789367675781]
["2017-01-23T21:45:16",60.014999389648438,130.38789367675781]
["2017-01-23T21:45:17",60.014999389648438,130.38789367675781]
["2017-01-23T21:45:18",60.014999389648438,130.73875427246094]
["2017-01-23T21:45:19",60.014999389648438,130.73875427246094]
["2017-01-23T21:45:20",60.014999389648438,130.72586059570312]
["2017-01-23T21:45:21",60.01300048828125,130.72586059570312]
["2017-01-23T21:45:22",60.01300048828125,130.37770080566406]
["2017-01-23T21:45:23",60.01300048828125,130.37770080566406]
["2017-01-23T21:45:24",60.012001037597656,130.39057922363281]
["2017-01-23T21:45:25",60.012001037597656,130.39057922363281]
["2017-01-23T21:45:26",60.012001037597656,129.56979370117187]
["2017-01-23T21:45:27",60.011001586914063,129.56979370117187]
["2017-01-23T21:45:28",60.011001586914063,129.60015869140625]
["2017-01-23T21:45:29",60.008998870849609,129.60015869140625]
["2017-01-23T21:45:30",60.008998870849609,129.47599792480469]
["2017-01-23T21:45:31",60.006999969482422,129.47599792480469]
["2017-01-23T21:45:32",60.006999969482422,129.47599792480469]
["2017-01-23T21:45:33",60.006999969482422,129.47599792480469]
["2017-01-23T21:45:34",60.007999420166016,129.91107177734375]
["2017-01-23T21:45:35",60.007999420166016,129.91107177734375]
["2017-01-23T21:45:36",60.006999969482422,129.89515686035156]
["2017-01-23T21:45:37",60.006000518798828,129.89515686035156]
["2017-01-23T21:45:38",60.005001068115234,130.96214294433594]
["2017-01-23T21:45:39",60.005001068115234,130.96214294433594]
["2017-01-23T21:45:40",60.004001617431641,130.92266845703125]
["2017-01-23T21:45:41",60.004001617431641,130.92266845703125]
["2017-01-23T21:45:42",60.006000518798828,131.10870361328125]
["2017-01-23T21:45:43",60.006000518798828,131.10870361328125]
["2017-01-23T21:45:44",60.006999969482422,131.10870361328125]
["2017-01-23T21:45:45",60.006999969482422,131.10870361328125]
["2017-01-23T21:45:46",60.011001586914063,131.22511291503906]
["2017-01-23T21:45:47",60.01300048828125,131.22511291503906]
["2017-01-23T21:45:48",60.01300048828125,131.22511291503906]
["2017-01-23T21:45:49",60.013999938964844,131.22511291503906]
["2017-01-23T21:45:50",60.014999389648438,130.81056213378906]
["2017-01-23T21:45:51",60.016998291015625,130.81056213378906]
["2017-01-23T21:45:52",60.015998840332031,130.82574462890625]
["2017-01-23T21:45:53",60.011001586914063,130.82574462890625]
["2017-01-23T21:45:54",60.008998870849609,131.03025817871094]
["2017-01-23T21:45:55",60.008998870849609,131.03025817871094]
["2017-01-23T21:45:56",60.005001068115234,131.03025817871094]
["2017-01-23T21:45:57",60.004001617431641,131.03025817871094]
["2017-01-23T21:45:58",60.000999450683594,131.53565979003906]
["2017-01-23T21:45:59",60.000999450683594,131.53565979003906]
["2017-01-23T21:46:00",59.999000549316406,131.51667785644531]
["2017-01-23T21:46:01",59.994998931884766,131.51667785644531]
["2017-01-23T21:46:02",59.992000579833984,131.51667785644531]
["2017-01-23T21:46:03",59.991001129150391,131.51667785644531]
["2017-01-23T21:46:04",59.988998413085937,131.51667785644531]
["2017-01-23T21:46:05",59.988998413085937,131.51667785644531]
["2017-01-23T21:46:06",59.98699951171875,130.88162231445312]
["2017-01-23T21:46:07",59.98699951171875,130.88162231445312]
["2017-01-23T21:46:08",59.987998962402344,130.90513610839844]
["2017-01-23T21:46:09",59.987998962402344,130.90513610839844]
["2017-01-23T21:46:10",59.98699951171875,131.45797729492187]
["2017-01-23T21:46:11",59.98699951171875,131.45797729492187]
["2017-01-23T21:46:12",59.98699951171875,131.43753051757813]
["2017-01-23T21:46:13",59.988998413085937,131.43753051757813]
["2017-01-23T21:46:14",59.988998413085937,132.27909851074219]
["2017-01-23T21:46:15",59.990001678466797,132.27909851074219]
["2017-01-23T21:46:16",59.990001678466797,132.24797058105469]
["2017-01-23T21:46:17",59.990001678466797,132.24797058105469]
["2017-01-23T21:46:18",59.991001129150391,132.88485717773437]
["2017-01-23T21:46:19",59.991001129150391,132.88485717773437]
["2017-01-23T21:46:20",59.991001129150391,132.86129760742187]
["2017-01-23T21:46:21",59.987998962402344,132.86129760742187]
["2017-01-23T21:46:22",59.985000610351563,132.73912048339844]
["2017-01-23T21:46:23",59.981998443603516,132.73912048339844]
["2017-01-23T21:46:24",59.981998443603516,132.73912048339844]
["2017-01-23T21:46:25",59.981998443603516,132.73912048339844]
["2017-01-23T21:46:26",59.983001708984375,132.73912048339844]
["2017-01-23T21:46:27",59.983001708984375,132.73912048339844]
["2017-01-23T21:46:28",59.981998443603516,131.92317199707031]
["2017-01-23T21:46:29",59.981998443603516,131.92317199707031]
["2017-01-23T21:46:30",59.985000610351563,131.95352172851562]
["2017-01-23T21:46:31",59.985000610351563,131.95352172851562]
["2017-01-23T21:46:32",59.98699951171875,131.603759765625]
["2017-01-23T21:46:33",59.986000061035156,131.603759765625]
["2017-01-23T21:46:34",59.986000061035156,131.61669921875]
["2017-01-23T21:46:35",59.987998962402344,131.61669921875]
["2017-01-23T21:46:36",59.987998962402344,132.62110900878906]
["2017-01-23T21:46:37",59.987998962402344,132.62110900878906]
["2017-01-23T21:46:38",59.986000061035156,132.58393859863281]
["2017-01-23T21:46:39",59.984001159667969,132.58393859863281]
["2017-01-23T21:46:40",59.981998443603516,133.09800720214844]
["2017-01-23T21:46:41",59.981998443603516,133.09800720214844]
["2017-01-23T21:46:42",59.978000640869141,133.07899475097656]
["2017-01-23T21:46:43",59.978000640869141,133.07899475097656]
["2017-01-23T21:46:44",59.976001739501953,132.75157165527344]
["2017-01-23T21:46:45",59.978000640869141,132.75157165527344]
["2017-01-23T21:46:46",59.979000091552734,132.76368713378906]
["2017-01-23T21:46:47",59.980998992919922,132.76368713378906]
["2017-01-23T21:46:48",59.980998992919922,132.04545593261719]
["2017-01-23T21:46:49",59.981998443603516,132.04545593261719]
["2017-01-23T21:46:50",59.983001708984375,132.07203674316406]
["2017-01-23T21:46:51",59.986000061035156,132.07203674316406]
["2017-01-23T21:46:52",59.987998962402344,132.35816955566406]
["2017-01-23T21:46:53",59.990001678466797,132.35816955566406]
["2017-01-23T21:46:54",59.990001678466797,132.34757995605469]
["2017-01-23T21:46:55",59.990001678466797,132.34757995605469]
["2017-01-23T21:46:56",59.990001678466797,133.25030517578125]
["2017-01-23T21:46:57",59.991001129150391,133.25030517578125]
["2017-01-23T21:46:58",59.991001129150391,133.2169189453125]
["2017-01-23T21:46:59",59.990001678466797,133.2169189453125]
["2017-01-23T21:47:00",59.990001678466797,133.2591552734375]
["2017-01-23T21:47:01",59.990001678466797,133.2591552734375]
["2017-01-23T21:47:02",59.991001129150391,133.2591552734375]
["2017-01-23T21:47:03",59.991001129150391,133.2591552734375]
["2017-01-23T21:47:04",59.991001129150391,132.39633178710937]
["2017-01-23T21:47:05",59.992000579833984,132.39633178710937]
["2017-01-23T21:47:06",59.992000579833984,132.42819213867187]
["2017-01-23T21:47:07",59.991001129150391,132.42819213867187]
["2017-01-23T21:47:08",59.991001129150391,132.13990783691406]
["2017-01-23T21:47:09",59.990001678466797,132.13990783691406]
["2017-01-23T21:47:10",59.987998962402344,132.15057373046875]
["2017-01-23T21:47:11",59.987998962402344,132.15057373046875]
["2017-01-23T21:47:12",59.985000610351563,132.33474731445312]
["2017-01-23T21:47:13",59.984001159667969,132.33474731445312]
["2017-01-23T21:47:14",59.985000610351563,132.33474731445312]
["2017-01-23T21:47:15",59.98699951171875,132.33474731445312]
["2017-01-23T21:47:16",59.988998413085937,132.75885009765625]
["2017-01-23T21:47:17",59.988998413085937,132.75885009765625]
["2017-01-23T21:47:18",59.991001129150391,132.74290466308594]
["2017-01-23T21:47:19",59.991001129150391,132.74290466308594]
["2017-01-23T21:47:20",59.992000579833984,132.98959350585937]
["2017-01-23T21:47:21",59.992000579833984,132.98959350585937]
["2017-01-23T21:47:22",59.991001129150391,132.98959350585937]
["2017-01-23T21:47:23",59.991001129150391,132.98959350585937]
["2017-01-23T21:47:24",59.991001129150391,132.42709350585937]
["2017-01-23T21:47:25",59.991001129150391,132.42709350585937]
["2017-01-23T21:47:26",59.991001129150391,132.44757080078125]
["2017-01-23T21:47:27",59.991001129150391,132.44757080078125]
["2017-01-23T21:47:28",59.992000579833984,132.22122192382812]
["2017-01-23T21:47:29",59.992000579833984,132.22122192382812]
["2017-01-23T21:47:30",59.992000579833984,132.22122192382812]
["2017-01-23T21:47:31",59.992000579833984,132.22122192382812]
["2017-01-23T21:47:32",59.992000579833984,132.33183288574219]
["2017-01-23T21:47:33",59.992000579833984,132.33183288574219]
["2017-01-23T21:47:34",59.991001129150391,132.33183288574219]
["2017-01-23T21:47:35",59.990001678466797,132.33183288574219]
["2017-01-23T21:47:36",59.990001678466797,132.77935791015625]
["2017-01-23T21:47:37",59.990001678466797,132.77935791015625]
["2017-01-23T21:47:38",59.991001129150391,132.76264953613281]
["2017-01-23T21:47:39",59.991001129150391,132.76264953613281]
["2017-01-23T21:47:40",59.992000579833984,132.84530639648437]
["2017-01-23T21:47:41",59.992000579833984,132.84530639648437]
["2017-01-23T21:47:42",59.993999481201172,132.84530639648437]
["2017-01-23T21:47:43",59.994998931884766,132.84530639648437]
["2017-01-23T21:47:44",59.995998382568359,133.47810363769531]
["2017-01-23T21:47:45",59.995998382568359,133.47810363769531]
["2017-01-23T21:47:46",59.997001647949219,133.45457458496094]
["2017-01-23T21:47:47",59.998001098632813,133.45457458496094]
["2017-01-23T21:47:48",59.999000549316406,134.1937255859375]
["2017-01-23T21:47:49",59.999000549316406,134.1937255859375]
["2017-01-23T21:47:50",60.000999450683594,134.1663818359375]
["2017-01-23T21:47:51",60.000999450683594,134.1663818359375]
["2017-01-23T21:47:52",60.006000518798828,134.90567016601562]
["2017-01-23T21:47:53",60.006000518798828,134.90567016601562]
["2017-01-23T21:47:54",60.006999969482422,134.87832641601562]
["2017-01-23T21:47:55",60.006999969482422,134.87832641601562]
["2017-01-23T21:47:56",60.006999969482422,135.59710693359375]
["2017-01-23T21:47:57",60.006999969482422,135.59710693359375]
["2017-01-23T21:47:58",60.006999969482422,135.57051086425781]
["2017-01-23T21:47:59",60.006999969482422,135.57051086425781]
["2017-01-23T21:48:00",60.006999969482422,135.46894836425781]
["2017-01-23T21:48:01",60.006999969482422,135.46894836425781]
["2017-01-23T21:48:02",60.006999969482422,135.46894836425781]
["2017-01-23T21:48:03",60.006000518798828,135.46894836425781]
["2017-01-23T21:48:04",60.001998901367188,136.04679870605469]
["2017-01-23T21:48:05",60.001998901367188,136.04679870605469]
["2017-01-23T21:48:06",59.998001098632813,136.02554321289062]
["2017-01-23T21:48:07",59.997001647949219,136.02554321289062]
["2017-01-23T21:48:08",59.994998931884766,137.25680541992187]
["2017-01-23T21:48:09",59.994998931884766,137.25680541992187]
["2017-01-23T21:48:10",59.993000030517578,137.21124267578125]
["2017-01-23T21:48:11",59.993000030517578,137.21124267578125]
["2017-01-23T21:48:12",59.992000579833984,137.97172546386719]
["2017-01-23T21:48:13",59.990001678466797,137.97172546386719]
["2017-01-23T21:48:14",59.990001678466797,137.94358825683594]
["2017-01-23T21:48:15",59.990001678466797,137.94358825683594]
["2017-01-23T21:48:16",59.992000579833984,137.12431335449219]
["2017-01-23T21:48:17",59.990001678466797,137.12431335449219]
["2017-01-23T21:48:18",59.990001678466797,137.15463256835937]
["2017-01-23T21:48:19",59.986000061035156,137.15463256835937]
["2017-01-23T21:48:20",59.978000640869141,136.25115966796875]
["2017-01-23T21:48:21",59.976001739501953,136.25115966796875]
["2017-01-23T21:48:22",59.974998474121094,136.28459167480469]
["2017-01-23T21:48:23",59.974998474121094,136.28459167480469]
["2017-01-23T21:48:24",59.976001739501953,136.61148071289062]
["2017-01-23T21:48:25",59.976001739501953,136.61148071289062]
["2017-01-23T21:48:26",59.978000640869141,136.59938049316406]
["2017-01-23T21:48:27",59.979999542236328,136.59938049316406]
["2017-01-23T21:48:28",59.980998992919922,136.90745544433594]
["2017-01-23T21:48:29",59.983001708984375,136.90745544433594]
["2017-01-23T21:48:30",59.983001708984375,136.89604187011719]
["2017-01-23T21:48:31",59.984001159667969,136.89604187011719]
["2017-01-23T21:48:32",59.981998443603516,136.69139099121094]
["2017-01-23T21:48:33",59.981998443603516,136.69139099121094]
["2017-01-23T21:48:34",59.979999542236328,136.69139099121094]
["2017-01-23T21:48:35",59.979999542236328,136.69139099121094]
["2017-01-23T21:48:36",59.979999542236328,136.06294250488281]
["2017-01-23T21:48:37",59.979999542236328,136.06294250488281]
["2017-01-23T21:48:38",59.979000091552734,136.08647155761719]
["2017-01-23T21:48:39",59.979000091552734,136.08647155761719]
["2017-01-23T21:48:40",59.979999542236328,135.55239868164062]
["2017-01-23T21:48:41",59.980998992919922,135.55239868164062]
["2017-01-23T21:48:42",59.981998443603516,135.57215881347656]
["2017-01-23T21:48:43",59.981998443603516,135.57215881347656]
["2017-01-23T21:48:44",59.981998443603516,136.20716857910156]
["2017-01-23T21:48:45",59.980998992919922,136.20716857910156]
["2017-01-23T21:48:46",59.979999542236328,136.18368530273437]
["2017-01-23T21:48:47",59.979000091552734,136.18368530273437]
["2017-01-23T21:48:48",59.979000091552734,136.61521911621094]
["2017-01-23T21:48:49",59.979000091552734,136.61521911621094]
["2017-01-23T21:48:50",59.979999542236328,136.5992431640625]
["2017-01-23T21:48:51",59.979999542236328,136.5992431640625]
["2017-01-23T21:48:52",59.980998992919922,136.70237731933594]
["2017-01-23T21:48:53",59.980998992919922,136.70237731933594]
["2017-01-23T21:48:54",59.981998443603516,136.90364074707031]
["2017-01-23T21:48:55",59.981998443603516,136.90364074707031]
["2017-01-23T21:48:56",59.984001159667969,136.90364074707031]
["2017-01-23T21:48:57",59.984001159667969,136.90364074707031]
["2017-01-23T21:48:58",59.985000610351563,138.47557067871094]
["2017-01-23T21:48:59",59.985000610351563,138.47557067871094]
["2017-01-23T21:49:00",59.986000061035156,138.41712951660156]
["2017-01-23T21:49:01",59.985000610351563,138.41712951660156]
["2017-01-23T21:49:02",59.984001159667969,139.69078063964844]
["2017-01-23T21:49:03",59.981998443603516,139.69078063964844]
["2017-01-23T21:49:04",59.980998992919922,139.64364624023437]
["2017-01-23T21:49:05",59.980998992919922,139.64364624023437]
["2017-01-23T21:49:06",59.980998992919922,139.76844787597656]
["2017-01-23T21:49:07",59.983001708984375,139.76844787597656]
["2017-01-23T21:49:08",59.983001708984375,139.76844787597656]
["2017-01-23T21:49:09",59.984001159667969,139.76844787597656]
["2017-01-23T21:49:10",59.984001159667969,139.94856262207031]
["2017-01-23T21:49:11",59.983001708984375,139.94856262207031]
["2017-01-23T21:49:12",59.981998443603516,139.94856262207031]
["2017-01-23T21:49:13",59.981998443603516,139.94856262207031]
["2017-01-23T21:49:14",59.979000091552734,139.94856262207031]
["2017-01-23T21:49:15",59.978000640869141,139.94856262207031]
["2017-01-23T21:49:16",59.977001190185547,139.94856262207031]
["2017-01-23T21:49:17",59.976001739501953,139.94856262207031]
["2017-01-23T21:49:18",59.977001190185547,139.94856262207031]
["2017-01-23T21:49:19",59.978000640869141,139.94856262207031]
["2017-01-23T21:49:20",59.979000091552734,139.94856262207031]
["2017-01-23T21:49:21",59.979000091552734,139.94856262207031]
["2017-01-23T21:49:22",59.979000091552734,141.02888488769531]
["2017-01-23T21:49:23",59.979000091552734,141.02888488769531]
["2017-01-23T21:49:24",59.979999542236328,140.98867797851563]
["2017-01-23T21:49:25",59.979999542236328,140.98867797851563]
["2017-01-23T21:49:26",59.979000091552734,141.19523620605469]
["2017-01-23T21:49:27",59.976001739501953,141.19523620605469]
["2017-01-23T21:49:28",59.974998474121094,141.19523620605469]
["2017-01-23T21:49:29",59.974998474121094,141.19523620605469]
["2017-01-23T21:49:30",59.9739990234375,140.22401428222656]
["2017-01-23T21:49:31",59.9739990234375,140.22401428222656]
["2017-01-23T21:49:32",59.9739990234375,140.25965881347656]
["2017-01-23T21:49:33",59.974998474121094,140.25965881347656]
["2017-01-23T21:49:34",59.976001739501953,140.25965881347656]
["2017-01-23T21:49:35",59.978000640869141,140.25965881347656]
["2017-01-23T21:49:36",59.978000640869141,140.25965881347656]
["2017-01-23T21:49:37",59.978000640869141,140.25965881347656]
["2017-01-23T21:49:38",59.979000091552734,140.99667358398437]
["2017-01-23T21:49:39",59.979999542236328,140.99667358398437]
["2017-01-23T21:49:40",59.979999542236328,140.9693603515625]
["2017-01-23T21:49:41",59.979999542236328,140.9693603515625]
["2017-01-23T21:49:42",59.979999542236328,142.77505493164062]
["2017-01-23T21:49:43",59.979000091552734,142.77505493164062]
["2017-01-23T21:49:44",59.979000091552734,142.70823669433594]
["2017-01-23T21:49:45",59.978000640869141,142.70823669433594]
["2017-01-23T21:49:46",59.978000640869141,143.53103637695312]
["2017-01-23T21:49:47",59.977001190185547,143.53103637695312]
["2017-01-23T21:49:48",59.978000640869141,143.50057983398437]
["2017-01-23T21:49:49",59.978000640869141,143.50057983398437]
["2017-01-23T21:49:50",59.978000640869141,142.989013671875]
["2017-01-23T21:49:51",59.976001739501953,142.989013671875]
["2017-01-23T21:49:52",59.976001739501953,143.00794982910156]
["2017-01-23T21:49:53",59.976001739501953,143.00794982910156]
["2017-01-23T21:49:54",59.976001739501953,143.08927917480469]
["2017-01-23T21:49:55",59.976001739501953,143.08927917480469]
["2017-01-23T21:49:56",59.977001190185547,143.08927917480469]
["2017-01-23T21:49:57",59.979000091552734,143.08927917480469]
["2017-01-23T21:49:58",59.979000091552734,144.25532531738281]
["2017-01-23T21:49:59",59.979999542236328,144.25532531738281]
["2017-01-23T21:50:00",59.979999542236328,144.21206665039062]
["2017-01-23T21:50:01",59.979999542236328,144.21206665039062]
["2017-01-23T21:50:02",59.979000091552734,145.13652038574219]
["2017-01-23T21:50:03",59.978000640869141,145.13652038574219]
["2017-01-23T21:50:04",59.977001190185547,145.10231018066406]
["2017-01-23T21:50:05",59.977001190185547,145.10231018066406]
["2017-01-23T21:50:06",59.977001190185547,146.53912353515625]
["2017-01-23T21:50:07",59.977001190185547,146.53912353515625]
["2017-01-23T21:50:08",59.978000640869141,146.4859619140625]
["2017-01-23T21:50:09",59.978000640869141,146.4859619140625]
["2017-01-23T21:50:10",59.977001190185547,146.56996154785156]
["2017-01-23T21:50:11",59.977001190185547,146.56996154785156]
["2017-01-23T21:50:12",59.977001190185547,146.56996154785156]
["2017-01-23T21:50:13",59.979000091552734,146.56996154785156]
["2017-01-23T21:50:14",59.979000091552734,146.34138488769531]
["2017-01-23T21:50:15",59.979999542236328,146.34138488769531]
["2017-01-23T21:50:16",59.979000091552734,146.34138488769531]
["2017-01-23T21:50:17",59.980998992919922,146.34138488769531]
["2017-01-23T21:50:18",59.980998992919922,146.45195007324219]
["2017-01-23T21:50:19",59.985000610351563,146.45195007324219]
["2017-01-23T21:50:20",59.985000610351563,146.45195007324219]
["2017-01-23T21:50:21",59.941001892089844,146.45195007324219]
["2017-01-23T21:50:22",59.869998931884766,146.89949035644531]
["2017-01-23T21:50:23",59.824001312255859,146.89949035644531]
["2017-01-23T21:50:24",59.808998107910156,146.88278198242187]
["2017-01-23T21:50:25",59.808998107910156,146.88278198242187]
["2017-01-23T21:50:26",59.810001373291016,147.60118103027344]
["2017-01-23T21:50:27",59.838001251220703,147.60118103027344]
["2017-01-23T21:50:28",59.838001251220703,147.57460021972656]
["2017-01-23T21:50:29",59.855998992919922,147.57460021972656]
["2017-01-23T21:50:30",59.873001098632813,153.15370178222656]
["2017-01-23T21:50:31",59.898998260498047,153.15370178222656]
["2017-01-23T21:50:32",59.898998260498047,152.94728088378906]
["2017-01-23T21:50:33",59.915000915527344,152.94728088378906]
["2017-01-23T21:50:34",59.916999816894531,152.66780090332031]
["2017-01-23T21:50:35",59.916000366210938,152.66780090332031]
["2017-01-23T21:50:36",59.916000366210938,152.67814636230469]
["2017-01-23T21:50:37",59.919998168945313,152.67814636230469]
["2017-01-23T21:50:38",59.929000854492187,156.98440551757812]
["2017-01-23T21:50:39",59.930999755859375,156.98440551757812]
["2017-01-23T21:50:40",59.930999755859375,156.8250732421875]
["2017-01-23T21:50:41",59.932998657226562,156.8250732421875]
["2017-01-23T21:50:42",59.933998107910156,160.39932250976562]
["2017-01-23T21:50:43",59.933998107910156,160.39932250976562]
["2017-01-23T21:50:44",59.935001373291016,160.26707458496094]
["2017-01-23T21:50:45",59.937000274658203,160.26707458496094]
["2017-01-23T21:50:46",59.937000274658203,159.98486328125]
["2017-01-23T21:50:47",59.939998626708984,159.98486328125]
["2017-01-23T21:50:48",59.939998626708984,159.99530029296875]
["2017-01-23T21:50:49",59.938999176025391,159.99530029296875]
["2017-01-23T21:50:50",59.937000274658203,158.84648132324219]
["2017-01-23T21:50:51",59.937000274658203,158.84648132324219]
["2017-01-23T21:50:52",59.937000274658203,158.88899230957031]
["2017-01-23T21:50:53",59.937000274658203,158.88899230957031]
["2017-01-23T21:50:54",59.937000274658203,157.90304565429688]
["2017-01-23T21:50:55",59.937000274658203,157.90304565429688]
["2017-01-23T21:50:56",59.937000274658203,157.93951416015625]
["2017-01-23T21:50:57",59.938999176025391,157.93951416015625]
["2017-01-23T21:50:58",59.939998626708984,157.34344482421875]
["2017-01-23T21:50:59",59.939998626708984,157.34344482421875]
["2017-01-23T21:51:00",59.939998626708984,157.36549377441406]
["2017-01-23T21:51:01",59.939998626708984,157.36549377441406]
["2017-01-23T21:51:02",59.942001342773438,157.13909912109375]
["2017-01-23T21:51:03",59.944999694824219,157.13909912109375]
["2017-01-23T21:51:04",59.944000244140625,157.13909912109375]
["2017-01-23T21:51:05",59.944000244140625,157.13909912109375]
["2017-01-23T21:51:06",59.946998596191406,156.69599914550781]
["2017-01-23T21:51:07",59.946998596191406,156.69599914550781]
["2017-01-23T21:51:08",59.946998596191406,156.71269226074219]
["2017-01-23T21:51:09",59.944999694824219,156.71269226074219]
["2017-01-23T21:51:10",59.944999694824219,156.50700378417969]
["2017-01-23T21:51:11",59.945999145507813,156.50700378417969]
["2017-01-23T21:51:12",59.945999145507813,156.50700378417969]
["2017-01-23T21:51:13",59.945999145507813,156.50700378417969]
["2017-01-23T21:51:14",59.944999694824219,157.88835144042969]
["2017-01-23T21:51:15",59.944999694824219,157.88835144042969]
["2017-01-23T21:51:16",59.941001892089844,157.8375244140625]
["2017-01-23T21:51:17",59.938999176025391,157.8375244140625]
["2017-01-23T21:51:18",59.937000274658203,159.29545593261719]
["2017-01-23T21:51:19",59.937000274658203,159.29545593261719]
["2017-01-23T21:51:20",59.937000274658203,159.24151611328125]
["2017-01-23T21:51:21",59.937000274658203,159.24151611328125]
["2017-01-23T21:51:22",59.938999176025391,160.30992126464844]
["2017-01-23T21:51:23",59.937999725341797,160.30992126464844]
["2017-01-23T21:51:24",59.937999725341797,160.2703857421875]
["2017-01-23T21:51:25",59.937999725341797,160.2703857421875]
["2017-01-23T21:51:26",59.941001892089844,160.4154052734375]
["2017-01-23T21:51:27",59.941001892089844,160.4154052734375]
["2017-01-23T21:51:28",59.944000244140625,160.4154052734375]
["2017-01-23T21:51:29",59.946998596191406,160.4154052734375]
["2017-01-23T21:51:30",59.946998596191406,160.36921691894531]
["2017-01-23T21:51:31",59.949001312255859,160.36921691894531]
["2017-01-23T21:51:32",59.948001861572266,160.36921691894531]
["2017-01-23T21:51:33",59.948001861572266,160.36921691894531]
["2017-01-23T21:51:34",59.945999145507813,160.26814270019531]
["2017-01-23T21:51:35",59.945999145507813,160.26814270019531]
["2017-01-23T21:51:36",59.944000244140625,160.26814270019531]
["2017-01-23T21:51:37",59.939998626708984,160.26814270019531]
["2017-01-23T21:51:38",59.941001892089844,159.49249267578125]
["2017-01-23T21:51:39",59.943000793457031,159.49249267578125]
["2017-01-23T21:51:40",59.943000793457031,159.52133178710937]
["2017-01-23T21:51:41",59.943000793457031,159.52133178710937]
["2017-01-23T21:51:42",59.943000793457031,158.330810546875]
["2017-01-23T21:51:43",59.944999694824219,158.330810546875]
["2017-01-23T21:51:44",59.945999145507813,158.37486267089844]
["2017-01-23T21:51:45",59.943000793457031,158.37486267089844]
["2017-01-23T21:51:46",59.943000793457031,158.37486267089844]
["2017-01-23T21:51:47",59.944000244140625,158.37486267089844]
["2017-01-23T21:51:48",59.943000793457031,158.393798828125]
["2017-01-23T21:51:49",59.943000793457031,158.393798828125]
["2017-01-23T21:51:50",59.943000793457031,157.83932495117187]
["2017-01-23T21:51:51",59.943000793457031,157.83932495117187]
["2017-01-23T21:51:52",59.943000793457031,157.85984802246094]
["2017-01-23T21:51:53",59.939998626708984,157.85984802246094]
["2017-01-23T21:51:54",59.939998626708984,156.89521789550781]
["2017-01-23T21:51:55",59.943000793457031,156.89521789550781]
["2017-01-23T21:51:56",59.943000793457031,156.930908203125]
["2017-01-23T21:51:57",59.942001342773438,156.930908203125]
["2017-01-23T21:51:58",59.942001342773438,156.23233032226562]
["2017-01-23T21:51:59",59.943000793457031,156.23233032226562]
["2017-01-23T21:52:00",59.943000793457031,156.2581787109375]
["2017-01-23T21:52:01",59.945999145507813,156.2581787109375]
["2017-01-23T21:52:02",59.948001861572266,156.31874084472656]
["2017-01-23T21:52:03",59.948001861572266,156.31874084472656]
["2017-01-23T21:52:04",59.948001861572266,156.31874084472656]
["2017-01-23T21:52:05",59.949001312255859,156.31874084472656]
["2017-01-23T21:52:06",59.950000762939453,156.33709716796875]
["2017-01-23T21:52:07",59.950000762939453,156.33709716796875]
["2017-01-23T21:52:08",59.951000213623047,156.33709716796875]
["2017-01-23T21:52:09",59.953998565673828,156.33709716796875]
["2017-01-23T21:52:10",59.955001831054688,156.23382568359375]
["2017-01-23T21:52:11",59.951000213623047,156.23382568359375]
["2017-01-23T21:52:12",59.951000213623047,156.23382568359375]
["2017-01-23T21:52:13",59.950000762939453,156.23382568359375]
["2017-01-23T21:52:14",59.948001861572266,156.13493347167969]
["2017-01-23T21:52:15",59.948001861572266,156.13493347167969]
["2017-01-23T21:52:16",59.949001312255859,156.13493347167969]
["2017-01-23T21:52:17",59.950000762939453,156.13493347167969]
["2017-01-23T21:52:18",59.951000213623047,155.70793151855469]
["2017-01-23T21:52:19",59.951000213623047,155.70793151855469]
["2017-01-23T21:52:20",59.953998565673828,155.72386169433594]
["2017-01-23T21:52:21",59.953998565673828,155.72386169433594]
["2017-01-23T21:52:22",59.953998565673828,155.90785217285156]
["2017-01-23T21:52:23",59.951999664306641,155.90785217285156]
["2017-01-23T21:52:24",59.951999664306641,155.90785217285156]
["2017-01-23T21:52:25",59.951999664306641,155.90785217285156]
["2017-01-23T21:52:26",59.955001831054688,156.55754089355469]
["2017-01-23T21:52:27",59.959999084472656,156.55754089355469]
["2017-01-23T21:52:28",59.959999084472656,156.53324890136719]
["2017-01-23T21:52:29",59.959999084472656,156.53324890136719]
["2017-01-23T21:52:30",59.958999633789063,156.41110229492188]
["2017-01-23T21:52:31",59.958999633789063,156.41110229492188]
["2017-01-23T21:52:32",59.959999084472656,156.41110229492188]
["2017-01-23T21:52:33",59.959999084472656,156.41110229492188]
["2017-01-23T21:52:34",59.958000183105469,156.21037292480469]
["2017-01-23T21:52:35",59.958999633789063,156.21037292480469]
["2017-01-23T21:52:36",59.958999633789063,156.21037292480469]
["2017-01-23T21:52:37",59.958999633789063,156.21037292480469]
["2017-01-23T21:52:38",59.958999633789063,156.44328308105469]
["2017-01-23T21:52:39",59.959999084472656,156.44328308105469]
["2017-01-23T21:52:40",59.958999633789063,156.44328308105469]
["2017-01-23T21:52:41",59.958999633789063,156.44328308105469]
["2017-01-23T21:52:42",59.958000183105469,156.84539794921875]
["2017-01-23T21:52:43",59.957000732421875,156.84539794921875]
["2017-01-23T21:52:44",59.957000732421875,156.83021545410156]
["2017-01-23T21:52:45",59.958999633789063,156.83021545410156]
["2017-01-23T21:52:46",59.959999084472656,157.13839721679687]
["2017-01-23T21:52:47",59.96099853515625,157.13839721679687]
["2017-01-23T21:52:48",59.962001800537109,157.12699890136719]
["2017-01-23T21:52:49",59.962001800537109,157.12699890136719]
["2017-01-23T21:52:50",59.959999084472656,158.31686401367187]
["2017-01-23T21:52:51",59.958000183105469,158.31686401367187]
["2017-01-23T21:52:52",59.957000732421875,158.27284240722656]
["2017-01-23T21:52:53",59.959999084472656,158.27284240722656]
["2017-01-23T21:52:54",59.959999084472656,159.09478759765625]
["2017-01-23T21:52:55",59.966999053955078,159.09478759765625]
["2017-01-23T21:52:56",59.966999053955078,159.06437683105469]
["2017-01-23T21:52:57",59.974998474121094,159.06437683105469]
["2017-01-23T21:52:58",59.974998474121094,159.72174072265625]
["2017-01-23T21:52:59",59.972000122070313,159.72174072265625]
["2017-01-23T21:53:00",59.972000122070313,159.69741821289062]
["2017-01-23T21:53:01",59.966999053955078,159.69741821289062]
["2017-01-23T21:53:02",59.966999053955078,159.78034973144531]
["2017-01-23T21:53:03",59.965999603271484,159.78034973144531]
["2017-01-23T21:53:04",59.967998504638672,159.78034973144531]
["2017-01-23T21:53:05",59.967998504638672,159.78034973144531]
["2017-01-23T21:53:06",59.967998504638672,159.78034973144531]
["2017-01-23T21:53:07",59.970001220703125,159.78034973144531]
["2017-01-23T21:53:08",59.970001220703125,159.78034973144531]
["2017-01-23T21:53:09",59.972000122070313,159.78034973144531]
["2017-01-23T21:53:10",59.972000122070313,160.20806884765625]
["2017-01-23T21:53:11",59.970001220703125,160.20806884765625]
["2017-01-23T21:53:12",59.970001220703125,160.19212341308594]
["2017-01-23T21:53:13",59.967998504638672,160.19212341308594]
["2017-01-23T21:53:14",59.966999053955078,161.05404663085937]
["2017-01-23T21:53:15",59.966999053955078,161.05404663085937]
["2017-01-23T21:53:16",59.966999053955078,161.02215576171875]
["2017-01-23T21:53:17",59.969001770019531,161.02215576171875]
["2017-01-23T21:53:18",59.971000671386719,161.51551818847656]
["2017-01-23T21:53:19",59.971000671386719,161.51551818847656]
["2017-01-23T21:53:20",59.972000122070313,161.49726867675781]
["2017-01-23T21:53:21",59.972999572753906,161.49726867675781]
["2017-01-23T21:53:22",59.972999572753906,161.60047912597656]
["2017-01-23T21:53:23",59.9739990234375,161.60047912597656]
["2017-01-23T21:53:24",59.974998474121094,161.60047912597656]
["2017-01-23T21:53:25",59.976001739501953,161.60047912597656]
["2017-01-23T21:53:26",59.976001739501953,162.2530517578125]
["2017-01-23T21:53:27",59.977001190185547,162.2530517578125]
["2017-01-23T21:53:28",59.977001190185547,162.228759765625]
["2017-01-23T21:53:29",59.977001190185547,162.228759765625]
["2017-01-23T21:53:30",59.977001190185547,162.94743347167969]
["2017-01-23T21:53:31",59.974998474121094,162.94743347167969]
["2017-01-23T21:53:32",59.9739990234375,162.92085266113281]
["2017-01-23T21:53:33",59.974998474121094,162.92085266113281]
["2017-01-23T21:53:34",59.974998474121094,163.16792297363281]
["2017-01-23T21:53:35",59.978000640869141,163.16792297363281]
["2017-01-23T21:53:36",59.979000091552734,163.16792297363281]
["2017-01-23T21:53:37",59.978000640869141,163.16792297363281]
["2017-01-23T21:53:38",59.978000640869141,163.65130615234375]
["2017-01-23T21:53:39",59.978000640869141,163.65130615234375]
["2017-01-23T21:53:40",59.979999542236328,163.63308715820312]
["2017-01-23T21:53:41",59.979999542236328,163.63308715820312]
["2017-01-23T21:53:42",59.979999542236328,163.94137573242187]
["2017-01-23T21:53:43",59.980998992919922,163.94137573242187]
["2017-01-23T21:53:44",59.980998992919922,163.92996215820312]
["2017-01-23T21:53:45",59.981998443603516,163.92996215820312]
["2017-01-23T21:53:46",59.981998443603516,163.74581909179687]
["2017-01-23T21:53:47",59.983001708984375,163.74581909179687]
["2017-01-23T21:53:48",59.983001708984375,163.74581909179687]
["2017-01-23T21:53:49",59.984001159667969,163.74581909179687]
["2017-01-23T21:53:50",59.984001159667969,163.93695068359375]
["2017-01-23T21:53:51",59.984001159667969,163.93695068359375]
["2017-01-23T21:53:52",59.986000061035156,163.93695068359375]
["2017-01-23T21:53:53",59.986000061035156,163.93695068359375]
["2017-01-23T21:53:54",59.98699951171875,164.19699096679687]
["2017-01-23T21:53:55",59.98699951171875,164.19699096679687]
["2017-01-23T21:53:56",59.990001678466797,164.19699096679687]
["2017-01-23T21:53:57",59.993000030517578,164.19699096679687]
["2017-01-23T21:53:58",59.995998382568359,164.19699096679687]
["2017-01-23T21:53:59",59.995998382568359,164.19699096679687]
["2017-01-23T21:54:00",60,164.19699096679687]
["2017-01-23T21:54:01",60.005001068115234,164.19699096679687]
["2017-01-23T21:54:02",60.016998291015625,164.14645385742187]
["2017-01-23T21:54:03",60.020000457763672,164.14645385742187]
["2017-01-23T21:54:04",60.020000457763672,164.14645385742187]
["2017-01-23T21:54:05",60.020000457763672,164.14645385742187]
["2017-01-23T21:54:06",60.020000457763672,164.02487182617187]
["2017-01-23T21:54:07",60.019001007080078,164.02487182617187]
["2017-01-23T21:54:08",60.019001007080078,164.02487182617187]
["2017-01-23T21:54:09",60.019001007080078,164.02487182617187]
["2017-01-23T21:54:10",60.018001556396484,164.70600891113281]
["2017-01-23T21:54:11",60.018001556396484,164.70600891113281]
["2017-01-23T21:54:12",60.015998840332031,164.68096923828125]
["2017-01-23T21:54:13",60.016998291015625,164.68096923828125]
["2017-01-23T21:54:14",60.018001556396484,165.09205627441406]
["2017-01-23T21:54:15",60.019001007080078,165.09205627441406]
["2017-01-23T21:54:16",60.020000457763672,165.07684326171875]
["2017-01-23T21:54:17",60.021999359130859,165.07684326171875]
["2017-01-23T21:54:18",60.023998260498047,164.87232971191406]
["2017-01-23T21:54:19",60.023998260498047,164.87232971191406]
["2017-01-23T21:54:20",60.025001525878906,164.87232971191406]
["2017-01-23T21:54:21",60.0260009765625,164.87232971191406]
["2017-01-23T21:54:22",60.0260009765625,164.77708435058594]
["2017-01-23T21:54:23",60.0260009765625,164.77708435058594]
["2017-01-23T21:54:24",60.023998260498047,164.77708435058594]
["2017-01-23T21:54:25",60.023998260498047,164.77708435058594]
["2017-01-23T21:54:26",60.022998809814453,164.88328552246094]
["2017-01-23T21:54:27",60.021999359130859,164.88328552246094]
["2017-01-23T21:54:28",60.020999908447266,164.88328552246094]
["2017-01-23T21:54:29",60.020999908447266,164.88328552246094]
["2017-01-23T21:54:30",60.018001556396484,164.674560546875]
["2017-01-23T21:54:31",60.016998291015625,164.674560546875]
["2017-01-23T21:54:32",60.016998291015625,164.674560546875]
["2017-01-23T21:54:33",60.018001556396484,164.674560546875]
["2017-01-23T21:54:34",60.018001556396484,164.53829956054687]
["2017-01-23T21:54:35",60.018001556396484,164.53829956054687]
["2017-01-23T21:54:36",60.018001556396484,164.53829956054687]
["2017-01-23T21:54:37",60.018001556396484,164.53829956054687]
["2017-01-23T21:54:38",60.020999908447266,164.74850463867187]
["2017-01-23T21:54:39",60.020999908447266,164.74850463867187]
["2017-01-23T21:54:40",60.022998809814453,164.74850463867187]
["2017-01-23T21:54:41",60.022998809814453,164.74850463867187]
["2017-01-23T21:54:42",60.023998260498047,165.2744140625]
["2017-01-23T21:54:43",60.0260009765625,165.2744140625]
["2017-01-23T21:54:44",60.0260009765625,165.25466918945312]
["2017-01-23T21:54:45",60.023998260498047,165.25466918945312]
["2017-01-23T21:54:46",60.022998809814453,165.68606567382812]
["2017-01-23T21:54:47",60.022998809814453,165.68606567382812]
["2017-01-23T21:54:48",60.022998809814453,165.67010498046875]
["2017-01-23T21:54:49",60.019001007080078,165.67010498046875]
["2017-01-23T21:54:50",60.015998840332031,165.69120788574219]
["2017-01-23T21:54:51",60.015998840332031,165.69120788574219]
["2017-01-23T21:54:52",60.015998840332031,165.69120788574219]
["2017-01-23T21:54:53",60.015998840332031,165.69120788574219]
["2017-01-23T21:54:54",60.018001556396484,165.69120788574219]
["2017-01-23T21:54:55",60.020000457763672,165.69120788574219]
["2017-01-23T21:54:56",60.021999359130859,165.69120788574219]
["2017-01-23T21:54:57",60.021999359130859,165.69120788574219]
["2017-01-23T21:54:58",60.021999359130859,165.56739807128906]
["2017-01-23T21:54:59",60.021999359130859,165.56739807128906]
["2017-01-23T21:55:00",60.020000457763672,165.56739807128906]
["2017-01-23T21:55:01",60.018001556396484,165.56739807128906]
["2017-01-23T21:55:02",60.018001556396484,166.12550354003906]
["2017-01-23T21:55:03",60.019001007080078,166.12550354003906]
["2017-01-23T21:55:04",60.020000457763672,166.10501098632812]
["2017-01-23T21:55:05",60.020000457763672,166.10501098632812]
["2017-01-23T21:55:06",60.019001007080078,166.72100830078125]
["2017-01-23T21:55:07",60.019001007080078,166.72100830078125]
["2017-01-23T21:55:08",60.019001007080078,166.69821166992187]
["2017-01-23T21:55:09",60.019001007080078,166.69821166992187]
["2017-01-23T21:55:10",60.019001007080078,166.92465209960937]
["2017-01-23T21:55:11",60.019001007080078,166.92465209960937]
["2017-01-23T21:55:12",60.019001007080078,166.92465209960937]
["2017-01-23T21:55:13",60.018001556396484,166.92465209960937]
["2017-01-23T21:55:14",60.019001007080078,166.77302551269531]
["2017-01-23T21:55:15",60.020000457763672,166.77302551269531]
["2017-01-23T21:55:16",60.020000457763672,166.77302551269531]
["2017-01-23T21:55:17",60.020999908447266,166.77302551269531]
["2017-01-23T21:55:18",60.020999908447266,167.22929382324219]
["2017-01-23T21:55:19",60.025001525878906,167.22929382324219]
["2017-01-23T21:55:20",60.0260009765625,167.21261596679687]
["2017-01-23T21:55:21",60.0260009765625,167.21261596679687]
["2017-01-23T21:55:22",60.027999877929687,167.31576538085937]
["2017-01-23T21:55:23",60.027999877929687,167.31576538085937]
["2017-01-23T21:55:24",60.0260009765625,167.31576538085937]
["2017-01-23T21:55:25",60.021999359130859,167.31576538085937]
["2017-01-23T21:55:26",60.021999359130859,167.74275207519531]
["2017-01-23T21:55:27",60.018001556396484,167.74275207519531]
["2017-01-23T21:55:28",60.018001556396484,167.72682189941406]
["2017-01-23T21:55:29",60.018001556396484,167.72682189941406]
["2017-01-23T21:55:30",60.016998291015625,167.37876892089844]
["2017-01-23T21:55:31",60.016998291015625,167.37876892089844]
["2017-01-23T21:55:32",60.019001007080078,167.39164733886719]
["2017-01-23T21:55:33",60.018001556396484,167.39164733886719]
["2017-01-23T21:55:34",60.01300048828125,167.00152587890625]
["2017-01-23T21:55:35",60.007999420166016,167.00152587890625]
["2017-01-23T21:55:36",60.006000518798828,167.01596069335938]
["2017-01-23T21:55:37",60.005001068115234,167.01596069335938]
["2017-01-23T21:55:38",60.001998901367188,166.68730163574219]
["2017-01-23T21:55:39",59.998001098632813,166.68730163574219]
["2017-01-23T21:55:40",59.998001098632813,166.699462890625]
["2017-01-23T21:55:41",59.998001098632813,166.699462890625]
["2017-01-23T21:55:42",60,166.78105163574219]
["2017-01-23T21:55:43",60.001998901367188,166.78105163574219]
["2017-01-23T21:55:44",60.001998901367188,166.78105163574219]
["2017-01-23T21:55:45",60.006000518798828,166.78105163574219]
["2017-01-23T21:55:46",60.009998321533203,167.20880126953125]
["2017-01-23T21:55:47",60.019001007080078,167.20880126953125]
["2017-01-23T21:55:48",60.019001007080078,167.19285583496094]
["2017-01-23T21:55:49",60.027000427246094,167.19285583496094]
["2017-01-23T21:55:50",60.019001007080078,167.21395874023437]
["2017-01-23T21:55:51",60.019001007080078,167.21395874023437]
["2017-01-23T21:55:52",60.011001586914063,167.21395874023437]
["2017-01-23T21:55:53",60.004001617431641,167.21395874023437]
["2017-01-23T21:55:54",60.004001617431641,167.35676574707031]
["2017-01-23T21:55:55",60.005001068115234,167.35676574707031]
["2017-01-23T21:55:56",60.005001068115234,167.35676574707031]
["2017-01-23T21:55:57",60.005001068115234,167.35676574707031]
["2017-01-23T21:55:58",60.006999969482422,167.41317749023437]
["2017-01-23T21:55:59",60.007999420166016,167.41317749023437]
["2017-01-23T21:56:00",60.007999420166016,167.41317749023437]
["2017-01-23T21:56:01",60.007999420166016,167.41317749023437]
["2017-01-23T21:56:02",60.006999969482422,167.28791809082031]
["2017-01-23T21:56:03",60.006999969482422,167.28791809082031]
["2017-01-23T21:56:04",60.005001068115234,167.28791809082031]
["2017-01-23T21:56:05",60.004001617431641,167.28791809082031]
["2017-01-23T21:56:06",60.002998352050781,167.18977355957031]
["2017-01-23T21:56:07",60.002998352050781,167.18977355957031]
["2017-01-23T21:56:08",60.002998352050781,167.18977355957031]
["2017-01-23T21:56:09",60.001998901367188,167.18977355957031]
["2017-01-23T21:56:10",60.000999450683594,167.41900634765625]
["2017-01-23T21:56:11",60,167.41900634765625]
["2017-01-23T21:56:12",59.998001098632813,167.41900634765625]
["2017-01-23T21:56:13",59.998001098632813,167.41900634765625]
["2017-01-23T21:56:14",59.994998931884766,167.69808959960937]
["2017-01-23T21:56:15",59.993000030517578,167.69808959960937]
["2017-01-23T21:56:16",59.993000030517578,167.68745422363281]
["2017-01-23T21:56:17",59.991001129150391,167.68745422363281]
["2017-01-23T21:56:18",59.991001129150391,167.62632751464844]
["2017-01-23T21:56:19",59.992000579833984,167.62632751464844]
["2017-01-23T21:56:20",59.993999481201172,167.62632751464844]
["2017-01-23T21:56:21",59.993999481201172,167.62632751464844]
["2017-01-23T21:56:22",59.997001647949219,167.73104858398438]
["2017-01-23T21:56:23",59.998001098632813,167.73104858398438]
["2017-01-23T21:56:24",60,167.73104858398438]
["2017-01-23T21:56:25",60,167.73104858398438]
["2017-01-23T21:56:26",60.002998352050781,167.62484741210937]
["2017-01-23T21:56:27",60.005001068115234,167.62484741210937]
["2017-01-23T21:56:28",60.006999969482422,167.62484741210937]
["2017-01-23T21:56:29",60.007999420166016,167.62484741210937]
["2017-01-23T21:56:30",60.008998870849609,167.58747863769531]
["2017-01-23T21:56:31",60.011001586914063,167.58747863769531]
["2017-01-23T21:56:32",60.011001586914063,167.58747863769531]
["2017-01-23T21:56:33",60.01300048828125,167.58747863769531]
["2017-01-23T21:56:34",60.01300048828125,167.69149780273437]
["2017-01-23T21:56:35",60.014999389648438,167.69149780273437]
["2017-01-23T21:56:36",60.014999389648438,167.69149780273437]
["2017-01-23T21:56:37",60.015998840332031,167.69149780273437]
["2017-01-23T21:56:38",60.014999389648438,168.11849975585937]
["2017-01-23T21:56:39",60.014999389648438,168.11849975585937]
["2017-01-23T21:56:40",60.01300048828125,168.10256958007812]
["2017-01-23T21:56:41",60.012001037597656,168.10256958007812]
["2017-01-23T21:56:42",60.01300048828125,167.9185791015625]
["2017-01-23T21:56:43",60.013999938964844,167.9185791015625]
["2017-01-23T21:56:44",60.013999938964844,167.9185791015625]
["2017-01-23T21:56:45",60.015998840332031,167.9185791015625]
["2017-01-23T21:56:46",60.019001007080078,167.9185791015625]
["2017-01-23T21:56:47",60.020000457763672,167.9185791015625]
["2017-01-23T21:56:48",60.020000457763672,167.9185791015625]
["2017-01-23T21:56:49",60.019001007080078,167.9185791015625]
["2017-01-23T21:56:50",60.018001556396484,168.00717163085937]
["2017-01-23T21:56:51",60.015998840332031,168.00717163085937]
["2017-01-23T21:56:52",60.013999938964844,168.00717163085937]
["2017-01-23T21:56:53",60.013999938964844,168.00717163085937]
["2017-01-23T21:56:54",60.013999938964844,167.92222595214844]
["2017-01-23T21:56:55",60.013999938964844,167.92222595214844]
["2017-01-23T21:56:56",60.013999938964844,167.92222595214844]
["2017-01-23T21:56:57",60.022998809814453,167.92222595214844]
["2017-01-23T21:56:58",60.022998809814453,168.00717163085937]
["2017-01-23T21:56:59",60.022998809814453,168.00717163085937]
["2017-01-23T21:57:00",60.021999359130859,168.00717163085937]
["2017-01-23T21:57:01",60.020000457763672,168.00717163085937]
["2017-01-23T21:57:02",60.018001556396484,168.10679626464844]
["2017-01-23T21:57:03",60.015998840332031,168.10679626464844]
["2017-01-23T21:57:04",60.014999389648438,168.10679626464844]
["2017-01-23T21:57:05",60.013999938964844,168.10679626464844]
["2017-01-23T21:57:06",60.013999938964844,167.79551696777344]
["2017-01-23T21:57:07",60.015998840332031,167.79551696777344]
["2017-01-23T21:57:08",60.015998840332031,167.80690002441406]
["2017-01-23T21:57:09",60.018001556396484,167.80690002441406]
["2017-01-23T21:57:10",60.020999908447266,167.37580871582031]
["2017-01-23T21:57:11",60.020999908447266,167.37580871582031]
["2017-01-23T21:57:12",60.021999359130859,167.39176940917969]
["2017-01-23T21:57:13",60.020999908447266,167.39176940917969]
["2017-01-23T21:57:14",60.020000457763672,166.96051025390625]
["2017-01-23T21:57:15",60.020000457763672,166.96051025390625]
["2017-01-23T21:57:16",60.020000457763672,166.97647094726562]
["2017-01-23T21:57:17",60.020000457763672,166.97647094726562]
["2017-01-23T21:57:18",60.020000457763672,166.38114929199219]
["2017-01-23T21:57:19",60.018001556396484,166.38114929199219]
["2017-01-23T21:57:20",60.015998840332031,166.40316772460937]
["2017-01-23T21:57:21",60.013999938964844,166.40316772460937]
["2017-01-23T21:57:22",60.013999938964844,166.40316772460937]
["2017-01-23T21:57:23",60.013999938964844,166.40316772460937]
["2017-01-23T21:57:24",60.014999389648438,166.38188171386719]
["2017-01-23T21:57:25",60.016998291015625,166.38188171386719]
["2017-01-23T21:57:26",60.016998291015625,166.38188171386719]
["2017-01-23T21:57:27",60.018001556396484,166.38188171386719]
["2017-01-23T21:57:28",60.019001007080078,166.15702819824219]
["2017-01-23T21:57:29",60.020000457763672,166.15702819824219]
["2017-01-23T21:57:30",60.020000457763672,166.15702819824219]
["2017-01-23T21:57:31",60.020999908447266,166.15702819824219]
["2017-01-23T21:57:32",60.021999359130859,165.75491333007812]
["2017-01-23T21:57:33",60.023998260498047,165.75491333007812]
["2017-01-23T21:57:34",60.022998809814453,165.77009582519531]
["2017-01-23T21:57:35",60.021999359130859,165.77009582519531]
["2017-01-23T21:57:36",60.021999359130859,165.564453125]
["2017-01-23T21:57:37",60.019001007080078,165.564453125]
["2017-01-23T21:57:38",60.018001556396484,165.564453125]
["2017-01-23T21:57:39",60.019001007080078,165.564453125]
["2017-01-23T21:57:40",60.019001007080078,165.34619140625]
["2017-01-23T21:57:41",60.018001556396484,165.34619140625]
["2017-01-23T21:57:42",60.018001556396484,165.34619140625]
["2017-01-23T21:57:43",60.018001556396484,165.34619140625]
["2017-01-23T21:57:44",60.018001556396484,165.600341796875]
["2017-01-23T21:57:45",60.018001556396484,165.600341796875]
["2017-01-23T21:57:46",60.016998291015625,165.600341796875]
["2017-01-23T21:57:47",60.015998840332031,165.600341796875]
["2017-01-23T21:57:48",60.015998840332031,165.34548950195312]
["2017-01-23T21:57:49",60.016998291015625,165.34548950195312]
["2017-01-23T21:57:50",60.018001556396484,164.71884155273437]
["2017-01-23T21:57:51",60.018001556396484,164.71884155273437]
["2017-01-23T21:57:52",60.020999908447266,164.74201965332031]
["2017-01-23T21:57:53",60.020999908447266,164.74201965332031]
["2017-01-23T21:57:54",60.020000457763672,164.53608703613281]
["2017-01-23T21:57:55",60.019001007080078,164.53608703613281]
["2017-01-23T21:57:56",60.018001556396484,164.53608703613281]
["2017-01-23T21:57:57",60.018001556396484,164.53608703613281]
["2017-01-23T21:57:58",60.018001556396484,164.25631713867187]
["2017-01-23T21:57:59",60.018001556396484,164.25631713867187]
["2017-01-23T21:58:00",60.019001007080078,164.26695251464844]
["2017-01-23T21:58:01",60.020000457763672,164.26695251464844]
["2017-01-23T21:58:02",60.019001007080078,163.50776672363281]
["2017-01-23T21:58:03",60.020000457763672,163.50776672363281]
["2017-01-23T21:58:04",60.020000457763672,163.53585815429687]
["2017-01-23T21:58:05",60.021999359130859,163.53585815429687]
["2017-01-23T21:58:06",60.023998260498047,163.53585815429687]
["2017-01-23T21:58:07",60.023998260498047,163.53585815429687]
["2017-01-23T21:58:08",60.020000457763672,163.53585815429687]
["2017-01-23T21:58:09",60.019001007080078,163.53585815429687]
["2017-01-23T21:58:10",60.016998291015625,162.91961669921875]
["2017-01-23T21:58:11",60.015998840332031,162.91961669921875]
["2017-01-23T21:58:12",60.014999389648438,162.9423828125]
["2017-01-23T21:58:13",60.015998840332031,162.9423828125]
["2017-01-23T21:58:14",60.015998840332031,161.89564514160156]
["2017-01-23T21:58:15",60.015998840332031,161.89564514160156]
["2017-01-23T21:58:16",60.016998291015625,161.93437194824219]
["2017-01-23T21:58:17",60.018001556396484,161.93437194824219]
["2017-01-23T21:58:18",60.015998840332031,161.05110168457031]
["2017-01-23T21:58:19",60.014999389648438,161.05110168457031]
["2017-01-23T21:58:20",60.016998291015625,161.08378601074219]
["2017-01-23T21:58:21",60.020000457763672,161.08378601074219]
["2017-01-23T21:58:22",60.020000457763672,160.95953369140625]
["2017-01-23T21:58:23",60.0260009765625,160.95953369140625]
["2017-01-23T21:58:24",60.0260009765625,160.95953369140625]
["2017-01-23T21:58:25",60.014999389648438,160.95953369140625]
["2017-01-23T21:58:26",60.009998321533203,160.90243530273437]
["2017-01-23T21:58:27",60.009998321533203,160.90243530273437]
["2017-01-23T21:58:28",60.009998321533203,160.90243530273437]
["2017-01-23T21:58:29",60.008998870849609,160.90243530273437]
["2017-01-23T21:58:30",60.007999420166016,160.59701538085937]
["2017-01-23T21:58:31",60.007999420166016,160.59701538085937]
["2017-01-23T21:58:32",60.005001068115234,160.6083984375]
["2017-01-23T21:58:33",60.004001617431641,160.6083984375]
["2017-01-23T21:58:34",60.002998352050781,160.15679931640625]
["2017-01-23T21:58:35",60.002998352050781,160.15679931640625]
["2017-01-23T21:58:36",60.004001617431641,160.17350769042969]
["2017-01-23T21:58:37",60.006000518798828,160.17350769042969]
["2017-01-23T21:58:38",60.006000518798828,159.35258483886719]
["2017-01-23T21:58:39",60.006000518798828,159.35258483886719]
["2017-01-23T21:58:40",60.007999420166016,159.38296508789062]
["2017-01-23T21:58:41",60.008998870849609,159.38296508789062]
["2017-01-23T21:58:42",60.009998321533203,159.279296875]
["2017-01-23T21:58:43",60.009998321533203,159.279296875]
["2017-01-23T21:58:44",60.011001586914063,159.279296875]
["2017-01-23T21:58:45",60.011001586914063,159.279296875]
["2017-01-23T21:58:46",60.011001586914063,158.97537231445312]
["2017-01-23T21:58:47",60.011001586914063,158.97537231445312]
["2017-01-23T21:58:48",60.012001037597656,158.98675537109375]
["2017-01-23T21:58:49",60.01300048828125,158.98675537109375]
["2017-01-23T21:58:50",60.01300048828125,158.78126525878906]
["2017-01-23T21:58:51",60.012001037597656,158.78126525878906]
["2017-01-23T21:58:52",60.012001037597656,158.78126525878906]
["2017-01-23T21:58:53",60.008998870849609,158.78126525878906]
["2017-01-23T21:58:54",60.006999969482422,158.23487854003906]
["2017-01-23T21:58:55",60.006999969482422,158.23487854003906]
["2017-01-23T21:58:56",60.006999969482422,158.25537109375]
["2017-01-23T21:58:57",60.006999969482422,158.25537109375]
["2017-01-23T21:58:58",60.008998870849609,157.72140502929687]
["2017-01-23T21:58:59",60.009998321533203,157.72140502929687]
["2017-01-23T21:59:00",60.012001037597656,157.74116516113281]
["2017-01-23T21:59:01",60.01300048828125,157.74116516113281]
["2017-01-23T21:59:02",60.01300048828125,157.10469055175781]
["2017-01-23T21:59:03",60.015998840332031,157.10469055175781]
["2017-01-23T21:59:04",60.018001556396484,157.12823486328125]
["2017-01-23T21:59:05",60.015998840332031,157.12823486328125]
["2017-01-23T21:59:06",60.014999389648438,156.38908386230469]
["2017-01-23T21:59:07",60.014999389648438,156.38908386230469]
["2017-01-23T21:59:08",60.014999389648438,156.41644287109375]
["2017-01-23T21:59:09",60.014999389648438,156.41644287109375]
["2017-01-23T21:59:10",60.014999389648438,155.92323303222656]
["2017-01-23T21:59:11",60.013999938964844,155.92323303222656]
["2017-01-23T21:59:12",60.013999938964844,155.94148254394531]
["2017-01-23T21:59:13",60.013999938964844,155.94148254394531]
["2017-01-23T21:59:14",60.013999938964844,155.40760803222656]
["2017-01-23T21:59:15",60.014999389648438,155.40760803222656]
["2017-01-23T21:59:16",60.014999389648438,155.4273681640625]
["2017-01-23T21:59:17",60.015998840332031,155.4273681640625]
["2017-01-23T21:59:18",60.018001556396484,154.5447998046875]
["2017-01-23T21:59:19",60.016998291015625,154.5447998046875]
["2017-01-23T21:59:20",60.015998840332031,154.57745361328125]
["2017-01-23T21:59:21",60.015998840332031,154.57745361328125]
["2017-01-23T21:59:22",60.01300048828125,153.98152160644531]
["2017-01-23T21:59:23",60.009998321533203,153.98152160644531]
["2017-01-23T21:59:24",60.009998321533203,154.00357055664062]
["2017-01-23T21:59:25",60.01300048828125,154.00357055664062]
["2017-01-23T21:59:26",60.016998291015625,153.44903564453125]
["2017-01-23T21:59:27",60.019001007080078,153.44903564453125]
["2017-01-23T21:59:28",60.019001007080078,153.46955871582031]
["2017-01-23T21:59:29",60.020000457763672,153.46955871582031]
["2017-01-23T21:59:30",60.019001007080078,153.07914733886719]
["2017-01-23T21:59:31",60.019001007080078,153.07914733886719]
["2017-01-23T21:59:32",60.018001556396484,153.09359741210937]
["2017-01-23T21:59:33",60.019001007080078,153.09359741210937]
["2017-01-23T21:59:34",60.020000457763672,152.43681335449219]
["2017-01-23T21:59:35",60.020000457763672,152.43681335449219]
["2017-01-23T21:59:36",60.019001007080078,152.43681335449219]
["2017-01-23T21:59:37",60.019001007080078,152.43681335449219]
["2017-01-23T21:59:38",60.018001556396484,152.234619140625]
["2017-01-23T21:59:39",60.018001556396484,152.234619140625]
["2017-01-23T21:59:40",60.016998291015625,152.234619140625]
["2017-01-23T21:59:41",60.016998291015625,152.234619140625]
["2017-01-23T21:59:42",60.016998291015625,152.234619140625]
["2017-01-23T21:59:43",60.016998291015625,152.234619140625]
["2017-01-23T21:59:44",60.016998291015625,152.234619140625]
["2017-01-23T21:59:45",60.016998291015625,152.234619140625]
["2017-01-23T21:59:46",60.018001556396484,151.11180114746094]
["2017-01-23T21:59:47",60.018001556396484,151.11180114746094]
["2017-01-23T21:59:48",60.018001556396484,151.1361083984375]
["2017-01-23T21:59:49",60.018001556396484,151.1361083984375]
["2017-01-23T21:59:50",60.018001556396484,150.60200500488281]
["2017-01-23T21:59:51",60.018001556396484,150.60200500488281]
["2017-01-23T21:59:52",60.018001556396484,150.62176513671875]
["2017-01-23T21:59:53",60.016998291015625,150.62176513671875]
["2017-01-23T21:59:54",60.018001556396484,150.35443115234375]
["2017-01-23T21:59:55",60.019001007080078,150.35443115234375]
["2017-01-23T21:59:56",60.018001556396484,150.35443115234375]
["2017-01-23T21:59:57",60.018001556396484,150.35443115234375]
["2017-01-23T21:59:58",60.019001007080078,150.32295227050781]
["2017-01-23T21:59:59",60.019001007080078,150.32295227050781]
["2017-01-23T22:00:00",60.018001556396484,150.32295227050781]
["2017-01-23T22:00:01",60.015998840332031,150.32295227050781]
["2017-01-23T22:00:02",60.013999938964844,149.89375305175781]
["2017-01-23T22:00:03",60.013999938964844,149.89375305175781]
["2017-01-23T22:00:04",60.018001556396484,149.90969848632812]
["2017-01-23T22:00:05",60.020000457763672,149.90969848632812]
["2017-01-23T22:00:06",60.020999908447266,149.60148620605469]
["2017-01-23T22:00:07",60.020999908447266,149.60148620605469]
["2017-01-23T22:00:08",60.020999908447266,149.61288452148437]
["2017-01-23T22:00:09",60.020000457763672,149.61288452148437]
["2017-01-23T22:00:10",60.020000457763672,148.46403503417969]
["2017-01-23T22:00:11",60.020000457763672,148.46403503417969]
["2017-01-23T22:00:12",60.018001556396484,148.50654602050781]
["2017-01-23T22:00:13",60.016998291015625,148.50654602050781]
["2017-01-23T22:00:14",60.016998291015625,147.66415405273437]
["2017-01-23T22:00:15",60.015998840332031,147.66415405273437]
["2017-01-23T22:00:16",60.014999389648438,147.6953125]
["2017-01-23T22:00:17",60.015998840332031,147.6953125]
["2017-01-23T22:00:18",60.016998291015625,146.97639465332031]
["2017-01-23T22:00:19",60.015998840332031,146.97639465332031]
["2017-01-23T22:00:20",60.015998840332031,147.00299072265625]
["2017-01-23T22:00:21",60.014999389648438,147.00299072265625]
["2017-01-23T22:00:22",60.014999389648438,147.26860046386719]
["2017-01-23T22:00:23",60.014999389648438,147.26860046386719]
["2017-01-23T22:00:24",60.016998291015625,147.26860046386719]
["2017-01-23T22:00:25",60.016998291015625,147.26860046386719]
["2017-01-23T22:00:26",60.019001007080078,147.40269470214844]
["2017-01-23T22:00:27",60.019001007080078,147.40269470214844]
["2017-01-23T22:00:28",60.019001007080078,147.40269470214844]
["2017-01-23T22:00:29",60.019001007080078,147.40269470214844]
["2017-01-23T22:00:30",60.019001007080078,146.76182556152344]
["2017-01-23T22:00:31",60.016998291015625,146.76182556152344]
["2017-01-23T22:00:32",60.016998291015625,146.78533935546875]
["2017-01-23T22:00:33",60.016998291015625,146.78533935546875]
["2017-01-23T22:00:34",60.016998291015625,146.47685241699219]
["2017-01-23T22:00:35",60.018001556396484,146.47685241699219]
["2017-01-23T22:00:36",60.018001556396484,146.48826599121094]
["2017-01-23T22:00:37",60.020000457763672,146.48826599121094]
["2017-01-23T22:00:38",60.020000457763672,146.59039306640625]
["2017-01-23T22:00:39",60.020000457763672,146.59039306640625]
["2017-01-23T22:00:40",60.021999359130859,146.59039306640625]
["2017-01-23T22:00:41",60.020999908447266,146.59039306640625]
["2017-01-23T22:00:42",60.019001007080078,146.25862121582031]
["2017-01-23T22:00:43",60.019001007080078,146.25862121582031]
["2017-01-23T22:00:44",60.020000457763672,146.270751953125]
["2017-01-23T22:00:45",60.020999908447266,146.270751953125]
["2017-01-23T22:00:46",60.021999359130859,146.37284851074219]
["2017-01-23T22:00:47",60.020999908447266,146.37284851074219]
["2017-01-23T22:00:48",60.020999908447266,146.37284851074219]
["2017-01-23T22:00:49",60.018001556396484,146.37284851074219]
["2017-01-23T22:00:50",60.018001556396484,145.83601379394531]
["2017-01-23T22:00:51",60.015998840332031,145.83601379394531]
["2017-01-23T22:00:52",60.016998291015625,145.85572814941406]
["2017-01-23T22:00:53",60.018001556396484,145.85572814941406]
["2017-01-23T22:00:54",60.018001556396484,145.62940979003906]
["2017-01-23T22:00:55",60.019001007080078,145.62940979003906]
["2017-01-23T22:00:56",60.019001007080078,145.62940979003906]
["2017-01-23T22:00:57",60.019001007080078,145.62940979003906]
["2017-01-23T22:00:58",60.019001007080078,146.27322387695312]
["2017-01-23T22:00:59",60.020000457763672,146.27322387695312]
["2017-01-23T22:01:00",60.020000457763672,146.24971008300781]
["2017-01-23T22:01:01",60.018001556396484,146.24971008300781]
["2017-01-23T22:01:02",60.018001556396484,146.68124389648437]
["2017-01-23T22:01:03",60.018001556396484,146.68124389648437]
["2017-01-23T22:01:04",60.018001556396484,146.665283203125]
["2017-01-23T22:01:05",60.018001556396484,146.665283203125]
["2017-01-23T22:01:06",60.018001556396484,147.28109741210937]
["2017-01-23T22:01:07",60.018001556396484,147.28109741210937]
["2017-01-23T22:01:08",60.018001556396484,147.25831604003906]
["2017-01-23T22:01:09",60.018001556396484,147.25831604003906]
["2017-01-23T22:01:10",60.020999908447266,146.3157958984375]
["2017-01-23T22:01:11",60.020999908447266,146.3157958984375]
["2017-01-23T22:01:12",60.020999908447266,146.35067749023437]
["2017-01-23T22:01:13",60.021999359130859,146.35067749023437]
["2017-01-23T22:01:14",60.020000457763672,145.30348205566406]
["2017-01-23T22:01:15",60.018001556396484,145.30348205566406]
["2017-01-23T22:01:16",60.018001556396484,145.34222412109375]
["2017-01-23T22:01:17",60.016998291015625,145.34222412109375]
["2017-01-23T22:01:18",60.016998291015625,145.34222412109375]
["2017-01-23T22:01:19",60.014999389648438,145.34222412109375]
["2017-01-23T22:01:20",60.015998840332031,145.26185607910156]
["2017-01-23T22:01:21",60.020000457763672,145.26185607910156]
["2017-01-23T22:01:22",60.020000457763672,145.26185607910156]
["2017-01-23T22:01:23",60.016998291015625,145.26185607910156]
["2017-01-23T22:01:24",60.016998291015625,145.26185607910156]
["2017-01-23T22:01:25",60.015998840332031,145.26185607910156]
["2017-01-23T22:01:26",60.014999389648438,145.26185607910156]
["2017-01-23T22:01:27",60.009998321533203,145.26185607910156]
["2017-01-23T22:01:28",60.009998321533203,145.26185607910156]
["2017-01-23T22:01:29",60.012001037597656,145.26185607910156]
["2017-01-23T22:01:30",60.014999389648438,145.26185607910156]
["2017-01-23T22:01:31",60.016998291015625,145.26185607910156]
["2017-01-23T22:01:32",60.019001007080078,144.90652465820312]
["2017-01-23T22:01:33",60.019001007080078,144.90652465820312]
["2017-01-23T22:01:34",60.018001556396484,144.92625427246094]
["2017-01-23T22:01:35",60.018001556396484,144.92625427246094]
["2017-01-23T22:01:36",60.014999389648438,144.72805786132812]
["2017-01-23T22:01:37",60.015998840332031,144.72805786132812]
["2017-01-23T22:01:38",60.016998291015625,144.830322265625]
["2017-01-23T22:01:39",60.016998291015625,144.830322265625]
["2017-01-23T22:01:40",60.019001007080078,144.830322265625]
["2017-01-23T22:01:41",60.019001007080078,144.830322265625]
["2017-01-23T22:01:42",60.018001556396484,144.92921447753906]
["2017-01-23T22:01:43",60.015998840332031,144.92921447753906]
["2017-01-23T22:01:44",60.014999389648438,144.92921447753906]
["2017-01-23T22:01:45",60.01300048828125,144.92921447753906]
["2017-01-23T22:01:46",60.012001037597656,144.90504455566406]
["2017-01-23T22:01:47",60.012001037597656,144.90504455566406]
["2017-01-23T22:01:48",60.012001037597656,144.90504455566406]
["2017-01-23T22:01:49",60.01300048828125,144.90504455566406]
["2017-01-23T22:01:50",60.01300048828125,143.59327697753906]
["2017-01-23T22:01:51",60.01300048828125,143.59327697753906]
["2017-01-23T22:01:52",60.013999938964844,143.64183044433594]
["2017-01-23T22:01:53",60.014999389648438,143.64183044433594]
["2017-01-23T22:01:54",60.014999389648438,143.41445922851563]
["2017-01-23T22:01:55",60.015998840332031,143.41445922851563]
["2017-01-23T22:01:56",60.015998840332031,143.41445922851563]
["2017-01-23T22:01:57",60.015998840332031,143.41445922851563]
["2017-01-23T22:01:58",60.015998840332031,144.34541320800781]
["2017-01-23T22:01:59",60.014999389648438,144.34541320800781]
["2017-01-23T22:02:00",60.014999389648438,144.311279296875]
["2017-01-23T22:02:01",60.013999938964844,144.311279296875]
["2017-01-23T22:02:02",60.013999938964844,144.20999145507812]
["2017-01-23T22:02:03",60.019001007080078,144.20999145507812]
["2017-01-23T22:02:04",60.0260009765625,144.20999145507812]
["2017-01-23T22:02:05",60.029998779296875,144.20999145507812]
["2017-01-23T22:02:06",60.030998229980469,143.61888122558594]
["2017-01-23T22:02:07",60.028999328613281,143.61888122558594]
["2017-01-23T22:02:08",60.027999877929687,143.64088439941406]
["2017-01-23T22:02:09",60.027000427246094,143.64088439941406]
["2017-01-23T22:02:10",60.025001525878906,143.08636474609375]
["2017-01-23T22:02:11",60.020999908447266,143.08636474609375]
["2017-01-23T22:02:12",60.019001007080078,143.10688781738281]
["2017-01-23T22:02:13",60.019001007080078,143.10688781738281]
["2017-01-23T22:02:14",60.020000457763672,142.67546081542969]
["2017-01-23T22:02:15",60.021999359130859,142.67546081542969]
["2017-01-23T22:02:16",60.023998260498047,142.69142150878906]
["2017-01-23T22:02:17",60.025001525878906,142.69142150878906]
["2017-01-23T22:02:18",60.025001525878906,140.80410766601562]
["2017-01-23T22:02:19",60.021999359130859,140.80410766601562]
["2017-01-23T22:02:20",60.019001007080078,140.87394714355469]
["2017-01-23T22:02:21",60.018001556396484,140.87394714355469]
["2017-01-23T22:02:22",60.018001556396484,140.76881408691406]
["2017-01-23T22:02:23",60.019001007080078,140.76881408691406]
["2017-01-23T22:02:24",60.020999908447266,140.76881408691406]
["2017-01-23T22:02:25",60.022998809814453,140.76881408691406]
["2017-01-23T22:02:26",60.022998809814453,141.42881774902344]
["2017-01-23T22:02:27",60.022998809814453,141.42881774902344]
["2017-01-23T22:02:28",60.022998809814453,141.404541015625]
["2017-01-23T22:02:29",60.021999359130859,141.404541015625]
["2017-01-23T22:02:30",60.022998809814453,140.87223815917969]
["2017-01-23T22:02:31",60.022998809814453,140.87223815917969]
["2017-01-23T22:02:32",60.022998809814453,140.89193725585937]
["2017-01-23T22:02:33",60.022998809814453,140.89193725585937]
["2017-01-23T22:02:34",60.021999359130859,140.02987670898437]
["2017-01-23T22:02:35",60.020999908447266,140.02987670898437]
["2017-01-23T22:02:36",60.020999908447266,140.061767578125]
["2017-01-23T22:02:37",60.019001007080078,140.061767578125]
["2017-01-23T22:02:38",60.019001007080078,140.59379577636719]
["2017-01-23T22:02:39",60.020000457763672,140.59379577636719]
["2017-01-23T22:02:40",60.020000457763672,140.57411193847656]
["2017-01-23T22:02:41",60.020000457763672,140.57411193847656]
["2017-01-23T22:02:42",60.019001007080078,140.3492431640625]
["2017-01-23T22:02:43",60.019001007080078,140.3492431640625]
["2017-01-23T22:02:44",60.020000457763672,140.3492431640625]
["2017-01-23T22:02:45",60.020000457763672,140.3492431640625]
["2017-01-23T22:02:46",60.020000457763672,140.17268371582031]
["2017-01-23T22:02:47",60.020000457763672,140.17268371582031]
["2017-01-23T22:02:48",60.020999908447266,140.17268371582031]
["2017-01-23T22:02:49",60.020999908447266,140.17268371582031]
["2017-01-23T22:02:50",60.021999359130859,139.72810363769531]
["2017-01-23T22:02:51",60.020999908447266,139.72810363769531]
["2017-01-23T22:02:52",60.020000457763672,139.74481201171875]
["2017-01-23T22:02:53",60.020000457763672,139.74481201171875]
["2017-01-23T22:02:54",60.019001007080078,139.10844421386719]
["2017-01-23T22:02:55",60.018001556396484,139.10844421386719]
["2017-01-23T22:02:56",60.016998291015625,139.13198852539062]
["2017-01-23T22:02:57",60.016998291015625,139.13198852539062]
["2017-01-23T22:02:58",60.015998840332031,138.08522033691406]
["2017-01-23T22:02:59",60.014999389648438,138.08522033691406]
["2017-01-23T22:03:00",60.013999938964844,138.12396240234375]
["2017-01-23T22:03:01",60.012001037597656,138.12396240234375]
["2017-01-23T22:03:02",60.009998321533203,138.34811401367188]
["2017-01-23T22:03:03",60.009998321533203,138.34811401367188]
["2017-01-23T22:03:04",60.012001037597656,138.34811401367188]
["2017-01-23T22:03:05",60.013999938964844,138.34811401367188]
["2017-01-23T22:03:06",60.015998840332031,138.54519653320312]
["2017-01-23T22:03:07",60.016998291015625,138.54519653320312]
["2017-01-23T22:03:08",60.016998291015625,138.54519653320312]
["2017-01-23T22:03:09",60.015998840332031,138.54519653320312]
["2017-01-23T22:03:10",60.015998840332031,138.54519653320312]
["2017-01-23T22:03:11",60.018001556396484,138.54519653320312]
["2017-01-23T22:03:12",60.019001007080078,138.33279418945313]
["2017-01-23T22:03:13",60.019001007080078,138.33279418945313]
["2017-01-23T22:03:14",60.020000457763672,138.33279418945313]
["2017-01-23T22:03:15",60.020999908447266,138.33279418945313]
["2017-01-23T22:03:16",60.019001007080078,138.33279418945313]
["2017-01-23T22:03:17",60.018001556396484,138.33279418945313]
["2017-01-23T22:03:18",60.016998291015625,138.33279418945313]
["2017-01-23T22:03:19",60.014999389648438,138.33279418945313]
["2017-01-23T22:03:20",60.013999938964844,138.54519653320312]
["2017-01-23T22:03:21",60.01300048828125,138.54519653320312]
["2017-01-23T22:03:22",60.012001037597656,138.54519653320312]
["2017-01-23T22:03:23",60.012001037597656,138.54519653320312]
["2017-01-23T22:03:24",60.012001037597656,138.20976257324219]
["2017-01-23T22:03:25",60.013999938964844,138.20976257324219]
["2017-01-23T22:03:26",60.014999389648438,138.22189331054687]
["2017-01-23T22:03:27",60.015998840332031,138.22189331054687]
["2017-01-23T22:03:28",60.015998840332031,137.072998046875]
["2017-01-23T22:03:29",60.016998291015625,137.072998046875]
["2017-01-23T22:03:30",60.016998291015625,137.072998046875]
["2017-01-23T22:03:31",60.015998840332031,137.072998046875]
["2017-01-23T22:03:32",60.014999389648438,137.11550903320312]
["2017-01-23T22:03:33",60.014999389648438,137.11550903320312]
["2017-01-23T22:03:34",60.016998291015625,136.50177001953125]
["2017-01-23T22:03:35",60.016998291015625,136.50177001953125]
["2017-01-23T22:03:36",60.018001556396484,137.13664245605469]
["2017-01-23T22:03:37",60.018001556396484,137.13664245605469]
["2017-01-23T22:03:38",60.019001007080078,137.1131591796875]
["2017-01-23T22:03:39",60.018001556396484,137.1131591796875]
["2017-01-23T22:03:40",60.016998291015625,137.62672424316406]
["2017-01-23T22:03:41",60.015998840332031,137.62672424316406]
["2017-01-23T22:03:42",60.015998840332031,137.60771179199219]
["2017-01-23T22:03:43",60.013999938964844,137.60771179199219]
["2017-01-23T22:03:44",60.01300048828125,137.42384338378906]
["2017-01-23T22:03:45",60.012001037597656,137.42384338378906]
["2017-01-23T22:03:46",60.011001586914063,137.42384338378906]
["2017-01-23T22:03:47",60.012001037597656,137.42384338378906]
["2017-01-23T22:03:48",60.013999938964844,136.89720153808594]
["2017-01-23T22:03:49",60.015998840332031,136.89720153808594]
["2017-01-23T22:03:50",60.013999938964844,136.91693115234375]
["2017-01-23T22:03:51",60.011001586914063,136.91693115234375]
["2017-01-23T22:03:52",60.008998870849609,136.17793273925781]
["2017-01-23T22:03:53",60.006999969482422,136.17793273925781]
["2017-01-23T22:03:54",60.005001068115234,135.87713623046875]
["2017-01-23T22:03:55",60.002998352050781,135.87713623046875]
["2017-01-23T22:03:56",60.002998352050781,135.88827514648437]
["2017-01-23T22:03:57",60.002998352050781,135.88827514648437]
["2017-01-23T22:03:58",60.004001617431641,136.93376159667969]
["2017-01-23T22:03:59",60.005001068115234,136.93376159667969]
["2017-01-23T22:04:00",60.006000518798828,136.89508056640625]
["2017-01-23T22:04:01",60.006000518798828,136.89508056640625]
["2017-01-23T22:04:02",60.006999969482422,136.89508056640625]
["2017-01-23T22:04:03",60.007999420166016,136.89508056640625]
["2017-01-23T22:04:04",60.009998321533203,136.89508056640625]
["2017-01-23T22:04:05",60.011001586914063,136.89508056640625]
["2017-01-23T22:04:06",60.013999938964844,136.99899291992187]
["2017-01-23T22:04:07",60.013999938964844,136.99899291992187]
["2017-01-23T22:04:08",60.01300048828125,136.99899291992187]
["2017-01-23T22:04:09",60.011001586914063,136.99899291992187]
["2017-01-23T22:04:10",60.007999420166016,136.48265075683594]
["2017-01-23T22:04:11",60.004001617431641,136.48265075683594]
["2017-01-23T22:04:12",60,136.50161743164062]
["2017-01-23T22:04:13",59.997001647949219,136.50161743164062]
["2017-01-23T22:04:14",59.993000030517578,135.76263427734375]
["2017-01-23T22:04:15",59.990001678466797,135.76263427734375]
["2017-01-23T22:04:16",59.986000061035156,135.78997802734375]
["2017-01-23T22:04:17",59.981998443603516,135.78997802734375]
["2017-01-23T22:04:18",59.978000640869141,135.78997802734375]
["2017-01-23T22:04:19",59.976001739501953,135.78997802734375]
["2017-01-23T22:04:20",59.9739990234375,135.78997802734375]
["2017-01-23T22:04:21",59.972999572753906,135.78997802734375]
["2017-01-23T22:04:22",59.972999572753906,135.99407958984375]
["2017-01-23T22:04:23",59.972000122070313,135.99407958984375]
["2017-01-23T22:04:24",59.971000671386719,135.99407958984375]
["2017-01-23T22:04:25",59.969001770019531,135.99407958984375]
["2017-01-23T22:04:26",59.969001770019531,135.99407958984375]
["2017-01-23T22:04:27",59.969001770019531,135.99407958984375]
["2017-01-23T22:04:28",59.969001770019531,135.99407958984375]
["2017-01-23T22:04:29",59.971000671386719,135.99407958984375]
["2017-01-23T22:04:30",59.972000122070313,137.17620849609375]
["2017-01-23T22:04:31",59.9739990234375,137.17620849609375]
["2017-01-23T22:04:32",59.976001739501953,137.1322021484375]
["2017-01-23T22:04:33",59.976001739501953,137.1322021484375]
["2017-01-23T22:04:34",59.974998474121094,136.88774108886719]
["2017-01-23T22:04:35",59.972999572753906,136.88774108886719]
["2017-01-23T22:04:36",59.972999572753906,136.88774108886719]
["2017-01-23T22:04:37",59.972999572753906,136.88774108886719]
["2017-01-23T22:04:38",59.974998474121094,136.88774108886719]
["2017-01-23T22:04:39",59.976001739501953,136.88774108886719]
["2017-01-23T22:04:40",59.974998474121094,136.88774108886719]
["2017-01-23T22:04:41",59.9739990234375,136.88774108886719]
["2017-01-23T22:04:42",59.9739990234375,136.48629760742187]
["2017-01-23T22:04:43",59.9739990234375,136.48629760742187]
["2017-01-23T22:04:44",59.972999572753906,136.50148010253906]
["2017-01-23T22:04:45",59.972999572753906,136.50148010253906]
["2017-01-23T22:04:46",59.972999572753906,136.09075927734375]
["2017-01-23T22:04:47",59.972000122070313,136.09075927734375]
["2017-01-23T22:04:48",59.972000122070313,136.10595703125]
["2017-01-23T22:04:49",59.971000671386719,136.10595703125]
["2017-01-23T22:04:50",59.971000671386719,136.33097839355469]
["2017-01-23T22:04:51",59.970001220703125,136.33097839355469]
["2017-01-23T22:04:52",59.969001770019531,136.33097839355469]
["2017-01-23T22:04:53",59.967998504638672,136.33097839355469]
["2017-01-23T22:04:54",59.967998504638672,136.73312377929687]
["2017-01-23T22:04:55",59.967998504638672,136.73312377929687]
["2017-01-23T22:04:56",59.967998504638672,136.71792602539062]
["2017-01-23T22:04:57",59.967998504638672,136.71792602539062]
["2017-01-23T22:04:58",59.969001770019531,136.39036560058594]
["2017-01-23T22:04:59",59.969001770019531,136.39036560058594]
["2017-01-23T22:05:00",59.969001770019531,136.40248107910156]
["2017-01-23T22:05:01",59.969001770019531,136.40248107910156]
["2017-01-23T22:05:02",59.969001770019531,136.42254638671875]
["2017-01-23T22:05:03",59.969001770019531,136.42254638671875]
["2017-01-23T22:05:04",59.969001770019531,136.42254638671875]
["2017-01-23T22:05:05",59.967998504638672,136.42254638671875]
["2017-01-23T22:05:06",59.966999053955078,137.16011047363281]
["2017-01-23T22:05:07",59.967998504638672,137.16011047363281]
["2017-01-23T22:05:08",59.969001770019531,137.16011047363281]
["2017-01-23T22:05:09",59.969001770019531,137.16011047363281]
["2017-01-23T22:05:10",59.967998504638672,137.13279724121094]
["2017-01-23T22:05:11",59.967998504638672,137.13279724121094]
["2017-01-23T22:05:12",59.967998504638672,137.50900268554687]
["2017-01-23T22:05:13",59.969001770019531,137.50900268554687]
["2017-01-23T22:05:14",59.971000671386719,138.24781799316406]
["2017-01-23T22:05:15",59.971000671386719,138.24781799316406]
["2017-01-23T22:05:16",59.972000122070313,138.22047424316406]
["2017-01-23T22:05:17",59.972000122070313,138.22047424316406]
["2017-01-23T22:05:18",59.972000122070313,138.15997314453125]
["2017-01-23T22:05:19",59.971000671386719,138.15997314453125]
["2017-01-23T22:05:20",59.967998504638672,138.15997314453125]

{"sheet":"Calculations","index":3,"n_rows":279,"n_cols":35,"rows_kept":279,"cut":false,"hidden":false,"merged":[[38,6,40,14],[5,27,9,27],[43,17,47,17],[43,6,47,6],[43,7,47,7],[43,8,47,8],[43,9,47,9],[43,10,47,10],[43,11,47,11],[41,7,42,10],[43,12,47,12],[43,13,47,13],[43,14,47,14],[41,11,42,14],[3,27,4,29],[3,30,4,31],[41,0,42,0],[41,2,42,3],[43,0,47,0],[43,1,47,1],[43,2,47,2],[43,3,47,3],[5,28,9,28],[5,29,9,29],[5,30,9,30],[5,31,9,31],[43,4,47,4],[43,5,47,5],[43,15,47,15],[43,16,47,16]]}
["Offset (s)",{"$f":"Chart!$H$34","v":0},null,null,null,"Date (UTC):",null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!D19","v":"2017-01-24T03:50:20"}]
["*Offset should not be more than +/-38s",null,null,null,null,"Time of T(0) (UTC)",null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!D19","v":42759.159953703704},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"min frequency",{"$f":"IF(MIN(AC:AC)<59.975,FLOOR(MIN(AC:AC)-0.025,0.025),59.975)","v":59.775000000000006}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"max frequency",{"$f":"IF(MAX(AC:AC)>60.025,CEILING(MAX(AC:AC)+0.025,0.025),60.025)","v":60.024999999999999}]
["Calculated using Generator provided Historian Data",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Calculated using Generator provided manually calculated data",null,null,null,null,null,null,null,null,"Raw Input Data",null,null,"Interpolated Values",null,null,"frequency major unit",2.5000000000000001E-2]
[null,null,null,null,null,"Pre-Perturbation Average Frequency [T(-16) to T(-2)]",null,null,null,null,null,null,null,null,null,{"$f":"$E$105","v":59.978067270914714},null,null,null,"Pre-Perturbation Average Frequency [T(-16) to T(-2)]",{"$f":"'Main Data Entry'!E28","v":0},null,null,null,null,null,null,null,null,null,null,null,null,"frequency units",{"$f":"(AI3-AI2)/AI4","v":9.9999999999997158}]
[null,null,null,null,null,"Post-Perturbation Average Frequency [T(+20 to T(+52)]",null,null,null,null,null,null,null,null,null,{"$f":"$E$141","v":59.939423763390742},null,null,null,"Post-Perturbation Average Frequency [T(+20 to T(+52)]",{"$f":"'Main Data Entry'!E29","v":0},null,null,null,null,null,null,"Timestamp","Raw Frequency (Hz)","Raw Generator Output (MW)","Raw Frequency (Hz)","Raw Generator Output (MW)",null,"min response",{"$f":"CEILING(MIN(AD:AD)-10,10)","v":130}]
[null,null,null,null,null,"Pre to Post Perturbation Delta Frequency Actual",null,null,null,null,null,null,null,null,null,{"$f":"P6-P5","v":-3.8643507523971721E-2},null,null,null,"Pre to Post Perturbation Delta Frequency Actual",{"$f":"U6-U5","v":0},null,null,null,null,null,null,null,null,null,null,null,null,"max response",{"$f":"CEILING(MAX(AD:AD)+10,10)","v":180}]
[null,null,null,null,null,"Post-Perturbation Frequency (T+46)",null,null,null,null,null,null,null,null,null,{"$f":"$C$167","v":59.944000244140625},null,null,null,"Post-Perturbation Frequency (T+46)",{"$f":"'Main Data Entry'!E30","v":0},null,null,null,null,null,null,null,null,null,null,null,null,"response major unit",{"$f":"(AI7-AI6)/AI5","v":5.0000000000001421}]
[null,null,null,null,null,"Pre to Post-Event Delta Frequency Actual (T+46)",null,null,null,null,null,null,null,null,null,{"$f":"P8-P5","v":-3.4067026774089015E-2},null,null,null,"Pre to Post-Event Delta Frequency Actual (T+46)",{"$f":"U8-U5","v":0}]
[null,null,null,null,null,"High or Low Frequency Event?",null,null,null,null,null,null,null,null,null,{"$f":"IF(P6>'Main Data Entry'!D20,\"High\",IF(P6<'Main Data Entry'!D20,\"Low\",\"Does Not Compute\"))","v":"Low"},null,null,null,"High or Low Frequency Event?",{"$f":"IF(U6>'Main Data Entry'!$D$20,\"High\",IF(U6<'Main Data Entry'!$D$20,\"Low\",\"Does Not Compute\"))","v":"Low"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"AB12-TIME(0,0,1)","v":42759.158680555258},59.983001708984375,136.90745544433594,{"$f":"$AC$11","v":59.983001708984375},{"$f":"$AD$11","v":136.90745544433594}]
[null,null,null,null,null,"Pre-Perturbation Average MW [T(-2 ) to T(-16)]",null,null,null,null,null,null,null,null,null,{"$f":"$F$105","v":146.20244649251302},"Headroom Available:",{"$f":"'Main Data Entry'!G15-Calculations!P12","v":268.79755350748701},null,"Pre-Perturbation Average MW [T(-2 ) to T(-16)]",{"$f":"'Main Data Entry'!E31","v":0},"Headroom Available:",{"$f":"'Main Data Entry'!$G$15-Calculations!$U$12","v":415},null,null,null,null,42759.158692129335,59.983001708984375,136.89604187011719,{"$f":"IF($AC12=\"\",$AE11,IF($AC12<>$AE11,$AC12,$AE11))","v":59.983001708984375},{"$f":"IF($AD12=\"\",$AF11,IF($AD12<>$AF11,$AD12,$AF11))","v":136.89604187011719}]
[null,null,null,null,null,"Post-Perturbation Average MW [T(+20 to T(+52)]",null,null,null,null,null,null,null,null,null,{"$f":"$F$141","v":158.08755770596591},"Footroom Available:",{"$f":"P12-'Main Data Entry'!D16","v":21.202446492513019},null,"Post-Perturbation Average MW [T(+20 to T(+52)]",{"$f":"'Main Data Entry'!E32","v":0},"Footroom Available:",{"$f":"U12-'Main Data Entry'!$D$16","v":-125},null,null,null,null,42759.158703703411,59.984001159667969,136.89604187011719,59.984001159667969,136.89604187011719]
[null,null,null,null,null,"Pre to Post-Perturbation Delta MW Actual",null,null,null,null,null,null,null,null,null,{"$f":"P13-P12","v":11.885111213452888},"Adequate Margin?",{"$f":"IF(P10=\"Low\",IF(P12>=MIN(('Main Data Entry'!G15*0.98),'Main Data Entry'!G15-5),\"No\",\"Yes\"),IF(P10=\"High\",IF(Calculations!P12<=MAX(('Main Data Entry'!D16+('Main Data Entry'!G15*0.2)),('Main Data Entry'!D16+5)),\"No\",\"Yes\")))","v":"Yes"},null,"Pre to Post-Perturbation Delta MW Actual",{"$f":"U13-U12","v":0},"Adequate Margin?",{"$f":"IF(U10=\"Low\",IF(U12>=MIN(('Main Data Entry'!$G$15*0.98),'Main Data Entry'!$G$15-5),\"No\",\"Yes\"),IF(U10=\"High\",IF(Calculations!U12<=MAX(('Main Data Entry'!$D$16+('Main Data Entry'!$G$15*0.2)),('Main Data Entry'!$D$16+5)),\"No\",\"Yes\")))","v":"Yes"},null,null,null,null,42759.158715277488,59.981998443603516,136.69139099121094,59.981998443603516,136.69139099121094]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.158726851565,59.981998443603516,136.69139099121094,59.981998443603516,136.69139099121094]
[null,null,null,null,null,"RampMagnitude_initial",null,null,null,null,null,null,null,null,null,{"$f":"($D$117-$D$61)*0.59","v":3.7717651367187499},null,null,null,"RampMagnitude_initial",{"$f":"('Main Data Entry'!$E$34-'Main Data Entry'!$E$35)*0.59","v":0},null,null,null,null,null,null,42759.158738425642,59.979999542236328,136.69139099121094,59.979999542236328,136.69139099121094]
[null,null,null,null,null,"Actual Primary Frequency Response (adjusted)",null,null,null,null,null,null,null,null,null,{"$f":"P14-P16","v":8.1133460767341372},null,null,null,"Actual Primary Frequency Response (adjusted)",{"$f":"U14-U16","v":0},null,null,null,null,null,null,42759.158749999719,59.979999542236328,136.69139099121094,59.979999542236328,136.69139099121094]
[null,null,null,null,null,"Expected Primary Frequency Response (Pre)",null,null,null,null,null,null,null,null,null,{"$f":"$R$105","v":0.68624960455711714},null,null,null,"Expected Primary Frequency Response (Pre)",{"$f":"IF($U$5>'Main Data Entry'!$D$20+'Main Data Entry'!$D$14,((Calculations!$U$5-'Main Data Entry'!$D$20-'Main Data Entry'!$D$14)/('Main Data Entry'!$D$20*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*-1*'Main Data Entry'!$D$15,IF(Calculations!$U$5<'Main Data Entry'!$D$20-'Main Data Entry'!$D$14,((Calculations!$U$5-'Main Data Entry'!$D$20+'Main Data Entry'!$D$14)/('Main Data Entry'!$D$20*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*-1*'Main Data Entry'!$D$15,0))","v":8344.9363057324827},null,null,null,null,null,null,42759.158761573795,59.979999542236328,136.06294250488281,59.979999542236328,136.06294250488281]
[null,null,null,null,null,"Expected Primary Frequency Response (Post)",null,null,null,null,null,null,null,null,null,{"$f":"$R$141","v":6.0623996623672456},null,null,null,"Expected Primary Frequency Response (Post)",{"$f":"IF($U$6>'Main Data Entry'!$D$20+'Main Data Entry'!$D$14,((Calculations!$U$6-'Main Data Entry'!$D$20-'Main Data Entry'!$D$14)/('Main Data Entry'!$D$20*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*-1*'Main Data Entry'!$D$15,IF(Calculations!$U$6<'Main Data Entry'!$D$20-'Main Data Entry'!$D$14,((Calculations!$U$6-'Main Data Entry'!$D$20+'Main Data Entry'!$D$14)/('Main Data Entry'!$D$20*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*-1*'Main Data Entry'!$D$15,0))","v":8344.9363057324827},null,null,null,null,null,null,42759.158773147872,59.979999542236328,136.06294250488281,59.979999542236328,136.06294250488281]
[null,null,null,null,null,"Expected Primary Frequency Response (Ideal)",null,null,null,null,null,null,null,null,null,{"$f":"$P$19-$P$18","v":5.3761500578101282},null,null,null,"Expected Primary Frequency Response (Ideal)",{"$f":"U19-U18","v":0},null,null,null,null,null,null,42759.158784721949,59.979000091552734,136.08647155761719,59.979000091552734,136.08647155761719]
[null,null,null,null,null,"Expected Primary Frequency Response (Final)",null,null,null,null,null,null,null,null,null,{"$f":"$P$20","v":5.3761500578101282},null,null,null,"Expected Primary Frequency Response (Final)",{"$f":"U20","v":0},null,null,null,null,null,null,42759.158796296026,59.979000091552734,136.08647155761719,59.979000091552734,136.08647155761719]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.158807870102,59.979999542236328,135.55239868164062,59.979999542236328,135.55239868164062]
[null,null,null,null,null,"PUPFR Performance",null,null,null,null,null,null,null,null,null,{"$f":"IFERROR($P$17/$P$21,0)","v":1.5091368338849815},"Final PUPFR Performance",{"$f":"IFERROR(IF($R$14=\"Yes\",P23,\"No Evaluation\"),0)","v":1.5091368338849815},null,"PUPFR Performance",{"$f":"IFERROR(U17/U21,0)","v":0},"Final PUPFR Performance",{"$f":"IFERROR(IF($W$14=\"Yes\",U23,\"No Evaluation\"),0)","v":0},null,null,null,null,42759.158819444179,59.980998992919922,135.55239868164062,59.980998992919922,135.55239868164062]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.158831018256,59.981998443603516,135.57215881347656,59.981998443603516,135.57215881347656]
[null,null,null,null,null,"Maximum MW Response [T(+46) to T(+60)]",null,null,null,null,null,null,null,null,null,{"$f":"MAX($D$167:$D$181)","v":159.29545593261719},null,null,null,"Maximum MW Response [T(+46) to T(+60)]",{"$f":"'Main Data Entry'!$E$33","v":0},null,null,null,null,null,null,42759.158842592333,59.981998443603516,135.57215881347656,59.981998443603516,135.57215881347656]
[null,null,null,null,null,"Actual Sustained Primary Frequency Response",null,null,null,null,null,null,null,null,null,{"$f":"P25-P12","v":13.093009440104169},null,null,null,"Actual Sustained Primary Frequency Response",{"$f":"U25-U12","v":0},null,null,null,null,null,null,42759.15885416641,59.981998443603516,136.20716857910156,59.981998443603516,136.20716857910156]
[null,null,null,null,null,"RampMagnitude_sustained",null,null,null,null,null,null,null,null,null,{"$f":"($D$117-$D$61)*0.821","v":5.2485070800781246},null,null,null,"RampMagnitude_sustained",{"$f":"('Main Data Entry'!$E$34-'Main Data Entry'!$E$35)*0.821","v":0},null,null,null,null,null,null,42759.158865740486,59.980998992919922,136.20716857910156,59.980998992919922,136.20716857910156]
[null,null,null,null,null,"Actual Sustained Primary Frequency Response (adjusted)",null,null,null,null,null,null,null,null,null,{"$f":"$P$26-$P$27","v":7.844502360026044},null,null,null,"Actual Sustained Primary Frequency Response (adjusted)",{"$f":"U26-U27","v":0},null,null,null,null,null,null,42759.158877314563,59.979999542236328,136.18368530273437,59.979999542236328,136.18368530273437]
[null,null,null,null,null,"Expected Sustained Primary Frequency Response [T(+46)]",null,null,null,null,null,null,null,null,null,{"$f":"$Q$167","v":5.4257119281396662},null,null,null,"Expected Sustained Primary Frequency Response [T(+46)]",{"$f":"V108","v":0},null,null,null,null,null,null,42759.15888888864,59.979000091552734,136.18368530273437,59.979000091552734,136.18368530273437]
[null,null,null,null,null,"Expected Sustained Primary Frequency Response (Ideal)",null,null,null,null,null,null,null,null,null,{"$f":"$P$29-$P$18","v":4.7394623235825488},null,null,null,"Expected Sustained Primary Frequency Response (Ideal)",{"$f":"IF('Main Data Entry'!$E$30<'Main Data Entry'!$D$20-'Main Data Entry'!$D$14,(('Main Data Entry'!$E$30-'Main Data Entry'!$D$20+'Main Data Entry'!$D$14)/('Main Data Entry'!$D$20*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF('Main Data Entry'!$E$30>'Main Data Entry'!$D$20+'Main Data Entry'!$D$14,(('Main Data Entry'!$E$30-'Main Data Entry'!$D$20-'Main Data Entry'!$D$14)/('Main Data Entry'!$D$20*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":8344.9363057324827},null,null,null,null,null,null,42759.158900462717,59.979000091552734,136.61521911621094,59.979000091552734,136.61521911621094]
[null,null,null,null,null,"Expected Sustained Primary Frequency Response (Final)",null,null,null,null,null,null,null,null,null,{"$f":"$P$30","v":4.7394623235825488},null,null,null,"Expected Sustained Primary Frequency Response (Final)",{"$f":"U30","v":8344.9363057324827},null,null,null,null,null,null,42759.158912036793,59.979000091552734,136.61521911621094,59.979000091552734,136.61521911621094]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.15892361087,59.979999542236328,136.5992431640625,59.979999542236328,136.5992431640625]
[null,null,null,null,null,"PUSPFR Performance",null,null,null,null,null,null,null,null,null,{"$f":"IFERROR($P$28/$P$31,0)","v":1.6551460533810938},"Final PUSPFR Performance",{"$f":"IFERROR(IF($R$14=\"Yes\",P33,\"No Evaluation\"),0)","v":1.6551460533810938},null,"PUSPFR Performance",{"$f":"IFERROR(U28/U31,0)","v":0},"Final PUSPFR Performance",{"$f":"IFERROR(IF($W$14=\"Yes\",U33,\"No Evaluation\"),0)","v":0},null,null,null,null,42759.158935184947,59.979999542236328,136.5992431640625,59.979999542236328,136.5992431640625]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.158946759024,59.980998992919922,136.70237731933594,59.980998992919922,136.70237731933594]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.158958333101,59.980998992919922,136.70237731933594,59.980998992919922,136.70237731933594]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.158969907177,59.981998443603516,136.90364074707031,59.981998443603516,136.90364074707031]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.158981481254,59.981998443603516,136.90364074707031,59.981998443603516,136.90364074707031]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"AB39-TIME(0,0,1)","v":42759.158993055331},59.984001159667969,136.90364074707031,59.984001159667969,136.90364074707031]
[null,"Pre-Event Period",null,null,null,null,"Chart Values",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.159004629408,59.984001159667969,136.90364074707031,59.984001159667969,136.90364074707031]
[null,"T(0)",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.159016203484,59.985000610351563,138.47557067871094,59.985000610351563,138.47557067871094]
[null,"Post-Event Period",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.159027777561,59.985000610351563,138.47557067871094,59.985000610351563,138.47557067871094]
[null,"Input Data","Interpolated",null,"*Note that all times are in UTC time",null,null,"Pre and Post-Perturbation Average Values",null,null,null,"PFR Values",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.159039351638,59.986000061035156,138.41712951660156,59.986000061035156,138.41712951660156]
[null,null,null,null,"*Note that the first few rows in this might be blank depending on data provided.",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.159050925715,59.985000610351563,138.41712951660156,59.985000610351563,138.41712951660156]
["T","Offset Timestamp","Offset Frequency (Hz)","Offset Generator Output (MW)","Average Frequency (Hz)","Average Output (MW)","Proxy","Pre-Perturbation Frequency (Hz)","Post-Perturbation Frequency (Hz)","Pre-Perturbation Output (MW)","Post-Perturbation Output (MW)","Measured Initial Response (MW)","Expected Initial PFR (MW)","Measured Sustained Response (MW)","Expected Sustained PFR (MW)","HSL (MW)","Ideal Expected Primary Frequency Response (EPFR) (MW)","Average EPFR (MW)",null,null,null,null,null,null,null,null,null,42759.159062499792,59.984001159667969,139.69078063964844,59.984001159667969,139.69078063964844]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.159074073868,59.981998443603516,139.69078063964844,59.981998443603516,139.69078063964844]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.159085647945,59.980998992919922,139.64364624023437,59.980998992919922,139.64364624023437]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.159097222022,59.980998992919922,139.64364624023437,59.980998992919922,139.64364624023437]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"AB49-TIME(0,0,1)","v":42759.159108796099},59.980998992919922,139.76844787597656,59.980998992919922,139.76844787597656]
["T-72s",{"$f":"B50-TIME(0,0,1)","v":42759.159120370176},{"$f":"OFFSET($AE49,-$B$1,0)","v":59.983001708984375},{"$f":"OFFSET($AF49,-$B$1,0)","v":139.76844787597656},null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C49>(60+'Main Data Entry'!$D$14),(($C49-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C49<(60-'Main Data Entry'!$D$14),(($C49-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"AB50-TIME(0,0,1)","v":42759.159120370176},59.983001708984375,139.76844787597656,59.983001708984375,139.76844787597656]
["T-71s",{"$f":"B51-TIME(0,0,1)","v":42759.159131944252},59.983001708984375,139.76844787597656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C50>(60+'Main Data Entry'!$D$14),(($C50-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C50<(60-'Main Data Entry'!$D$14),(($C50-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0},null,null,null,null,null,null,null,null,null,null,42759.159131944252,59.983001708984375,139.76844787597656,59.983001708984375,139.76844787597656]
["T-70s",42759.159143518329,59.984001159667969,139.76844787597656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C51>(60+'Main Data Entry'!$D$14),(($C51-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C51<(60-'Main Data Entry'!$D$14),(($C51-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0},null,null,null,null,null,null,null,null,null,null,42759.159143518329,59.984001159667969,139.76844787597656,59.984001159667969,139.76844787597656]
["T-69s",42759.159155092406,59.984001159667969,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C52>(60+'Main Data Entry'!$D$14),(($C52-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C52<(60-'Main Data Entry'!$D$14),(($C52-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0},null,null,null,null,null,null,null,null,null,null,42759.159155092406,59.984001159667969,139.94856262207031,59.984001159667969,139.94856262207031]
["T-68s",42759.159166666483,59.983001708984375,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C53>(60+'Main Data Entry'!$D$14),(($C53-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C53<(60-'Main Data Entry'!$D$14),(($C53-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0},null,null,null,null,null,null,null,null,null,null,42759.159166666483,59.983001708984375,139.94856262207031,59.983001708984375,139.94856262207031]
["T-67s",42759.159178240559,59.981998443603516,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C54>(60+'Main Data Entry'!$D$14),(($C54-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C54<(60-'Main Data Entry'!$D$14),(($C54-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.13933821808280761},null,null,null,null,null,null,null,null,null,null,42759.159178240559,59.981998443603516,139.94856262207031,59.981998443603516,139.94856262207031]
["T-66s",42759.159189814636,59.981998443603516,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C55>(60+'Main Data Entry'!$D$14),(($C55-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C55<(60-'Main Data Entry'!$D$14),(($C55-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.13933821808280761},null,null,null,null,null,null,null,null,null,null,42759.159189814636,59.981998443603516,139.94856262207031,59.981998443603516,139.94856262207031]
["T-65s",42759.159201388713,59.979000091552734,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C56>(60+'Main Data Entry'!$D$14),(($C56-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C56<(60-'Main Data Entry'!$D$14),(($C56-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,42759.159201388713,59.979000091552734,139.94856262207031,59.979000091552734,139.94856262207031]
["T-64s",42759.15921296279,59.978000640869141,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C57>(60+'Main Data Entry'!$D$14),(($C57-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C57<(60-'Main Data Entry'!$D$14),(($C57-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},null,null,null,null,null,null,null,null,null,null,42759.15921296279,59.978000640869141,139.94856262207031,59.978000640869141,139.94856262207031]
["T-63s",42759.159224536867,59.977001190185547,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C58>(60+'Main Data Entry'!$D$14),(($C58-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C58<(60-'Main Data Entry'!$D$14),(($C58-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.83456455682133646},null,null,null,null,null,null,null,null,null,null,42759.159224536867,59.977001190185547,139.94856262207031,59.977001190185547,139.94856262207031]
["T-62s",42759.159236110943,59.976001739501953,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C59>(60+'Main Data Entry'!$D$14),(($C59-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C59<(60-'Main Data Entry'!$D$14),(($C59-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.9736098245690421},null,null,null,null,null,null,null,null,null,null,42759.159236110943,59.976001739501953,139.94856262207031,59.976001739501953,139.94856262207031]
["T-61s",42759.15924768502,59.977001190185547,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C60>(60+'Main Data Entry'!$D$14),(($C60-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C60<(60-'Main Data Entry'!$D$14),(($C60-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.83456455682133646},null,null,null,null,null,null,null,null,null,null,42759.15924768502,59.977001190185547,139.94856262207031,59.977001190185547,139.94856262207031]
["T-60s",42759.159259259097,59.978000640869141,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C61>(60+'Main Data Entry'!$D$14),(($C61-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C61<(60-'Main Data Entry'!$D$14),(($C61-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},null,null,null,null,null,null,null,null,null,null,42759.159259259097,59.978000640869141,139.94856262207031,59.978000640869141,139.94856262207031]
["T-59s",42759.159270833174,59.979000091552734,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C62>(60+'Main Data Entry'!$D$14),(($C62-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C62<(60-'Main Data Entry'!$D$14),(($C62-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,42759.159270833174,59.979000091552734,139.94856262207031,59.979000091552734,139.94856262207031]
["T-58s",42759.15928240725,59.979000091552734,139.94856262207031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C63>(60+'Main Data Entry'!$D$14),(($C63-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C63<(60-'Main Data Entry'!$D$14),(($C63-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,42759.15928240725,59.979000091552734,139.94856262207031,59.979000091552734,139.94856262207031]
["T-57s",42759.159293981327,59.979000091552734,141.02888488769531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C64>(60+'Main Data Entry'!$D$14),(($C64-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C64<(60-'Main Data Entry'!$D$14),(($C64-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,42759.159293981327,59.979000091552734,141.02888488769531,59.979000091552734,141.02888488769531]
["T-56s",42759.159305555404,59.979000091552734,141.02888488769531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C65>(60+'Main Data Entry'!$D$14),(($C65-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C65<(60-'Main Data Entry'!$D$14),(($C65-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,{"$f":"AB66-TIME(0,0,1)","v":42759.159305555404},59.979000091552734,141.02888488769531,59.979000091552734,141.02888488769531]
["T-55s",42759.159317129481,59.979999542236328,140.98867797851563,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C66>(60+'Main Data Entry'!$D$14),(($C66-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C66<(60-'Main Data Entry'!$D$14),(($C66-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.41742875357821907},null,null,null,null,null,null,null,null,null,null,42759.159317129481,59.979999542236328,140.98867797851563,59.979999542236328,140.98867797851563]
["T-54s",42759.159328703558,59.979999542236328,140.98867797851563,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C67>(60+'Main Data Entry'!$D$14),(($C67-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C67<(60-'Main Data Entry'!$D$14),(($C67-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.41742875357821907},null,null,null,null,null,null,null,null,null,null,42759.159328703558,59.979999542236328,140.98867797851563,59.979999542236328,140.98867797851563]
["T-53s",42759.159340277634,59.979000091552734,141.19523620605469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C68>(60+'Main Data Entry'!$D$14),(($C68-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C68<(60-'Main Data Entry'!$D$14),(($C68-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,42759.159340277634,59.979000091552734,141.19523620605469,59.979000091552734,141.19523620605469]
["T-52s",42759.159351851711,59.976001739501953,141.19523620605469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C69>(60+'Main Data Entry'!$D$14),(($C69-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C69<(60-'Main Data Entry'!$D$14),(($C69-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.9736098245690421},null,null,null,null,null,null,null,null,null,null,42759.159351851711,59.976001739501953,141.19523620605469,59.976001739501953,141.19523620605469]
["T-51s",42759.159363425788,59.974998474121094,141.19523620605469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C70>(60+'Main Data Entry'!$D$14),(($C70-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C70<(60-'Main Data Entry'!$D$14),(($C70-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":1.1131857994455558},null,null,null,null,null,null,null,null,null,null,42759.159363425788,59.974998474121094,141.19523620605469,59.974998474121094,141.19523620605469]
["T-50s",42759.159374999865,59.974998474121094,141.19523620605469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C71>(60+'Main Data Entry'!$D$14),(($C71-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C71<(60-'Main Data Entry'!$D$14),(($C71-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":1.1131857994455558},null,null,null,null,null,null,null,null,null,null,42759.159374999865,59.974998474121094,141.19523620605469,59.974998474121094,141.19523620605469]
["T-49s",42759.159386573941,59.9739990234375,140.22401428222656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C72>(60+'Main Data Entry'!$D$14),(($C72-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C72<(60-'Main Data Entry'!$D$14),(($C72-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":1.2522310671932617},null,null,null,null,null,null,null,null,null,null,42759.159386573941,59.9739990234375,140.22401428222656,59.9739990234375,140.22401428222656]
["T-48s",42759.159398148018,59.9739990234375,140.22401428222656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C73>(60+'Main Data Entry'!$D$14),(($C73-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C73<(60-'Main Data Entry'!$D$14),(($C73-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":1.2522310671932617},null,null,null,null,null,null,null,null,null,null,42759.159398148018,59.9739990234375,140.22401428222656,59.9739990234375,140.22401428222656]
["T-47s",42759.159409722095,59.9739990234375,140.25965881347656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C74>(60+'Main Data Entry'!$D$14),(($C74-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C74<(60-'Main Data Entry'!$D$14),(($C74-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":1.2522310671932617},null,null,null,null,null,null,null,null,null,null,42759.159409722095,59.9739990234375,140.25965881347656,59.9739990234375,140.25965881347656]
["T-46s",42759.159421296172,59.974998474121094,140.25965881347656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C75>(60+'Main Data Entry'!$D$14),(($C75-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C75<(60-'Main Data Entry'!$D$14),(($C75-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":1.1131857994455558},null,null,null,null,null,null,null,null,null,null,42759.159421296172,59.974998474121094,140.25965881347656,59.974998474121094,140.25965881347656]
["T-45s",42759.159432870249,59.976001739501953,140.25965881347656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C76>(60+'Main Data Entry'!$D$14),(($C76-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C76<(60-'Main Data Entry'!$D$14),(($C76-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.9736098245690421},null,null,null,null,null,null,null,null,null,null,42759.159432870249,59.976001739501953,140.25965881347656,{"$f":"IF($AC76=\"\",$AE75,IF($AC76<>$AE75,$AC76,$AE75))","v":59.976001739501953},{"$f":"IF($AD76=\"\",$AF75,IF($AD76<>$AF75,$AD76,$AF75))","v":140.25965881347656}]
["T-44s",42759.159444444325,59.978000640869141,140.25965881347656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C77>(60+'Main Data Entry'!$D$14),(($C77-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C77<(60-'Main Data Entry'!$D$14),(($C77-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},null,null,null,null,null,null,null,null,null,null,42759.159444444325,59.978000640869141,140.25965881347656,59.978000640869141,140.25965881347656]
["T-43s",42759.159456018402,59.978000640869141,140.25965881347656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C78>(60+'Main Data Entry'!$D$14),(($C78-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C78<(60-'Main Data Entry'!$D$14),(($C78-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},null,null,null,null,null,null,null,null,null,null,42759.159456018402,59.978000640869141,140.25965881347656,59.978000640869141,140.25965881347656]
["T-42s",42759.159467592479,59.978000640869141,140.25965881347656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C79>(60+'Main Data Entry'!$D$14),(($C79-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C79<(60-'Main Data Entry'!$D$14),(($C79-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},null,null,null,null,null,null,null,null,null,null,42759.159467592479,59.978000640869141,140.25965881347656,59.978000640869141,140.25965881347656]
["T-41s",42759.159479166556,59.979000091552734,140.99667358398437,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C80>(60+'Main Data Entry'!$D$14),(($C80-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C80<(60-'Main Data Entry'!$D$14),(($C80-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,42759.159479166556,59.979000091552734,140.99667358398437,59.979000091552734,140.99667358398437]
["T-40s",42759.159490740632,{"$f":"OFFSET($AE81,-$B$1,0)","v":59.979999542236328},{"$f":"OFFSET($AF81,-$B$1,0)","v":140.99667358398437},null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C81>(60+'Main Data Entry'!$D$14),(($C81-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C81<(60-'Main Data Entry'!$D$14),(($C81-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.41742875357821907},null,null,null,null,null,null,null,null,null,null,{"$f":"AB82-TIME(0,0,1)","v":42759.159490740632},59.979999542236328,140.99667358398437,59.979999542236328,140.99667358398437]
["T-39s",42759.159502314709,59.979999542236328,140.9693603515625,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C82>(60+'Main Data Entry'!$D$14),(($C82-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C82<(60-'Main Data Entry'!$D$14),(($C82-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.41742875357821907},null,null,null,null,null,null,null,null,null,null,42759.159502314709,59.979999542236328,140.9693603515625,59.979999542236328,140.9693603515625]
["T-38s",42759.159513888786,59.979999542236328,140.9693603515625,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C83>(60+'Main Data Entry'!$D$14),(($C83-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C83<(60-'Main Data Entry'!$D$14),(($C83-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.41742875357821907},null,null,null,null,null,null,null,null,null,null,42759.159513888786,59.979999542236328,140.9693603515625,59.979999542236328,140.9693603515625]
["T-37s",42759.159525462863,59.979999542236328,142.77505493164062,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C84>(60+'Main Data Entry'!$D$14),(($C84-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C84<(60-'Main Data Entry'!$D$14),(($C84-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.41742875357821907},null,null,null,null,null,null,null,null,null,null,42759.159525462863,59.979999542236328,142.77505493164062,59.979999542236328,142.77505493164062]
["T-36s",42759.15953703694,59.979000091552734,142.77505493164062,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C85>(60+'Main Data Entry'!$D$14),(($C85-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C85<(60-'Main Data Entry'!$D$14),(($C85-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,42759.15953703694,59.979000091552734,142.77505493164062,59.979000091552734,142.77505493164062]
["T-35s",42759.159548611016,59.979000091552734,142.70823669433594,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C86>(60+'Main Data Entry'!$D$14),(($C86-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C86<(60-'Main Data Entry'!$D$14),(($C86-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,42759.159548611016,59.979000091552734,142.70823669433594,59.979000091552734,142.70823669433594]
["T-34s",42759.159560185093,59.978000640869141,142.70823669433594,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C87>(60+'Main Data Entry'!$D$14),(($C87-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C87<(60-'Main Data Entry'!$D$14),(($C87-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},null,null,null,null,null,null,null,null,null,null,42759.159560185093,59.978000640869141,142.70823669433594,59.978000640869141,142.70823669433594]
["T-33s",42759.15957175917,59.978000640869141,143.53103637695312,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C88>(60+'Main Data Entry'!$D$14),(($C88-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C88<(60-'Main Data Entry'!$D$14),(($C88-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},null,null,null,null,null,null,null,null,null,null,42759.15957175917,59.978000640869141,143.53103637695312,59.978000640869141,143.53103637695312]
["T-32s",42759.159583333247,59.977001190185547,143.53103637695312,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C89>(60+'Main Data Entry'!$D$14),(($C89-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C89<(60-'Main Data Entry'!$D$14),(($C89-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.83456455682133646},null,null,null,null,null,null,null,null,null,null,42759.159583333247,59.977001190185547,143.53103637695312,59.977001190185547,143.53103637695312]
["T-31s",42759.159594907323,59.978000640869141,143.50057983398437,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C90>(60+'Main Data Entry'!$D$14),(($C90-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C90<(60-'Main Data Entry'!$D$14),(($C90-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},null,null,null,null,null,null,null,null,null,null,42759.159594907323,59.978000640869141,143.50057983398437,59.978000640869141,143.50057983398437]
["T-30s",42759.1596064814,59.978000640869141,143.50057983398437,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C91>(60+'Main Data Entry'!$D$14),(($C91-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C91<(60-'Main Data Entry'!$D$14),(($C91-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},null,null,null,null,null,null,null,null,null,null,42759.1596064814,59.978000640869141,143.50057983398437,59.978000640869141,143.50057983398437]
["T-29s",42759.159618055477,59.978000640869141,142.989013671875,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C92>(60+'Main Data Entry'!$D$14),(($C92-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C92<(60-'Main Data Entry'!$D$14),(($C92-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},null,null,null,null,null,null,null,null,null,null,42759.159618055477,59.978000640869141,142.989013671875,59.978000640869141,142.989013671875]
["T-28s",42759.159629629554,59.976001739501953,142.989013671875,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C93>(60+'Main Data Entry'!$D$14),(($C93-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C93<(60-'Main Data Entry'!$D$14),(($C93-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.9736098245690421},null,null,null,null,null,null,null,null,null,null,42759.159629629554,59.976001739501953,142.989013671875,59.976001739501953,142.989013671875]
["T-27s",42759.159641203631,59.976001739501953,143.00794982910156,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C94>(60+'Main Data Entry'!$D$14),(($C94-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C94<(60-'Main Data Entry'!$D$14),(($C94-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.9736098245690421},null,null,null,null,null,null,null,null,null,null,42759.159641203631,59.976001739501953,143.00794982910156,59.976001739501953,143.00794982910156]
["T-26s",42759.159652777707,59.976001739501953,143.00794982910156,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C95>(60+'Main Data Entry'!$D$14),(($C95-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C95<(60-'Main Data Entry'!$D$14),(($C95-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.9736098245690421},null,null,null,null,null,null,null,null,null,null,42759.159652777707,59.976001739501953,143.00794982910156,59.976001739501953,143.00794982910156]
["T-25s",42759.159664351784,59.976001739501953,143.08927917480469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C96>(60+'Main Data Entry'!$D$14),(($C96-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C96<(60-'Main Data Entry'!$D$14),(($C96-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.9736098245690421},null,null,null,null,null,null,null,null,null,null,42759.159664351784,59.976001739501953,143.08927917480469,59.976001739501953,143.08927917480469]
["T-24s",42759.159675925861,59.976001739501953,143.08927917480469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C97>(60+'Main Data Entry'!$D$14),(($C97-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C97<(60-'Main Data Entry'!$D$14),(($C97-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.9736098245690421},null,null,null,null,null,null,null,null,null,null,{"$f":"AB98-TIME(0,0,1)","v":42759.159675925861},59.976001739501953,143.08927917480469,59.976001739501953,143.08927917480469]
["T-23s",42759.159687499938,59.977001190185547,143.08927917480469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C98>(60+'Main Data Entry'!$D$14),(($C98-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C98<(60-'Main Data Entry'!$D$14),(($C98-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.83456455682133646},null,null,null,null,null,null,null,null,null,null,42759.159687499938,59.977001190185547,143.08927917480469,59.977001190185547,143.08927917480469]
["T-22s",42759.159699074014,59.979000091552734,143.08927917480469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C99>(60+'Main Data Entry'!$D$14),(($C99-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C99<(60-'Main Data Entry'!$D$14),(($C99-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,42759.159699074014,59.979000091552734,143.08927917480469,59.979000091552734,143.08927917480469]
["T-21s",42759.159710648091,59.979000091552734,144.25532531738281,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C100>(60+'Main Data Entry'!$D$14),(($C100-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C100<(60-'Main Data Entry'!$D$14),(($C100-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,42759.159710648091,59.979000091552734,144.25532531738281,59.979000091552734,144.25532531738281]
["T-20s",42759.159722222168,59.979999542236328,144.25532531738281,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C101>(60+'Main Data Entry'!$D$14),(($C101-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C101<(60-'Main Data Entry'!$D$14),(($C101-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.41742875357821907},null,null,null,null,null,null,null,null,null,null,42759.159722222168,59.979999542236328,144.25532531738281,59.979999542236328,144.25532531738281]
["T-19s",42759.159733796245,59.979999542236328,144.21206665039062,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C102>(60+'Main Data Entry'!$D$14),(($C102-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C102<(60-'Main Data Entry'!$D$14),(($C102-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.41742875357821907},null,null,null,null,null,null,null,null,null,null,42759.159733796245,59.979999542236328,144.21206665039062,59.979999542236328,144.21206665039062]
["T-18s",42759.159745370322,59.979999542236328,144.21206665039062,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C103>(60+'Main Data Entry'!$D$14),(($C103-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C103<(60-'Main Data Entry'!$D$14),(($C103-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.41742875357821907},null,null,null,null,null,null,null,null,null,null,42759.159745370322,59.979999542236328,144.21206665039062,59.979999542236328,144.21206665039062]
["T-17s",42759.159756944398,59.979000091552734,145.13652038574219,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C104>(60+'Main Data Entry'!$D$14),(($C104-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C104<(60-'Main Data Entry'!$D$14),(($C104-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},null,null,null,null,null,null,null,null,null,null,42759.159756944398,59.979000091552734,145.13652038574219,59.979000091552734,145.13652038574219]
["T-16s",42759.159768518475,59.978000640869141,145.13652038574219,{"$f":"AVERAGE($C$105:$C$119)","v":59.978067270914714},{"$f":"AVERAGE($D$105:$D$119)","v":146.20244649251302},null,{"$f":"E105","v":59.978067270914714},null,{"$f":"F105","v":146.20244649251302},null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C105>(60+'Main Data Entry'!$D$14),(($C105-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C105<(60-'Main Data Entry'!$D$14),(($C105-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},{"$f":"AVERAGE($Q$105:$Q$119)","v":0.68624960455711714},null,null,null,null,null,null,null,null,null,42759.159768518475,59.978000640869141,145.13652038574219,59.978000640869141,145.13652038574219]
["T-15s",42759.159780092552,59.977001190185547,145.10231018066406,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C106>(60+'Main Data Entry'!$D$14),(($C106-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C106<(60-'Main Data Entry'!$D$14),(($C106-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.83456455682133646},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.159780092552,59.977001190185547,145.10231018066406,59.977001190185547,145.10231018066406]
["T-14s",42759.159791666629,59.977001190185547,145.10231018066406,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C107>(60+'Main Data Entry'!$D$14),(($C107-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C107<(60-'Main Data Entry'!$D$14),(($C107-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.83456455682133646},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.159791666629,59.977001190185547,145.10231018066406,59.977001190185547,145.10231018066406]
["T-13s",42759.159803240706,59.977001190185547,146.53912353515625,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C108>(60+'Main Data Entry'!$D$14),(($C108-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C108<(60-'Main Data Entry'!$D$14),(($C108-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.83456455682133646},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.159803240706,59.977001190185547,146.53912353515625,59.977001190185547,146.53912353515625]
["T-12s",42759.159814814782,59.977001190185547,146.53912353515625,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C109>(60+'Main Data Entry'!$D$14),(($C109-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C109<(60-'Main Data Entry'!$D$14),(($C109-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.83456455682133646},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.159814814782,59.977001190185547,146.53912353515625,59.977001190185547,146.53912353515625]
["T-11s",42759.159826388859,59.978000640869141,146.4859619140625,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C110>(60+'Main Data Entry'!$D$14),(($C110-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C110<(60-'Main Data Entry'!$D$14),(($C110-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.159826388859,59.978000640869141,146.4859619140625,59.978000640869141,146.4859619140625]
["T-10s",42759.159837962936,59.978000640869141,146.4859619140625,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C111>(60+'Main Data Entry'!$D$14),(($C111-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C111<(60-'Main Data Entry'!$D$14),(($C111-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.69551928907363059},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.159837962936,59.978000640869141,146.4859619140625,59.978000640869141,146.4859619140625]
["T-9s",42759.159849537013,59.977001190185547,146.56996154785156,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C112>(60+'Main Data Entry'!$D$14),(($C112-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C112<(60-'Main Data Entry'!$D$14),(($C112-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.83456455682133646},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.159849537013,59.977001190185547,146.56996154785156,59.977001190185547,146.56996154785156]
["T-8s",42759.159861111089,{"$f":"OFFSET($AE113,-$B$1,0)","v":59.977001190185547},{"$f":"OFFSET($AF113,-$B$1,0)","v":146.56996154785156},59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C113>(60+'Main Data Entry'!$D$14),(($C113-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C113<(60-'Main Data Entry'!$D$14),(($C113-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.83456455682133646},0.68624960455711714,null,null,null,null,null,null,null,null,null,{"$f":"AB114-TIME(0,0,1)","v":42759.159861111089},59.977001190185547,146.56996154785156,59.977001190185547,146.56996154785156]
["T-7s",{"$f":"B115-TIME(0,0,1)","v":42759.159872685166},59.977001190185547,146.56996154785156,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C114>(60+'Main Data Entry'!$D$14),(($C114-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C114<(60-'Main Data Entry'!$D$14),(($C114-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.83456455682133646},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.159872685166,59.977001190185547,146.56996154785156,59.977001190185547,146.56996154785156]
["T-6s",42759.159884259243,59.979000091552734,146.56996154785156,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C115>(60+'Main Data Entry'!$D$14),(($C115-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C115<(60-'Main Data Entry'!$D$14),(($C115-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.159884259243,59.979000091552734,146.56996154785156,59.979000091552734,146.56996154785156]
["T-5s",42759.15989583332,59.979000091552734,146.34138488769531,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C116>(60+'Main Data Entry'!$D$14),(($C116-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C116<(60-'Main Data Entry'!$D$14),(($C116-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.15989583332,59.979000091552734,146.34138488769531,59.979000091552734,146.34138488769531]
["T-4s",42759.159907407397,59.979999542236328,146.34138488769531,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C117>(60+'Main Data Entry'!$D$14),(($C117-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C117<(60-'Main Data Entry'!$D$14),(($C117-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.41742875357821907},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.159907407397,59.979999542236328,146.34138488769531,59.979999542236328,146.34138488769531]
["T-3s",42759.159918981473,59.979000091552734,146.34138488769531,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C118>(60+'Main Data Entry'!$D$14),(($C118-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C118<(60-'Main Data Entry'!$D$14),(($C118-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.55647402132592483},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.159918981473,59.979000091552734,146.34138488769531,59.979000091552734,146.34138488769531]
["T-2s",42759.15993055555,59.980998992919922,146.34138488769531,59.978067270914714,146.20244649251302,null,59.978067270914714,null,146.20244649251302,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C119>(60+'Main Data Entry'!$D$14),(($C119-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C119<(60-'Main Data Entry'!$D$14),(($C119-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.27838348583051337},0.68624960455711714,null,null,null,null,null,null,null,null,null,42759.15993055555,59.980998992919922,146.34138488769531,59.980998992919922,146.34138488769531]
["T-1s",42759.159942129627,59.980998992919922,146.45195007324219,null,null,-1000000000,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C120>(60+'Main Data Entry'!$D$14),(($C120-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C120<(60-'Main Data Entry'!$D$14),(($C120-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0.27838348583051337},null,null,null,null,null,null,null,null,null,null,42759.159942129627,59.980998992919922,146.45195007324219,59.980998992919922,146.45195007324219]
["T=0",{"$f":"$P$2+IF($B$1>0,-TIME(0,0,ABS($B$1)),+TIME(0,0,ABS($B$1)))","v":42759.159953703704},59.985000610351563,146.45195007324219,null,null,60,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C121>(60+'Main Data Entry'!$D$14),(($C121-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C121<(60-'Main Data Entry'!$D$14),(($C121-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"$P$2","v":42759.159953703704},59.985000610351563,146.45195007324219,59.985000610351563,146.45195007324219]
["T+1s",{"$f":"B121+TIME(0,0,1)","v":42759.15996527778},59.985000610351563,146.45195007324219,null,null,1000000000,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C122>(60+'Main Data Entry'!$D$14),(($C122-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C122<(60-'Main Data Entry'!$D$14),(($C122-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"AB121+TIME(0,0,1)","v":42759.15996527778},59.985000610351563,146.45195007324219,59.985000610351563,146.45195007324219]
["T+2s",{"$f":"B122+TIME(0,0,1)","v":42759.159976851857},59.941001892089844,146.45195007324219,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C123>(60+'Main Data Entry'!$D$14),(($C123-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C123<(60-'Main Data Entry'!$D$14),(($C123-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.8428477313827827},null,null,null,null,null,null,null,null,null,null,42759.159976851857,59.941001892089844,146.45195007324219,59.941001892089844,146.45195007324219]
["T+3s",42759.159988425934,59.869998931884766,146.89949035644531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C124>(60+'Main Data Entry'!$D$14),(($C124-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C124<(60-'Main Data Entry'!$D$14),(($C124-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":15.720899519886782},null,null,null,null,null,null,null,null,null,null,42759.159988425934,59.869998931884766,146.89949035644531,59.869998931884766,146.89949035644531]
["T+4s",42759.160000000011,59.824001312255859,146.89949035644531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C125>(60+'Main Data Entry'!$D$14),(($C125-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C125<(60-'Main Data Entry'!$D$14),(($C125-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":22.120166079054091},null,null,null,null,null,null,null,null,null,null,42759.160000000011,59.824001312255859,146.89949035644531,59.824001312255859,146.89949035644531]
["T+5s",42759.160011574088,59.808998107910156,146.88278198242187,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C126>(60+'Main Data Entry'!$D$14),(($C126-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C126<(60-'Main Data Entry'!$D$14),(($C126-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":24.2074372166561},null,null,null,null,null,null,null,null,null,null,42759.160011574088,59.808998107910156,146.88278198242187,59.808998107910156,146.88278198242187]
["T+6s",42759.160023148164,59.808998107910156,146.88278198242187,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C127>(60+'Main Data Entry'!$D$14),(($C127-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C127<(60-'Main Data Entry'!$D$14),(($C127-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":24.2074372166561},null,null,null,null,null,null,null,null,null,null,42759.160023148164,59.808998107910156,146.88278198242187,59.808998107910156,146.88278198242187]
["T+7s",42759.160034722241,59.810001373291016,147.60118103027344,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C128>(60+'Main Data Entry'!$D$14),(($C128-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C128<(60-'Main Data Entry'!$D$14),(($C128-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":24.067861241779589},null,null,null,null,null,null,null,null,null,null,42759.160034722241,59.810001373291016,147.60118103027344,59.810001373291016,147.60118103027344]
["T+8s",42759.160046296318,59.838001251220703,147.60118103027344,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C129>(60+'Main Data Entry'!$D$14),(($C129-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C129<(60-'Main Data Entry'!$D$14),(($C129-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":20.172470916328592},null,null,null,null,null,null,null,null,null,null,42759.160046296318,59.838001251220703,147.60118103027344,59.838001251220703,147.60118103027344]
["T+9s",42759.160057870395,59.838001251220703,147.57460021972656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C130>(60+'Main Data Entry'!$D$14),(($C130-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C130<(60-'Main Data Entry'!$D$14),(($C130-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":20.172470916328592},null,null,null,null,null,null,null,null,null,null,42759.160057870395,59.838001251220703,147.57460021972656,59.838001251220703,147.57460021972656]
["T+10s",42759.160069444471,59.855998992919922,147.57460021972656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C131>(60+'Main Data Entry'!$D$14),(($C131-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C131<(60-'Main Data Entry'!$D$14),(($C131-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":17.668594682612273},null,null,null,null,null,null,null,null,null,null,42759.160069444471,59.855998992919922,147.57460021972656,59.855998992919922,147.57460021972656]
["T+11s",42759.160081018548,59.873001098632813,153.15370178222656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C132>(60+'Main Data Entry'!$D$14),(($C132-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C132<(60-'Main Data Entry'!$D$14),(($C132-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":15.303233009514853},null,null,null,null,null,null,null,null,null,null,42759.160081018548,59.873001098632813,153.15370178222656,59.873001098632813,153.15370178222656]
["T+12s",42759.160092592625,59.898998260498047,153.15370178222656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C133>(60+'Main Data Entry'!$D$14),(($C133-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C133<(60-'Main Data Entry'!$D$14),(($C133-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":11.686463926688081},null,null,null,null,null,null,null,null,null,null,42759.160092592625,59.898998260498047,153.15370178222656,59.898998260498047,153.15370178222656]
["T+13s",42759.160104166702,59.898998260498047,152.94728088378906,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C134>(60+'Main Data Entry'!$D$14),(($C134-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C134<(60-'Main Data Entry'!$D$14),(($C134-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":11.686463926688081},null,null,null,null,null,null,null,null,null,null,42759.160104166702,59.898998260498047,152.94728088378906,59.898998260498047,152.94728088378906]
["T+14s",42759.160115740779,59.915000915527344,152.94728088378906,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C135>(60+'Main Data Entry'!$D$14),(($C135-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C135<(60-'Main Data Entry'!$D$14),(($C135-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":9.4601475213383655},null,null,null,null,null,null,null,null,null,null,42759.160115740779,59.915000915527344,152.94728088378906,59.915000915527344,152.94728088378906]
["T+15s",42759.160127314855,59.916999816894531,152.66780090332031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C136>(60+'Main Data Entry'!$D$14),(($C136-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C136<(60-'Main Data Entry'!$D$14),(($C136-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":9.1820569858429533},null,null,null,null,null,null,null,null,null,null,42759.160127314855,59.916999816894531,152.66780090332031,59.916999816894531,152.66780090332031]
["T+16s",42759.160138888932,59.916000366210938,152.66780090332031,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C137>(60+'Main Data Entry'!$D$14),(($C137-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C137<(60-'Main Data Entry'!$D$14),(($C137-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":9.3211022535906594},null,null,null,null,null,null,null,null,null,null,42759.160138888932,59.916000366210938,152.66780090332031,59.916000366210938,152.66780090332031]
["T+17s",42759.160150463009,59.916000366210938,152.67814636230469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C138>(60+'Main Data Entry'!$D$14),(($C138-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C138<(60-'Main Data Entry'!$D$14),(($C138-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":9.3211022535906594},null,null,null,null,null,null,null,null,null,null,{"$f":"AB137+TIME(0,0,1)","v":42759.160150463009},59.916000366210938,152.67814636230469,59.916000366210938,152.67814636230469]
["T+18s",42759.160162037086,59.919998168945313,152.67814636230469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C139>(60+'Main Data Entry'!$D$14),(($C139-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C139<(60-'Main Data Entry'!$D$14),(($C139-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":8.764921182599835},null,null,null,null,null,null,null,null,null,null,42759.160162037086,59.919998168945313,152.67814636230469,59.919998168945313,152.67814636230469]
["T+19s",42759.160173611162,59.929000854492187,156.98440551757812,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C140>(60+'Main Data Entry'!$D$14),(($C140-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C140<(60-'Main Data Entry'!$D$14),(($C140-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":7.512452358612868},null,null,null,null,null,null,null,null,null,null,42759.160173611162,59.929000854492187,156.98440551757812,{"$f":"IF($AC140=\"\",$AE139,IF($AC140<>$AE139,$AC140,$AE139))","v":59.929000854492187},{"$f":"IF($AD140=\"\",$AF139,IF($AD140<>$AF139,$AD140,$AF139))","v":156.98440551757812}]
["T+20s",42759.160185185239,59.930999755859375,156.98440551757812,{"$f":"AVERAGE($C$141:$C$173)","v":59.939423763390742},{"$f":"AVERAGE($D$141:$D$173)","v":158.08755770596591},null,null,{"$f":"E141","v":59.939423763390742},null,{"$f":"F141","v":158.08755770596591},{"$f":"P$12+P$17","v":154.31579256924715},{"$f":"P$12+P$21","v":151.57859655032314},null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C141>(60+'Main Data Entry'!$D$14),(($C141-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C141<(60-'Main Data Entry'!$D$14),(($C141-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":7.2343618231174567},{"$f":"AVERAGE($Q$141:$Q$173)","v":6.0623996623672456},null,null,null,null,null,null,null,null,null,42759.160185185239,59.930999755859375,156.98440551757812,59.930999755859375,156.98440551757812]
["T+21s",42759.160196759316,59.930999755859375,156.8250732421875,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,{"$f":"P$12+P$17","v":154.31579256924715},{"$f":"P$12+P$21","v":151.57859655032314},null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C142>(60+'Main Data Entry'!$D$14),(($C142-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C142<(60-'Main Data Entry'!$D$14),(($C142-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":7.2343618231174567},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160196759316,59.930999755859375,156.8250732421875,59.930999755859375,156.8250732421875]
["T+22s",42759.160208333393,59.932998657226562,156.8250732421875,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C143>(60+'Main Data Entry'!$D$14),(($C143-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C143<(60-'Main Data Entry'!$D$14),(($C143-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.9562712876220463},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160208333393,59.932998657226562,156.8250732421875,59.932998657226562,156.8250732421875]
["T+23s",42759.16021990747,59.933998107910156,160.39932250976562,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C144>(60+'Main Data Entry'!$D$14),(($C144-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C144<(60-'Main Data Entry'!$D$14),(($C144-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.8172260198743402},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.16021990747,59.933998107910156,160.39932250976562,59.933998107910156,160.39932250976562]
["T+24s",42759.160231481546,{"$f":"OFFSET($AE145,-$B$1,0)","v":59.933998107910156},{"$f":"OFFSET($AF145,-$B$1,0)","v":160.39932250976562},59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C145>(60+'Main Data Entry'!$D$14),(($C145-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C145<(60-'Main Data Entry'!$D$14),(($C145-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.8172260198743402},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160231481546,59.933998107910156,160.39932250976562,59.933998107910156,160.39932250976562]
["T+25s",42759.160243055623,59.935001373291016,160.26707458496094,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C146>(60+'Main Data Entry'!$D$14),(($C146-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C146<(60-'Main Data Entry'!$D$14),(($C146-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.6776500449978267},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160243055623,59.935001373291016,160.26707458496094,59.935001373291016,160.26707458496094]
["T+26s",42759.1602546297,59.937000274658203,160.26707458496094,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C147>(60+'Main Data Entry'!$D$14),(($C147-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C147<(60-'Main Data Entry'!$D$14),(($C147-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.1602546297,59.937000274658203,160.26707458496094,59.937000274658203,160.26707458496094]
["T+27s",42759.160266203777,59.937000274658203,159.98486328125,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C148>(60+'Main Data Entry'!$D$14),(($C148-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C148<(60-'Main Data Entry'!$D$14),(($C148-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160266203777,59.937000274658203,159.98486328125,59.937000274658203,159.98486328125]
["T+28s",42759.160277777853,59.939998626708984,159.98486328125,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C149>(60+'Main Data Entry'!$D$14),(($C149-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C149<(60-'Main Data Entry'!$D$14),(($C149-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.9824237062592971},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160277777853,59.939998626708984,159.98486328125,59.939998626708984,159.98486328125]
["T+29s",42759.16028935193,59.939998626708984,159.99530029296875,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C150>(60+'Main Data Entry'!$D$14),(($C150-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C150<(60-'Main Data Entry'!$D$14),(($C150-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.9824237062592971},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.16028935193,59.939998626708984,159.99530029296875,59.939998626708984,159.99530029296875]
["T+30s",42759.160300926007,59.938999176025391,159.99530029296875,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C151>(60+'Main Data Entry'!$D$14),(($C151-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C151<(60-'Main Data Entry'!$D$14),(($C151-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.1214689740070023},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160300926007,59.938999176025391,159.99530029296875,59.938999176025391,159.99530029296875]
["T+31s",42759.160312500084,59.937000274658203,158.84648132324219,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C152>(60+'Main Data Entry'!$D$14),(($C152-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C152<(60-'Main Data Entry'!$D$14),(($C152-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160312500084,59.937000274658203,158.84648132324219,59.937000274658203,158.84648132324219]
["T+32s",42759.160324074161,59.937000274658203,158.84648132324219,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C153>(60+'Main Data Entry'!$D$14),(($C153-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C153<(60-'Main Data Entry'!$D$14),(($C153-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160324074161,59.937000274658203,158.84648132324219,59.937000274658203,158.84648132324219]
["T+33s",42759.160335648237,59.937000274658203,158.88899230957031,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C154>(60+'Main Data Entry'!$D$14),(($C154-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C154<(60-'Main Data Entry'!$D$14),(($C154-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},6.0623996623672456,null,null,null,null,null,null,null,null,null,{"$f":"AB153+TIME(0,0,1)","v":42759.160335648237},59.937000274658203,158.88899230957031,59.937000274658203,158.88899230957031]
["T+34s",42759.160347222314,59.937000274658203,158.88899230957031,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C155>(60+'Main Data Entry'!$D$14),(($C155-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C155<(60-'Main Data Entry'!$D$14),(($C155-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160347222314,59.937000274658203,158.88899230957031,59.937000274658203,158.88899230957031]
["T+35s",42759.160358796391,59.937000274658203,157.90304565429688,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C156>(60+'Main Data Entry'!$D$14),(($C156-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C156<(60-'Main Data Entry'!$D$14),(($C156-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160358796391,59.937000274658203,157.90304565429688,59.937000274658203,157.90304565429688]
["T+36s",42759.160370370468,59.937000274658203,157.90304565429688,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C157>(60+'Main Data Entry'!$D$14),(($C157-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C157<(60-'Main Data Entry'!$D$14),(($C157-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160370370468,59.937000274658203,157.90304565429688,59.937000274658203,157.90304565429688]
["T+37s",42759.160381944544,59.937000274658203,157.93951416015625,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C158>(60+'Main Data Entry'!$D$14),(($C158-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C158<(60-'Main Data Entry'!$D$14),(($C158-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160381944544,59.937000274658203,157.93951416015625,59.937000274658203,157.93951416015625]
["T+38s",42759.160393518621,59.938999176025391,157.93951416015625,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C159>(60+'Main Data Entry'!$D$14),(($C159-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C159<(60-'Main Data Entry'!$D$14),(($C159-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.1214689740070023},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160393518621,59.938999176025391,157.93951416015625,59.938999176025391,157.93951416015625]
["T+39s",42759.160405092698,59.939998626708984,157.34344482421875,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C160>(60+'Main Data Entry'!$D$14),(($C160-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C160<(60-'Main Data Entry'!$D$14),(($C160-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.9824237062592971},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160405092698,59.939998626708984,157.34344482421875,59.939998626708984,157.34344482421875]
["T+40s",42759.160416666775,59.939998626708984,157.34344482421875,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C161>(60+'Main Data Entry'!$D$14),(($C161-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C161<(60-'Main Data Entry'!$D$14),(($C161-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.9824237062592971},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160416666775,59.939998626708984,157.34344482421875,59.939998626708984,157.34344482421875]
["T+41s",42759.160428240852,59.939998626708984,157.36549377441406,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C162>(60+'Main Data Entry'!$D$14),(($C162-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C162<(60-'Main Data Entry'!$D$14),(($C162-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.9824237062592971},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160428240852,59.939998626708984,157.36549377441406,59.939998626708984,157.36549377441406]
["T+42s",42759.160439814928,59.939998626708984,157.36549377441406,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C163>(60+'Main Data Entry'!$D$14),(($C163-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C163<(60-'Main Data Entry'!$D$14),(($C163-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.9824237062592971},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160439814928,59.939998626708984,157.36549377441406,59.939998626708984,157.36549377441406]
["T+43s",42759.160451389005,59.942001342773438,157.13909912109375,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C164>(60+'Main Data Entry'!$D$14),(($C164-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C164<(60-'Main Data Entry'!$D$14),(($C164-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.7038024636350775},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160451389005,59.942001342773438,157.13909912109375,59.942001342773438,157.13909912109375]
["T+44s",42759.160462963082,59.944999694824219,157.13909912109375,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C165>(60+'Main Data Entry'!$D$14),(($C165-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C165<(60-'Main Data Entry'!$D$14),(($C165-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.2866666603919601},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160462963082,59.944999694824219,157.13909912109375,59.944999694824219,157.13909912109375]
["T+45s",42759.160474537159,59.944000244140625,157.13909912109375,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C166>(60+'Main Data Entry'!$D$14),(($C166-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C166<(60-'Main Data Entry'!$D$14),(($C166-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.4257119281396662},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160474537159,59.944000244140625,157.13909912109375,59.944000244140625,157.13909912109375]
["T+46s",42759.160486111236,59.944000244140625,157.13909912109375,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,{"$f":"P$12+P$26","v":159.29545593261719},{"$f":"P$12+P$31","v":150.94190881609558},{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C167>(60+'Main Data Entry'!$D$14),(($C167-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C167<(60-'Main Data Entry'!$D$14),(($C167-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.4257119281396662},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160486111236,59.944000244140625,157.13909912109375,59.944000244140625,157.13909912109375]
["T+47s",42759.160497685312,59.946998596191406,156.69599914550781,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,{"$f":"P$12+P$26","v":159.29545593261719},{"$f":"P$12+P$31","v":150.94190881609558},{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C168>(60+'Main Data Entry'!$D$14),(($C168-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C168<(60-'Main Data Entry'!$D$14),(($C168-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.0085761248965488},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160497685312,59.946998596191406,156.69599914550781,59.946998596191406,156.69599914550781]
["T+48s",42759.160509259389,59.946998596191406,156.69599914550781,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C169>(60+'Main Data Entry'!$D$14),(($C169-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C169<(60-'Main Data Entry'!$D$14),(($C169-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.0085761248965488},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160509259389,59.946998596191406,156.69599914550781,59.946998596191406,156.69599914550781]
["T+49s",42759.160520833466,59.946998596191406,156.71269226074219,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C170>(60+'Main Data Entry'!$D$14),(($C170-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C170<(60-'Main Data Entry'!$D$14),(($C170-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.0085761248965488},6.0623996623672456,null,null,null,null,null,null,null,null,null,{"$f":"AB169+TIME(0,0,1)","v":42759.160520833466},59.946998596191406,156.71269226074219,59.946998596191406,156.71269226074219]
["T+50s",42759.160532407543,59.944999694824219,156.71269226074219,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C171>(60+'Main Data Entry'!$D$14),(($C171-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C171<(60-'Main Data Entry'!$D$14),(($C171-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.2866666603919601},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160532407543,59.944999694824219,156.71269226074219,59.944999694824219,156.71269226074219]
["T+51s",42759.160543981619,59.944999694824219,156.50700378417969,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C172>(60+'Main Data Entry'!$D$14),(($C172-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C172<(60-'Main Data Entry'!$D$14),(($C172-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.2866666603919601},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160543981619,59.944999694824219,156.50700378417969,59.944999694824219,156.50700378417969]
["T+52s",42759.160555555696,59.945999145507813,156.50700378417969,59.939423763390742,158.08755770596591,null,null,59.939423763390742,null,158.08755770596591,154.31579256924715,151.57859655032314,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C173>(60+'Main Data Entry'!$D$14),(($C173-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C173<(60-'Main Data Entry'!$D$14),(($C173-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.1476213926442549},6.0623996623672456,null,null,null,null,null,null,null,null,null,42759.160555555696,59.945999145507813,156.50700378417969,59.945999145507813,156.50700378417969]
["T+53s",42759.160567129773,59.945999145507813,156.50700378417969,null,null,null,null,null,null,null,null,null,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C174>(60+'Main Data Entry'!$D$14),(($C174-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C174<(60-'Main Data Entry'!$D$14),(($C174-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.1476213926442549},null,null,null,null,null,null,null,null,null,null,42759.160567129773,59.945999145507813,156.50700378417969,59.945999145507813,156.50700378417969]
["T+54s",42759.16057870385,59.945999145507813,156.50700378417969,null,null,null,null,null,null,null,null,null,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C175>(60+'Main Data Entry'!$D$14),(($C175-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C175<(60-'Main Data Entry'!$D$14),(($C175-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.1476213926442549},null,null,null,null,null,null,null,null,null,null,42759.16057870385,59.945999145507813,156.50700378417969,59.945999145507813,156.50700378417969]
["T+55s",42759.160590277927,59.944999694824219,157.88835144042969,null,null,null,null,null,null,null,null,null,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C176>(60+'Main Data Entry'!$D$14),(($C176-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C176<(60-'Main Data Entry'!$D$14),(($C176-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.2866666603919601},null,null,null,null,null,null,null,null,null,null,42759.160590277927,59.944999694824219,157.88835144042969,59.944999694824219,157.88835144042969]
["T+56s",42759.160601852003,{"$f":"OFFSET($AE177,-$B$1,0)","v":59.944999694824219},{"$f":"OFFSET($AF177,-$B$1,0)","v":157.88835144042969},null,null,null,null,null,null,null,null,null,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C177>(60+'Main Data Entry'!$D$14),(($C177-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C177<(60-'Main Data Entry'!$D$14),(($C177-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.2866666603919601},null,null,null,null,null,null,null,null,null,null,42759.160601852003,59.944999694824219,157.88835144042969,59.944999694824219,157.88835144042969]
["T+57s",42759.16061342608,59.941001892089844,157.8375244140625,null,null,null,null,null,null,null,null,null,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C178>(60+'Main Data Entry'!$D$14),(($C178-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C178<(60-'Main Data Entry'!$D$14),(($C178-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.8428477313827827},null,null,null,null,null,null,null,null,null,null,42759.16061342608,59.941001892089844,157.8375244140625,59.941001892089844,157.8375244140625]
["T+58s",42759.160625000157,59.938999176025391,157.8375244140625,null,null,null,null,null,null,null,null,null,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C179>(60+'Main Data Entry'!$D$14),(($C179-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C179<(60-'Main Data Entry'!$D$14),(($C179-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.1214689740070023},null,null,null,null,null,null,null,null,null,null,42759.160625000157,59.938999176025391,157.8375244140625,59.938999176025391,157.8375244140625]
["T+59s",42759.160636574234,59.937000274658203,159.29545593261719,null,null,null,null,null,null,null,null,null,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C180>(60+'Main Data Entry'!$D$14),(($C180-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C180<(60-'Main Data Entry'!$D$14),(($C180-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},null,null,null,null,null,null,null,null,null,null,42759.160636574234,59.937000274658203,159.29545593261719,59.937000274658203,159.29545593261719]
["T+60s",42759.16064814831,59.937000274658203,159.29545593261719,null,null,null,null,null,null,null,null,null,159.29545593261719,150.94190881609558,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C181>(60+'Main Data Entry'!$D$14),(($C181-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C181<(60-'Main Data Entry'!$D$14),(($C181-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},null,null,null,null,null,null,null,null,null,null,42759.16064814831,59.937000274658203,159.29545593261719,59.937000274658203,159.29545593261719]
["T+61s",42759.160659722387,59.937000274658203,159.24151611328125,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C182>(60+'Main Data Entry'!$D$14),(($C182-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C182<(60-'Main Data Entry'!$D$14),(($C182-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},null,null,null,null,null,null,null,null,null,null,42759.160659722387,59.937000274658203,159.24151611328125,59.937000274658203,159.24151611328125]
["T+62s",42759.160671296464,59.937000274658203,159.24151611328125,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C183>(60+'Main Data Entry'!$D$14),(($C183-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C183<(60-'Main Data Entry'!$D$14),(($C183-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.3995595095024145},null,null,null,null,null,null,null,null,null,null,42759.160671296464,59.937000274658203,159.24151611328125,59.937000274658203,159.24151611328125]
["T+63s",42759.160682870541,59.938999176025391,160.30992126464844,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C184>(60+'Main Data Entry'!$D$14),(($C184-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C184<(60-'Main Data Entry'!$D$14),(($C184-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.1214689740070023},null,null,null,null,null,null,null,null,null,null,42759.160682870541,59.938999176025391,160.30992126464844,59.938999176025391,160.30992126464844]
["T+64s",42759.160694444618,59.937999725341797,160.30992126464844,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C185>(60+'Main Data Entry'!$D$14),(($C185-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C185<(60-'Main Data Entry'!$D$14),(($C185-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.2605142417547084},null,null,null,null,null,null,null,null,null,null,42759.160694444618,59.937999725341797,160.30992126464844,59.937999725341797,160.30992126464844]
["T+65s",42759.160706018694,59.937999725341797,160.2703857421875,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C186>(60+'Main Data Entry'!$D$14),(($C186-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C186<(60-'Main Data Entry'!$D$14),(($C186-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.2605142417547084},null,null,null,null,null,null,null,null,null,null,{"$f":"AB185+TIME(0,0,1)","v":42759.160706018694},59.937999725341797,160.2703857421875,59.937999725341797,160.2703857421875]
["T+66s",{"$f":"B186+TIME(0,0,1)","v":42759.160717592771},59.937999725341797,160.2703857421875,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C187>(60+'Main Data Entry'!$D$14),(($C187-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C187<(60-'Main Data Entry'!$D$14),(($C187-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":6.2605142417547084},null,null,null,null,null,null,null,null,null,null,42759.160717592771,59.937999725341797,160.2703857421875,59.937999725341797,160.2703857421875]
["T+67s",42759.160729166848,59.941001892089844,160.4154052734375,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C188>(60+'Main Data Entry'!$D$14),(($C188-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C188<(60-'Main Data Entry'!$D$14),(($C188-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.8428477313827827},null,null,null,null,null,null,null,null,null,null,42759.160729166848,59.941001892089844,160.4154052734375,59.941001892089844,160.4154052734375]
["T+68s",42759.160740740925,59.941001892089844,160.4154052734375,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C189>(60+'Main Data Entry'!$D$14),(($C189-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C189<(60-'Main Data Entry'!$D$14),(($C189-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.8428477313827827},null,null,null,null,null,null,null,null,null,null,42759.160740740925,59.941001892089844,160.4154052734375,59.941001892089844,160.4154052734375]
["T+69s",42759.160752315001,59.944000244140625,160.4154052734375,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C190>(60+'Main Data Entry'!$D$14),(($C190-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C190<(60-'Main Data Entry'!$D$14),(($C190-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.4257119281396662},null,null,null,null,null,null,null,null,null,null,42759.160752315001,59.944000244140625,160.4154052734375,59.944000244140625,160.4154052734375]
["T+70s",42759.160763889078,59.946998596191406,160.4154052734375,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C191>(60+'Main Data Entry'!$D$14),(($C191-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C191<(60-'Main Data Entry'!$D$14),(($C191-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.0085761248965488},null,null,null,null,null,null,null,null,null,null,42759.160763889078,59.946998596191406,160.4154052734375,59.946998596191406,160.4154052734375]
["T+71s",42759.160775463155,59.946998596191406,160.36921691894531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C192>(60+'Main Data Entry'!$D$14),(($C192-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C192<(60-'Main Data Entry'!$D$14),(($C192-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.0085761248965488},null,null,null,null,null,null,null,null,null,null,42759.160775463155,59.946998596191406,160.36921691894531,59.946998596191406,160.36921691894531]
["T+72s",42759.160787037232,59.949001312255859,160.36921691894531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C193>(60+'Main Data Entry'!$D$14),(($C193-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C193<(60-'Main Data Entry'!$D$14),(($C193-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.7299548822723292},null,null,null,null,null,null,null,null,null,null,42759.160787037232,59.949001312255859,160.36921691894531,59.949001312255859,160.36921691894531]
["T+73s",42759.160798611309,59.948001861572266,160.36921691894531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C194>(60+'Main Data Entry'!$D$14),(($C194-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C194<(60-'Main Data Entry'!$D$14),(($C194-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.8690001500200353},null,null,null,null,null,null,null,null,null,null,42759.160798611309,59.948001861572266,160.36921691894531,59.948001861572266,160.36921691894531]
["T+74s",42759.160810185385,59.948001861572266,160.36921691894531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C195>(60+'Main Data Entry'!$D$14),(($C195-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C195<(60-'Main Data Entry'!$D$14),(($C195-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.8690001500200353},null,null,null,null,null,null,null,null,null,null,42759.160810185385,59.948001861572266,160.36921691894531,59.948001861572266,160.36921691894531]
["T+75s",42759.160821759462,59.945999145507813,160.26814270019531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C196>(60+'Main Data Entry'!$D$14),(($C196-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C196<(60-'Main Data Entry'!$D$14),(($C196-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.1476213926442549},null,null,null,null,null,null,null,null,null,null,42759.160821759462,59.945999145507813,160.26814270019531,59.945999145507813,160.26814270019531]
["T+76s",42759.160833333539,59.945999145507813,160.26814270019531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C197>(60+'Main Data Entry'!$D$14),(($C197-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C197<(60-'Main Data Entry'!$D$14),(($C197-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.1476213926442549},null,null,null,null,null,null,null,null,null,null,42759.160833333539,59.945999145507813,160.26814270019531,59.945999145507813,160.26814270019531]
["T+77s",42759.160844907616,59.944000244140625,160.26814270019531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C198>(60+'Main Data Entry'!$D$14),(($C198-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C198<(60-'Main Data Entry'!$D$14),(($C198-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.4257119281396662},null,null,null,null,null,null,null,null,null,null,42759.160844907616,59.944000244140625,160.26814270019531,59.944000244140625,160.26814270019531]
["T+78s",42759.160856481692,59.939998626708984,160.26814270019531,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C199>(60+'Main Data Entry'!$D$14),(($C199-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C199<(60-'Main Data Entry'!$D$14),(($C199-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.9824237062592971},null,null,null,null,null,null,null,null,null,null,42759.160856481692,59.939998626708984,160.26814270019531,59.939998626708984,160.26814270019531]
["T+79s",42759.160868055769,59.941001892089844,159.49249267578125,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C200>(60+'Main Data Entry'!$D$14),(($C200-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C200<(60-'Main Data Entry'!$D$14),(($C200-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.8428477313827827},null,null,null,null,null,null,null,null,null,null,42759.160868055769,59.941001892089844,159.49249267578125,59.941001892089844,159.49249267578125]
["T+80s",42759.160879629846,59.943000793457031,159.49249267578125,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C201>(60+'Main Data Entry'!$D$14),(($C201-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C201<(60-'Main Data Entry'!$D$14),(($C201-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.160879629846,59.943000793457031,159.49249267578125,59.943000793457031,159.49249267578125]
["T+81s",42759.160891203923,59.943000793457031,159.52133178710937,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C202>(60+'Main Data Entry'!$D$14),(($C202-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C202<(60-'Main Data Entry'!$D$14),(($C202-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,{"$f":"AB201+TIME(0,0,1)","v":42759.160891203923},59.943000793457031,159.52133178710937,59.943000793457031,159.52133178710937]
["T+82s",42759.160902778,59.943000793457031,159.52133178710937,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C203>(60+'Main Data Entry'!$D$14),(($C203-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C203<(60-'Main Data Entry'!$D$14),(($C203-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.160902778,59.943000793457031,159.52133178710937,59.943000793457031,159.52133178710937]
["T+83s",42759.160914352076,59.943000793457031,158.330810546875,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C204>(60+'Main Data Entry'!$D$14),(($C204-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C204<(60-'Main Data Entry'!$D$14),(($C204-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.160914352076,59.943000793457031,158.330810546875,{"$f":"IF($AC204=\"\",$AE203,IF($AC204<>$AE203,$AC204,$AE203))","v":59.943000793457031},{"$f":"IF($AD204=\"\",$AF203,IF($AD204<>$AF203,$AD204,$AF203))","v":158.330810546875}]
["T+84s",42759.160925926153,59.944999694824219,158.330810546875,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C205>(60+'Main Data Entry'!$D$14),(($C205-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C205<(60-'Main Data Entry'!$D$14),(($C205-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.2866666603919601},null,null,null,null,null,null,null,null,null,null,42759.160925926153,59.944999694824219,158.330810546875,59.944999694824219,158.330810546875]
["T+85s",42759.16093750023,59.945999145507813,158.37486267089844,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C206>(60+'Main Data Entry'!$D$14),(($C206-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C206<(60-'Main Data Entry'!$D$14),(($C206-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.1476213926442549},null,null,null,null,null,null,null,null,null,null,42759.16093750023,59.945999145507813,158.37486267089844,59.945999145507813,158.37486267089844]
["T+86s",42759.160949074307,59.943000793457031,158.37486267089844,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C207>(60+'Main Data Entry'!$D$14),(($C207-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C207<(60-'Main Data Entry'!$D$14),(($C207-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.160949074307,59.943000793457031,158.37486267089844,59.943000793457031,158.37486267089844]
["T+87s",42759.160960648383,59.943000793457031,158.37486267089844,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C208>(60+'Main Data Entry'!$D$14),(($C208-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C208<(60-'Main Data Entry'!$D$14),(($C208-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.160960648383,59.943000793457031,158.37486267089844,59.943000793457031,158.37486267089844]
["T+88s",42759.16097222246,{"$f":"OFFSET($AE209,-$B$1,0)","v":59.944000244140625},{"$f":"OFFSET($AF209,-$B$1,0)","v":158.37486267089844},null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C209>(60+'Main Data Entry'!$D$14),(($C209-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C209<(60-'Main Data Entry'!$D$14),(($C209-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.4257119281396662},null,null,null,null,null,null,null,null,null,null,42759.16097222246,59.944000244140625,158.37486267089844,59.944000244140625,158.37486267089844]
["T+89s",42759.160983796537,59.943000793457031,158.393798828125,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C210>(60+'Main Data Entry'!$D$14),(($C210-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C210<(60-'Main Data Entry'!$D$14),(($C210-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.160983796537,59.943000793457031,158.393798828125,59.943000793457031,158.393798828125]
["T+90s",42759.160995370614,59.943000793457031,158.393798828125,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C211>(60+'Main Data Entry'!$D$14),(($C211-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C211<(60-'Main Data Entry'!$D$14),(($C211-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.160995370614,59.943000793457031,158.393798828125,59.943000793457031,158.393798828125]
["T+91s",42759.161006944691,59.943000793457031,157.83932495117187,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C212>(60+'Main Data Entry'!$D$14),(($C212-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C212<(60-'Main Data Entry'!$D$14),(($C212-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.161006944691,59.943000793457031,157.83932495117187,59.943000793457031,157.83932495117187]
["T+92s",42759.161018518767,59.943000793457031,157.83932495117187,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C213>(60+'Main Data Entry'!$D$14),(($C213-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C213<(60-'Main Data Entry'!$D$14),(($C213-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.161018518767,59.943000793457031,157.83932495117187,59.943000793457031,157.83932495117187]
["T+93s",42759.161030092844,59.943000793457031,157.85984802246094,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C214>(60+'Main Data Entry'!$D$14),(($C214-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C214<(60-'Main Data Entry'!$D$14),(($C214-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.161030092844,59.943000793457031,157.85984802246094,59.943000793457031,157.85984802246094]
["T+94s",42759.161041666921,59.939998626708984,157.85984802246094,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C215>(60+'Main Data Entry'!$D$14),(($C215-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C215<(60-'Main Data Entry'!$D$14),(($C215-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.9824237062592971},null,null,null,null,null,null,null,null,null,null,42759.161041666921,59.939998626708984,157.85984802246094,59.939998626708984,157.85984802246094]
["T+95s",42759.161053240998,59.939998626708984,156.89521789550781,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C216>(60+'Main Data Entry'!$D$14),(($C216-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C216<(60-'Main Data Entry'!$D$14),(($C216-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.9824237062592971},null,null,null,null,null,null,null,null,null,null,42759.161053240998,59.939998626708984,156.89521789550781,59.939998626708984,156.89521789550781]
["T+96s",42759.161064815074,59.943000793457031,156.89521789550781,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C217>(60+'Main Data Entry'!$D$14),(($C217-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C217<(60-'Main Data Entry'!$D$14),(($C217-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.161064815074,59.943000793457031,156.89521789550781,59.943000793457031,156.89521789550781]
["T+97s",42759.161076389151,59.943000793457031,156.930908203125,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C218>(60+'Main Data Entry'!$D$14),(($C218-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C218<(60-'Main Data Entry'!$D$14),(($C218-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,{"$f":"AB217+TIME(0,0,1)","v":42759.161076389151},59.943000793457031,156.930908203125,59.943000793457031,156.930908203125]
["T+98s",42759.161087963228,59.942001342773438,156.930908203125,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C219>(60+'Main Data Entry'!$D$14),(($C219-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C219<(60-'Main Data Entry'!$D$14),(($C219-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.7038024636350775},null,null,null,null,null,null,null,null,null,null,42759.161087963228,59.942001342773438,156.930908203125,59.942001342773438,156.930908203125]
["T+99s",42759.161099537305,59.942001342773438,156.23233032226562,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C220>(60+'Main Data Entry'!$D$14),(($C220-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C220<(60-'Main Data Entry'!$D$14),(($C220-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.7038024636350775},null,null,null,null,null,null,null,null,null,null,42759.161099537305,59.942001342773438,156.23233032226562,59.942001342773438,156.23233032226562]
["T+100s",42759.161111111382,59.943000793457031,156.23233032226562,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C221>(60+'Main Data Entry'!$D$14),(($C221-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C221<(60-'Main Data Entry'!$D$14),(($C221-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.161111111382,59.943000793457031,156.23233032226562,59.943000793457031,156.23233032226562]
["T+101s",42759.161122685458,59.943000793457031,156.2581787109375,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C222>(60+'Main Data Entry'!$D$14),(($C222-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C222<(60-'Main Data Entry'!$D$14),(($C222-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.5647571958873723},null,null,null,null,null,null,null,null,null,null,42759.161122685458,59.943000793457031,156.2581787109375,59.943000793457031,156.2581787109375]
["T+102s",42759.161134259535,59.945999145507813,156.2581787109375,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C223>(60+'Main Data Entry'!$D$14),(($C223-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C223<(60-'Main Data Entry'!$D$14),(($C223-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":5.1476213926442549},null,null,null,null,null,null,null,null,null,null,42759.161134259535,59.945999145507813,156.2581787109375,59.945999145507813,156.2581787109375]
["T+103s",42759.161145833612,59.948001861572266,156.31874084472656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C224>(60+'Main Data Entry'!$D$14),(($C224-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C224<(60-'Main Data Entry'!$D$14),(($C224-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.8690001500200353},null,null,null,null,null,null,null,null,null,null,42759.161145833612,59.948001861572266,156.31874084472656,59.948001861572266,156.31874084472656]
["T+104s",42759.161157407689,59.948001861572266,156.31874084472656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C225>(60+'Main Data Entry'!$D$14),(($C225-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C225<(60-'Main Data Entry'!$D$14),(($C225-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.8690001500200353},null,null,null,null,null,null,null,null,null,null,42759.161157407689,59.948001861572266,156.31874084472656,59.948001861572266,156.31874084472656]
["T+105s",42759.161168981766,59.948001861572266,156.31874084472656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C226>(60+'Main Data Entry'!$D$14),(($C226-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C226<(60-'Main Data Entry'!$D$14),(($C226-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.8690001500200353},null,null,null,null,null,null,null,null,null,null,42759.161168981766,59.948001861572266,156.31874084472656,59.948001861572266,156.31874084472656]
["T+106s",42759.161180555842,59.949001312255859,156.31874084472656,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C227>(60+'Main Data Entry'!$D$14),(($C227-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C227<(60-'Main Data Entry'!$D$14),(($C227-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.7299548822723292},null,null,null,null,null,null,null,null,null,null,42759.161180555842,59.949001312255859,156.31874084472656,59.949001312255859,156.31874084472656]
["T+107s",42759.161192129919,59.950000762939453,156.33709716796875,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C228>(60+'Main Data Entry'!$D$14),(($C228-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C228<(60-'Main Data Entry'!$D$14),(($C228-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.5909096145246231},null,null,null,null,null,null,null,null,null,null,42759.161192129919,59.950000762939453,156.33709716796875,59.950000762939453,156.33709716796875]
["T+108s",42759.161203703996,59.950000762939453,156.33709716796875,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C229>(60+'Main Data Entry'!$D$14),(($C229-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C229<(60-'Main Data Entry'!$D$14),(($C229-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.5909096145246231},null,null,null,null,null,null,null,null,null,null,42759.161203703996,59.950000762939453,156.33709716796875,59.950000762939453,156.33709716796875]
["T+109s",42759.161215278073,59.951000213623047,156.33709716796875,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C230>(60+'Main Data Entry'!$D$14),(($C230-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C230<(60-'Main Data Entry'!$D$14),(($C230-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.4518643467769179},null,null,null,null,null,null,null,null,null,null,42759.161215278073,59.951000213623047,156.33709716796875,59.951000213623047,156.33709716796875]
["T+110s",42759.161226852149,59.953998565673828,156.33709716796875,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C231>(60+'Main Data Entry'!$D$14),(($C231-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C231<(60-'Main Data Entry'!$D$14),(($C231-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.0347285435338005},null,null,null,null,null,null,null,null,null,null,42759.161226852149,59.953998565673828,156.33709716796875,59.953998565673828,156.33709716796875]
["T+111s",42759.161238426226,59.955001831054688,156.23382568359375,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C232>(60+'Main Data Entry'!$D$14),(($C232-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C232<(60-'Main Data Entry'!$D$14),(($C232-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":3.8951525686572865},null,null,null,null,null,null,null,null,null,null,42759.161238426226,59.955001831054688,156.23382568359375,59.955001831054688,156.23382568359375]
["T+112s",42759.161250000303,59.951000213623047,156.23382568359375,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C233>(60+'Main Data Entry'!$D$14),(($C233-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C233<(60-'Main Data Entry'!$D$14),(($C233-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.4518643467769179},null,null,null,null,null,null,null,null,null,null,42759.161250000303,59.951000213623047,156.23382568359375,59.951000213623047,156.23382568359375]
["T+113s",42759.16126157438,59.951000213623047,156.23382568359375,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C234>(60+'Main Data Entry'!$D$14),(($C234-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C234<(60-'Main Data Entry'!$D$14),(($C234-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.4518643467769179},null,null,null,null,null,null,null,null,null,null,{"$f":"AB233+TIME(0,0,1)","v":42759.16126157438},59.951000213623047,156.23382568359375,59.951000213623047,156.23382568359375]
["T+114s",42759.161273148457,59.950000762939453,156.23382568359375,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C235>(60+'Main Data Entry'!$D$14),(($C235-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C235<(60-'Main Data Entry'!$D$14),(($C235-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.5909096145246231},null,null,null,null,null,null,null,null,null,null,42759.161273148457,59.950000762939453,156.23382568359375,59.950000762939453,156.23382568359375]
["T+115s",42759.161284722533,59.948001861572266,156.13493347167969,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C236>(60+'Main Data Entry'!$D$14),(($C236-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C236<(60-'Main Data Entry'!$D$14),(($C236-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.8690001500200353},null,null,null,null,null,null,null,null,null,null,42759.161284722533,59.948001861572266,156.13493347167969,59.948001861572266,156.13493347167969]
["T+116s",42759.16129629661,59.948001861572266,156.13493347167969,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C237>(60+'Main Data Entry'!$D$14),(($C237-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C237<(60-'Main Data Entry'!$D$14),(($C237-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.8690001500200353},null,null,null,null,null,null,null,null,null,null,42759.16129629661,59.948001861572266,156.13493347167969,59.948001861572266,156.13493347167969]
["T+117s",42759.161307870687,59.949001312255859,156.13493347167969,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C238>(60+'Main Data Entry'!$D$14),(($C238-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C238<(60-'Main Data Entry'!$D$14),(($C238-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.7299548822723292},null,null,null,null,null,null,null,null,null,null,42759.161307870687,59.949001312255859,156.13493347167969,59.949001312255859,156.13493347167969]
["T+118s",42759.161319444764,59.950000762939453,156.13493347167969,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C239>(60+'Main Data Entry'!$D$14),(($C239-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C239<(60-'Main Data Entry'!$D$14),(($C239-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.5909096145246231},null,null,null,null,null,null,null,null,null,null,42759.161319444764,59.950000762939453,156.13493347167969,59.950000762939453,156.13493347167969]
["T+119s",42759.16133101884,59.951000213623047,155.70793151855469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C240>(60+'Main Data Entry'!$D$14),(($C240-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C240<(60-'Main Data Entry'!$D$14),(($C240-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.4518643467769179},null,null,null,null,null,null,null,null,null,null,42759.16133101884,59.951000213623047,155.70793151855469,59.951000213623047,155.70793151855469]
["T+120s",42759.161342592917,59.951000213623047,155.70793151855469,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Main Data Entry'!$G$15","v":415},{"$f":"IF($C241>(60+'Main Data Entry'!$D$14),(($C241-60-'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,IF($C241<(60-'Main Data Entry'!$D$14),(($C241-60+'Main Data Entry'!$D$14)/(60*'Main Data Entry'!$D$13-'Main Data Entry'!$D$14))*(-1)*'Main Data Entry'!$G$15,0))","v":4.4518643467769179},null,null,null,null,null,null,null,null,null,null,42759.161342592917,59.951000213623047,155.70793151855469,59.951000213623047,155.70793151855469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"AB241+TIME(0,0,1)","v":42759.161354166994},59.953998565673828,155.72386169433594,59.953998565673828,155.72386169433594]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161365741071,59.953998565673828,155.72386169433594,59.953998565673828,155.72386169433594]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161377315148,59.953998565673828,155.90785217285156,59.953998565673828,155.90785217285156]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161388889224,59.951999664306641,155.90785217285156,59.951999664306641,155.90785217285156]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161400463301,59.951999664306641,155.90785217285156,59.951999664306641,155.90785217285156]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161412037378,59.951999664306641,155.90785217285156,59.951999664306641,155.90785217285156]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161423611455,59.955001831054688,156.55754089355469,59.955001831054688,156.55754089355469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161435185531,59.959999084472656,156.55754089355469,59.959999084472656,156.55754089355469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161446759608,59.959999084472656,156.53324890136719,59.959999084472656,156.53324890136719]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161458333685,59.959999084472656,156.53324890136719,59.959999084472656,156.53324890136719]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161469907762,59.958999633789063,156.41110229492188,59.958999633789063,156.41110229492188]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161481481839,59.958999633789063,156.41110229492188,59.958999633789063,156.41110229492188]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161493055915,59.959999084472656,156.41110229492188,59.959999084472656,156.41110229492188]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161504629992,59.959999084472656,156.41110229492188,59.959999084472656,156.41110229492188]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161516204069,59.958000183105469,156.21037292480469,59.958000183105469,156.21037292480469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161527778146,59.958999633789063,156.21037292480469,59.958999633789063,156.21037292480469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161539352222,59.958999633789063,156.21037292480469,59.958999633789063,156.21037292480469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161550926299,59.958999633789063,156.21037292480469,59.958999633789063,156.21037292480469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161562500376,59.958999633789063,156.44328308105469,59.958999633789063,156.44328308105469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161574074453,59.959999084472656,156.44328308105469,59.959999084472656,156.44328308105469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.16158564853,59.958999633789063,156.44328308105469,59.958999633789063,156.44328308105469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161597222606,59.958999633789063,156.44328308105469,59.958999633789063,156.44328308105469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161608796683,59.958000183105469,156.84539794921875,59.958000183105469,156.84539794921875]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.16162037076,59.957000732421875,156.84539794921875,59.957000732421875,156.84539794921875]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161631944837,59.957000732421875,156.83021545410156,59.957000732421875,156.83021545410156]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161643518913,59.958999633789063,156.83021545410156,59.958999633789063,156.83021545410156]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.16165509299,59.959999084472656,157.13839721679687,59.959999084472656,157.13839721679687]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161666667067,59.96099853515625,157.13839721679687,59.96099853515625,157.13839721679687]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161678241144,59.962001800537109,157.12699890136719,59.962001800537109,157.12699890136719]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161689815221,59.962001800537109,157.12699890136719,59.962001800537109,157.12699890136719]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161701389297,59.959999084472656,158.31686401367187,59.959999084472656,158.31686401367187]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161712963374,59.958000183105469,158.31686401367187,{"$f":"IF($AC273=\"\",$AE272,IF($AC273<>$AE272,$AC273,$AE272))","v":59.958000183105469},{"$f":"IF($AD273=\"\",$AF272,IF($AD273<>$AF272,$AD273,$AF272))","v":158.31686401367187}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161724537451,59.957000732421875,158.27284240722656,59.957000732421875,158.27284240722656]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161736111528,59.959999084472656,158.27284240722656,59.959999084472656,158.27284240722656]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161747685604,59.959999084472656,159.09478759765625,59.959999084472656,159.09478759765625]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161759259681,59.966999053955078,159.09478759765625,59.966999053955078,159.09478759765625]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161770833758,59.966999053955078,159.06437683105469,59.966999053955078,159.06437683105469]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,42759.161782407835,59.974998474121094,159.06437683105469,59.974998474121094,159.06437683105469]

{"sheet":"Chart","index":4,"n_rows":34,"n_cols":8,"rows_kept":34,"cut":false,"hidden":false,"merged":[[33,5,33,6]]}
["Alignment Chart for Historian Data"]
["-Users may use this chart to align their frequency and MW data to the t(0) of the event provided by NERC staff."]
["-Chart will not be available for manually entered data."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,null,null,null,"OFFSET (s):",null,0]